{"id":8479,"date":"2017-08-01T08:04:58","date_gmt":"2017-08-01T06:04:58","guid":{"rendered":"https:\/\/auren.com\/cl\/global-publication\/international-business-august-2017\/"},"modified":"2026-05-11T17:08:49","modified_gmt":"2026-05-11T15:08:49","slug":"international-business-august-2017","status":"publish","type":"global-publication","link":"https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/","title":{"rendered":"INTERNATIONAL BUSINESS AUGUST 2017"},"content":{"rendered":"<\/p>\n<figure rel=\"width: 541px; height: 380px;\" style=\"float: left; margin: 0px 10px 10px 0px;\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/d33c2a5xmvj7uh.cloudfront.net\/images\/originals\/auren-2.jpg?v=1501574551\" data-image=\"9992575\" style=\"width: 541px; height: 380px;\" width=\"541\" height=\"380\"><\/figure>\n<figure><a href=\"https:\/\/issuu.com\/auren-international\/docs\/auren_int.business_august_2017?e=26558439\/51728107\"><img decoding=\"async\" src=\"https:\/\/d33c2a5xmvj7uh.cloudfront.net\/images\/originals\/online-button-p-12.jpg?v=1499701484\" data-image=\"9992492\"><\/a><\/figure>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":6423,"template":"","meta":{"_acf_changed":false},"global-publication-category":[],"class_list":["post-8479","global-publication","type-global-publication","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INTERNATIONAL BUSINESS AUGUST 2017 - Auren Chile<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INTERNATIONAL BUSINESS AUGUST 2017 - Auren Chile\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren Chile\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Auren-Chile-102082852427361\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T15:08:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/cl\/wp-content\/uploads\/global\/2017\/08\/newsletter-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"443\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aurenchile\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/global-publication\\\/international-business-august-2017\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/global-publication\\\/international-business-august-2017\\\/\",\"name\":\"INTERNATIONAL BUSINESS AUGUST 2017 - Auren Chile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/global-publication\\\/international-business-august-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/global-publication\\\/international-business-august-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/global\\\/2017\\\/08\\\/newsletter-9.jpg\",\"datePublished\":\"2017-08-01T06:04:58+00:00\",\"dateModified\":\"2026-05-11T15:08:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/global-publication\\\/international-business-august-2017\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/global-publication\\\/international-business-august-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/global-publication\\\/international-business-august-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/global\\\/2017\\\/08\\\/newsletter-9.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/global\\\/2017\\\/08\\\/newsletter-9.jpg\",\"width\":443,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/global-publication\\\/international-business-august-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INTERNATIONAL BUSINESS AUGUST 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/\",\"name\":\"Auren Chile\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/#organization\",\"name\":\"Auren Chile\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren Chile\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Auren-Chile-102082852427361\\\/\",\"https:\\\/\\\/x.com\\\/aurenchile\",\"https:\\\/\\\/cl.linkedin.com\\\/company\\\/aurengroupchile\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC1INxEQ1wu0Jy5-btcBdzdA\",\"https:\\\/\\\/www.instagram.com\\\/auren.chile\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INTERNATIONAL BUSINESS AUGUST 2017 - Auren Chile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/","og_locale":"en_US","og_type":"article","og_title":"INTERNATIONAL BUSINESS AUGUST 2017 - Auren Chile","og_url":"https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/","og_site_name":"Auren Chile","article_publisher":"https:\/\/www.facebook.com\/Auren-Chile-102082852427361\/","article_modified_time":"2026-05-11T15:08:49+00:00","og_image":[{"width":443,"height":531,"url":"https:\/\/auren.com\/cl\/wp-content\/uploads\/global\/2017\/08\/newsletter-9.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@aurenchile","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/","url":"https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/","name":"INTERNATIONAL BUSINESS AUGUST 2017 - Auren Chile","isPartOf":{"@id":"https:\/\/auren.com\/cl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/cl\/wp-content\/uploads\/global\/2017\/08\/newsletter-9.jpg","datePublished":"2017-08-01T06:04:58+00:00","dateModified":"2026-05-11T15:08:49+00:00","breadcrumb":{"@id":"https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/#primaryimage","url":"https:\/\/auren.com\/cl\/wp-content\/uploads\/global\/2017\/08\/newsletter-9.jpg","contentUrl":"https:\/\/auren.com\/cl\/wp-content\/uploads\/global\/2017\/08\/newsletter-9.jpg","width":443,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/cl\/en\/global-publication\/international-business-august-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/cl\/en\/"},{"@type":"ListItem","position":2,"name":"INTERNATIONAL BUSINESS AUGUST 2017"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/cl\/en\/#website","url":"https:\/\/auren.com\/cl\/en\/","name":"Auren Chile","description":"","publisher":{"@id":"https:\/\/auren.com\/cl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/cl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/auren.com\/cl\/en\/#organization","name":"Auren Chile","url":"https:\/\/auren.com\/cl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/auren.com\/cl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren Chile"},"image":{"@id":"https:\/\/auren.com\/cl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Auren-Chile-102082852427361\/","https:\/\/x.com\/aurenchile","https:\/\/cl.linkedin.com\/company\/aurengroupchile","https:\/\/www.youtube.com\/channel\/UC1INxEQ1wu0Jy5-btcBdzdA","https:\/\/www.instagram.com\/auren.chile\/"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/cl\/en\/wp-json\/wp\/v2\/global-publication\/8479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/cl\/en\/wp-json\/wp\/v2\/global-publication"}],"about":[{"href":"https:\/\/auren.com\/cl\/en\/wp-json\/wp\/v2\/types\/global-publication"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/cl\/en\/wp-json\/wp\/v2\/media\/6423"}],"wp:attachment":[{"href":"https:\/\/auren.com\/cl\/en\/wp-json\/wp\/v2\/media?parent=8479"}],"wp:term":[{"taxonomy":"global-publication-category","embeddable":true,"href":"https:\/\/auren.com\/cl\/en\/wp-json\/wp\/v2\/global-publication-category?post=8479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}