{"id":3890,"date":"2022-06-28T11:20:53","date_gmt":"2022-06-28T09:20:53","guid":{"rendered":"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/"},"modified":"2022-06-28T11:20:53","modified_gmt":"2022-06-28T09:20:53","slug":"auditoria-auditar-cuentas-contables-o-auditar-el-negocio","status":"publish","type":"blog","link":"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/","title":{"rendered":"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio?"},"content":{"rendered":"<p>En un mundo globalizado como el actual, no es f\u00e1cil desarrollar una teor\u00eda respecto de cu\u00e1l es la situaci\u00f3n actual del trabajo del auditor externo de informaci\u00f3n financiera en diferentes pa\u00edses y cu\u00e1l deber\u00eda ser su enfoque a futuro.<\/p>\n<p>Diferentes estudios de respetados profesionales del \u00e1rea, han hecho \u00e9nfasis en la brecha que existe entre lo que el auditor define como su responsabilidad en cuanto a su informe de auditor\u00eda de los estados financieros evaluados y las expectativas de los diferentes grupos de inter\u00e9s: accionistas, trabajadores, instituciones de financiaci\u00f3n, entidades reguladoras y otros. Diferentes esc\u00e1ndalos financieros ocurridos en los \u00faltimos diez a\u00f1os as\u00ed lo comprueban, con evidente da\u00f1o a la reputaci\u00f3n p\u00fablica de los auditores que han estado ligados a tales eventos. Prueba de ello es que cada vez m\u00e1s se solicitan pericias forenses para identificar a los responsables \u2013 administradores y auditores de empresas \u2013 para respaldar la presentaci\u00f3n de acciones judiciales sobre \u00e9stos.<\/p>\n<p>Es claro que el futuro debe haber mayor consenso entre las entidades a ser auditadas y el auditor. Las primeras, en fortalecer sus herramientas de control de gesti\u00f3n y de procesos internos y los segundos, para desarrollar procedimientos de evaluaci\u00f3n de riesgos de auditor\u00eda que le permitan reducir el impacto de desviaciones materiales en la presentaci\u00f3n de las cuentas de las empresas.<\/p>\n<p>El auditor debe, necesariamente, incorporar a su enfoque de trabajo a otras disciplinas, tales como recursos de auditor\u00eda de sistemas, profesionales expertos en evaluaci\u00f3n de negocios, asesores fiscales,\u00a0 legales y a otras relacionadas con la actividad de cada empresa auditada.\u00a0\u00a0 En resumen, de auditar las cuentas del balance a pasar a \u201cauditar el negocio\u201d, para entender c\u00f3mo su actividad se refleja en la informaci\u00f3n financiera auditada. Muchas veces el auditor prioriza auditar las cuentas del estado de situaci\u00f3n, cuando en realidad el coraz\u00f3n del negocio y ritmo de su actividad se encuentra en la generaci\u00f3n de resultados. El auditor deber\u00eda apuntar entonces a evaluar la forma c\u00f3mo la administraci\u00f3n agrega valor a la empresa y consecuentemente a sus accionistas.<\/p>\n<p><a href=\"https:\/\/auren.com\/cl\/blog\">Blog: Auren Chile<\/a><\/p>\n<p><strong><em>Waldo Catal\u00e1n &#8211; Socio L\u00edder de Auditor\u00eda, Auren Chile\u00a0<\/em><\/strong><\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un mundo globalizado como el actual, no es f\u00e1cil desarrollar una teor\u00eda respecto de cu\u00e1l es la situaci\u00f3n actual del trabajo del auditor externo de informaci\u00f3n financiera en diferentes [&hellip;]<\/p>\n","protected":false},"featured_media":3891,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[],"class_list":["post-3890","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio? - Auren Chile<\/title>\n<meta name=\"description\" content=\"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio?: En un mundo globalizado como el actual, no es f\u00e1cil...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio? - Auren Chile\" \/>\n<meta property=\"og:description\" content=\"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio?: En un mundo globalizado como el actual, no es f\u00e1cil...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren Chile\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Auren-Chile-102082852427361\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/cl\/wp-content\/uploads\/2022\/06\/auditoria-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aurenchile\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\\\/\",\"name\":\"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio? - Auren Chile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/auditoria-scaled-1.jpg\",\"datePublished\":\"2022-06-28T09:20:53+00:00\",\"description\":\"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio?: En un mundo globalizado como el actual, no es f\u00e1cil...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/auditoria-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/auditoria-scaled-1.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/\",\"name\":\"Auren Chile\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#organization\",\"name\":\"Auren Chile\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren Chile\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Auren-Chile-102082852427361\\\/\",\"https:\\\/\\\/x.com\\\/aurenchile\",\"https:\\\/\\\/cl.linkedin.com\\\/company\\\/aurengroupchile\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC1INxEQ1wu0Jy5-btcBdzdA\",\"https:\\\/\\\/www.instagram.com\\\/auren.chile\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio? - Auren Chile","description":"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio?: En un mundo globalizado como el actual, no es f\u00e1cil...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/","og_locale":"es_ES","og_type":"article","og_title":"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio? - Auren Chile","og_description":"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio?: En un mundo globalizado como el actual, no es f\u00e1cil...","og_url":"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/","og_site_name":"Auren Chile","article_publisher":"https:\/\/www.facebook.com\/Auren-Chile-102082852427361\/","og_image":[{"width":2560,"height":1440,"url":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2022\/06\/auditoria-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@aurenchile","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/","url":"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/","name":"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio? - Auren Chile","isPartOf":{"@id":"https:\/\/auren.com\/cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2022\/06\/auditoria-scaled-1.jpg","datePublished":"2022-06-28T09:20:53+00:00","description":"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio?: En un mundo globalizado como el actual, no es f\u00e1cil...","breadcrumb":{"@id":"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/#primaryimage","url":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2022\/06\/auditoria-scaled-1.jpg","contentUrl":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2022\/06\/auditoria-scaled-1.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/cl\/blog\/auditoria-auditar-cuentas-contables-o-auditar-el-negocio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/cl\/"},{"@type":"ListItem","position":2,"name":"Auditor\u00eda: \u00bfauditar cuentas contables o auditar el negocio?"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/cl\/#website","url":"https:\/\/auren.com\/cl\/","name":"Auren Chile","description":"","publisher":{"@id":"https:\/\/auren.com\/cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/cl\/#organization","name":"Auren Chile","url":"https:\/\/auren.com\/cl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/cl\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren Chile"},"image":{"@id":"https:\/\/auren.com\/cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Auren-Chile-102082852427361\/","https:\/\/x.com\/aurenchile","https:\/\/cl.linkedin.com\/company\/aurengroupchile","https:\/\/www.youtube.com\/channel\/UC1INxEQ1wu0Jy5-btcBdzdA","https:\/\/www.instagram.com\/auren.chile\/"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/blog\/3890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/blog\/3890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/media\/3891"}],"wp:attachment":[{"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/media?parent=3890"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/blog-category?post=3890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}