{"id":3924,"date":"2019-10-11T10:35:50","date_gmt":"2019-10-11T08:35:50","guid":{"rendered":"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/"},"modified":"2019-10-11T10:35:50","modified_gmt":"2019-10-11T08:35:50","slug":"sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable","status":"publish","type":"blog","link":"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/","title":{"rendered":"Sustituci\u00f3n de trabajadores por robots. Sentencia discutible, debate inevitable."},"content":{"rendered":"<p class=\"text-justify\">Nos desayun\u00e1bamos hace pocos d\u00edas con la noticia de una sentencia de un juzgado de Las Palmas en la que se declaraba improcedente el despido de una trabajadora porque la empresa pretend\u00eda sustituirla por un robot.<\/p>\n<p class=\"text-justify\">La sentencia y su argumentaci\u00f3n es muy, pero que muy discutible y supongo que ser\u00e1 recurrida, pero es muy ilustrativa de la manera de pensar del juzgador a la hora de abordar la automatizaci\u00f3n de un puesto de trabajo y la sustituci\u00f3n de los trabajadores afectados. Vamos a darle una vuelta a ambas cosas. <\/p>\n<p class=\"text-justify\">La sentencia es muy discutible porque choca con la realidad que tiene que enjuiciar y parece que esa realidad no le gusta al juzgador, por lo que decide no aceptarla y llega a la conclusi\u00f3n de que el despido es improcedente. Digo que no acepta la realidad, porque la sentencia se\u00f1ala que las causas t\u00e9cnicas, organizativas o productivas en que la empresa basa su decisi\u00f3n de despedir, no quedan acreditadas en la carta de despido que se entreg\u00f3 a la trabajadora. Muy bien, eso bastar\u00eda para declarar la improcedencia del despido y no habr\u00eda nada m\u00e1s que decir (sobre todo para quien no conoce la mencionada carta, ni los detalles del caso). Lo que pasa, es que a continuaci\u00f3n de se\u00f1alar eso, su se\u00f1or\u00eda se mete en el complicado jard\u00edn del debate entre empleo y tecnolog\u00eda y convierte la sentencia en un art\u00edculo de opini\u00f3n sobre las consecuencias de la una sobre el otro, elev\u00e1ndose a construir explicaciones de orden constitucional, que resultan como m\u00ednimo fuera de lugar. <\/p>\n<p class=\"text-justify\">Como ya he dicho, la sentencia se\u00f1ala expresamente que al no recogerse adecuadamente la causa del despido en la carta entregada a la trabajadora, el despido se debe declarar improcedente por no acreditarse la concurrencia de la causa alegada. Pero es que, dicho esto, el se\u00f1or juez nos dice que aunque hubiera quedado acreditada la causa en la carta, tambi\u00e9n el despido deber\u00eda ser declarado improcedente. Para ello, la sentencia, apoy\u00e1ndose en el voto particular de una sentencia del TS (e ignorando la propia sentencia), se encarga primero de negar el sentido literal y de fondo de las \u00faltimas reformas del art.52 del Estatuto de los Trabajadores (ET), de contraponer los derechos constitucionales de libertad de empresa y del trabajo y de declarar (o reiterar) la improcedencia en base a que no se pueden admitir los despidos derivados de los cambios tecnol\u00f3gicos porque eso supondr\u00eda admitir que muchos trabajadores podr\u00edan perder su empleo (!!). O sea, porque no le gusta afrontar la realidad que el caso le plantea, que no es otra que, seg\u00fan la ley vigente, est\u00e1 justificado el despido que se deriva de causas t\u00e9cnicas. O lo que es lo mismo, viene a vaciar de contenido el art. 52 (y unos cuantos m\u00e1s) del ET, en base a unas elevadas razones (\u00bfcient\u00edficas, doctrinales, de equilibrio jur\u00eddico o de tertulia?) y sin plantear la inconstitucionalidad de los preceptos as\u00ed cuestionados . <\/p>\n<p class=\"text-justify\">En el camino, al juez se le desliza su manera de pensar sobre los despidos objetivos -a los que califica de extraordinarios- y justifica que hay que dictar la improcedencia porque eso supone una mayor indemnizaci\u00f3n para el trabajador. A \u00faltima hora, parece que todo es una cuesti\u00f3n de precio y su se\u00f1or\u00eda acepta el despido, siempre que sea m\u00e1s caro para la empresa y deja el supuesto mandato de protecci\u00f3n del empleo para mejor ocasi\u00f3n. Hasta ah\u00ed la sentencia. <\/p>\n<p class=\"text-justify\">El debate. La sentencia choca contra una realidad con la que nos toca vivir desde hace tiempo. D\u00eda a d\u00eda se destruyen miles de puestos de trabajo por la incorporaci\u00f3n de la tecnolog\u00eda y hay sectores que hemos visto cambiar en muy pocos a\u00f1os (\u00bfnos acordamos de c\u00f3mo eran las agencias de viaje, cuantas hab\u00eda y que empleo supon\u00edan, o de cuando solo compr\u00e1bamos en tiendas f\u00edsicas, limitados por horarios y por la carga de la compra, o de c\u00f3mo se fabricaban los coches?). El debate, en el que se plantea hasta \u0093el fin del trabajo\u0094 y que incluye la propuesta de que los robots coticen para salvar la seguridad social -precisamente porque est\u00e1n sustituyendo a trabajadores-, sobre la influencia de los cambios tecnol\u00f3gicos en el mercado de trabajo ya est\u00e1 iniciado desde hace m\u00e1s de cien a\u00f1os y la gran cuesti\u00f3n es si el saldo final entre generaci\u00f3n y destrucci\u00f3n de empleo ser\u00e1 finalmente favorable a la creaci\u00f3n de nuevos puestos de trabajo (como ha venido ocurriendo en las anteriores revoluciones industriales) o no. <\/p>\n<p class=\"text-justify\">Una parte de este debate es la de la regulaci\u00f3n y gesti\u00f3n del mercado de trabajo por parte de los legisladores y poderes p\u00fablicos. La ley no puede contemplar como excepcional y espor\u00e1dico el cambio tecnol\u00f3gico, porque es ya el d\u00eda a d\u00eda en la vida de las empresas (muchas de ellas desaparecen y otras se crean por ello) y de los trabajadores (muchos pierden y\/o encuentran empleo tambi\u00e9n por ello). Si la norma legal no brinda soluciones r\u00e1pidas, razonables y equilibradas que contemplen todos los intereses en juego, simplemente ser\u00e1 desbordada por la realidad y el coste ser\u00e1 muy alto en t\u00e9rminos de creaci\u00f3n de nuevos puestos de trabajo. La tecnolog\u00eda y el conocimiento como principal factor de producci\u00f3n caracterizan estos tiempos y brindan una gran oportunidad a las sociedades que apuesten por trabajadores formados y abiertos al cambio y por empresas flexibles e innovadoras capaces de crecer y aportar riqueza. <\/p>\n<p class=\"text-justify\">Hace tiempo que es una obviedad que ir contra la digitalizaci\u00f3n y robotizaci\u00f3n de las empresas supone no solo negar la evidencia sino pecar de iluso. La competitividad se centra, cada vez m\u00e1s, en econom\u00edas colaborativas, en nuevas metodolog\u00edas organizativas y en la colaboraci\u00f3n de los empleados con robots en procesos de trabajo de cada vez mayor valor a\u00f1adido (al principio, como pas\u00f3 en la industrializaci\u00f3n inicial, para superar los condicionantes de la fuerza f\u00edsica y la fatiga y, cada vez m\u00e1s, para incorporar la Inteligencia Artificial -IA-). Los seres humanos, que hemos evolucionado por nuestra capacidad de adaptaci\u00f3n, tenemos que seguir adapt\u00e1ndonos a este nuevo ecosistema digital y robotizado. Encerrarnos en una visi\u00f3n proteccionista nos lleva a una concepci\u00f3n maligna de la rob\u00f3tica y como todo en la vida, hay que ser consciente que la actitud (o el prejuicio) influye en nuestra conducta humana (si es malo seguro que har\u00e1n el mal) <\/p>\n<p class=\"text-justify\">El principal eje de reflexi\u00f3n para producir una adaptaci\u00f3n inteligente a la nueva realidad pasa por la humanizaci\u00f3n de la tecnolog\u00eda. No se trata de enfrentar lo humano a los robots (que son una obra humana&hellip;al menos, por ahora), sino de como generar una relaci\u00f3n de personas-robots que facilite el trabajo humano. Si creamos una visi\u00f3n negativista de los robots nos encontramos en una versi\u00f3n de lucha de clases entre obreros y robots (en una versi\u00f3n actualizada del ludismo). Hay que pensar que un trabajo con robots puede ser m\u00e1s humano, porque disponemos de mayor capacidad de autonom\u00eda, conciliaci\u00f3n e inteligencia. <\/p>\n<p class=\"text-justify\">Adem\u00e1s de cambiar nuestra actitud negativa hacia los robots e incidir en la humanizaci\u00f3n de la tecnolog\u00eda tenemos que aceptar el aprendizaje continuo como valor profesional. La tecnolog\u00eda incide en estar todo el d\u00eda actualizado e impide un anquilosamiento en hacer lo mismo. Hay que evitar ser un obsoleto digital para estar mejor preparado en la forma de colaboraci\u00f3n con tu robot (que es m\u00e1s una herramienta que un compa\u00f1ero, al menos hasta hoy). Actitud, humanizaci\u00f3n y formaci\u00f3n continua como llaves del empleo de hoy y de ma\u00f1ana. Huir del empleo que se base en labores repetitivas y con trabajadores de muy baja cualificaci\u00f3n es m\u00e1s efectivo que centrarnos en saber si la indemnizaci\u00f3n por despido ser\u00e1 m\u00e1s o menos alta. <\/p>\n<p><strong>Pilar S\u00e1nchez-Bleda, Socia de Auren Abogados; Juan Chozas,&nbsp;<\/strong><strong>Of counsel Auren Abogados<\/strong><strong>&nbsp;y Javier Cantera, Presidente de Auren-Blc<\/strong><\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos desayun\u00e1bamos hace pocos d\u00edas con la noticia de una sentencia de un juzgado de Las Palmas en la que se declaraba improcedente el despido de una trabajadora porque la empresa pretend\u00eda sustituirla por un robot.<\/p>\n","protected":false},"featured_media":3925,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[],"class_list":["post-3924","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sustituci\u00f3n de trabajadores por robots. Sentencia discutible, debate inevitable. - Auren Chile<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sustituci\u00f3n de trabajadores por robots. Sentencia discutible, debate inevitable. - Auren Chile\" \/>\n<meta property=\"og:description\" content=\"Nos desayun\u00e1bamos hace pocos d\u00edas con la noticia de una sentencia de un juzgado de Las Palmas en la que se declaraba improcedente el despido de una trabajadora porque la empresa pretend\u00eda sustituirla por un robot.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren Chile\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Auren-Chile-102082852427361\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/cl\/wp-content\/uploads\/2019\/10\/191010-robot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aurenchile\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\\\/\",\"name\":\"Sustituci\u00f3n de trabajadores por robots. Sentencia discutible, debate inevitable. - Auren Chile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/191010-robot.jpg\",\"datePublished\":\"2019-10-11T08:35:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/191010-robot.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/191010-robot.jpg\",\"width\":1920,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sustituci\u00f3n de trabajadores por robots. Sentencia discutible, debate inevitable.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/\",\"name\":\"Auren Chile\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#organization\",\"name\":\"Auren Chile\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren Chile\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Auren-Chile-102082852427361\\\/\",\"https:\\\/\\\/x.com\\\/aurenchile\",\"https:\\\/\\\/cl.linkedin.com\\\/company\\\/aurengroupchile\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC1INxEQ1wu0Jy5-btcBdzdA\",\"https:\\\/\\\/www.instagram.com\\\/auren.chile\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sustituci\u00f3n de trabajadores por robots. Sentencia discutible, debate inevitable. - Auren Chile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/","og_locale":"es_ES","og_type":"article","og_title":"Sustituci\u00f3n de trabajadores por robots. Sentencia discutible, debate inevitable. - Auren Chile","og_description":"Nos desayun\u00e1bamos hace pocos d\u00edas con la noticia de una sentencia de un juzgado de Las Palmas en la que se declaraba improcedente el despido de una trabajadora porque la empresa pretend\u00eda sustituirla por un robot.","og_url":"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/","og_site_name":"Auren Chile","article_publisher":"https:\/\/www.facebook.com\/Auren-Chile-102082852427361\/","og_image":[{"width":1920,"height":655,"url":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2019\/10\/191010-robot.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@aurenchile","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/","url":"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/","name":"Sustituci\u00f3n de trabajadores por robots. Sentencia discutible, debate inevitable. - Auren Chile","isPartOf":{"@id":"https:\/\/auren.com\/cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2019\/10\/191010-robot.jpg","datePublished":"2019-10-11T08:35:50+00:00","breadcrumb":{"@id":"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/#primaryimage","url":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2019\/10\/191010-robot.jpg","contentUrl":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2019\/10\/191010-robot.jpg","width":1920,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/cl\/blog\/sustitucion-de-trabajadores-por-robots-sentencia-discutible-debate-inevitable\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/cl\/"},{"@type":"ListItem","position":2,"name":"Sustituci\u00f3n de trabajadores por robots. Sentencia discutible, debate inevitable."}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/cl\/#website","url":"https:\/\/auren.com\/cl\/","name":"Auren Chile","description":"","publisher":{"@id":"https:\/\/auren.com\/cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/cl\/#organization","name":"Auren Chile","url":"https:\/\/auren.com\/cl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/cl\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren Chile"},"image":{"@id":"https:\/\/auren.com\/cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Auren-Chile-102082852427361\/","https:\/\/x.com\/aurenchile","https:\/\/cl.linkedin.com\/company\/aurengroupchile","https:\/\/www.youtube.com\/channel\/UC1INxEQ1wu0Jy5-btcBdzdA","https:\/\/www.instagram.com\/auren.chile\/"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/blog\/3924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/blog\/3924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/media\/3925"}],"wp:attachment":[{"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/media?parent=3924"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/blog-category?post=3924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}