{"id":3930,"date":"2019-10-09T14:47:12","date_gmt":"2019-10-09T12:47:12","guid":{"rendered":"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/"},"modified":"2019-10-09T14:47:12","modified_gmt":"2019-10-09T12:47:12","slug":"el-deber-de-informacion-en-aplicaciones-moviles","status":"publish","type":"blog","link":"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/","title":{"rendered":"El deber de informaci\u00f3n en aplicaciones m\u00f3viles"},"content":{"rendered":"<p class=\"text-justify\"><strong>Hoy en d\u00eda nadie puede negar la omnipresencia de los dispositivos m\u00f3viles y la importancia del mercado digital de aplicaciones para estos soportes<\/strong>. Tampoco es desde\u00f1able la cantidad de datos que se trata a trav\u00e9s de las mismas, y este fue uno de los motivos que impulsaron la redacci\u00f3n del ya de sobras conocido RGPD.<\/p>\n<p class=\"text-justify\">Sin embargo, <strong>no todos los responsables de tratamientos realizados a trav\u00e9s de aplicaciones m\u00f3viles son conscientes de sus obligaciones en este campo<\/strong>. De hecho, <strong>es demasiado frecuente encontrarse con incumplimientos legales<\/strong> que puede ser de mayor o menor calado.<\/p>\n<p class=\"text-justify\">Uno de los campos en los que es m\u00e1s habitual cometer estas infracciones es el de <strong>la<\/strong> <strong>informaci\u00f3n que se proporciona a los usuarios<\/strong>.<\/p>\n<p class=\"text-justify\">Como ya es bien sabido, a la hora de tratar datos de car\u00e1cter personal <strong><a href=\"https:\/\/www.auren.com\/es-ES\/blog\/abogados-y-asesores-fiscales\/2019-03-15\/tratando-datos-la-informacion-no-lo-es-todo-pero-casi\">tenemos la obligaci\u00f3n de ofrecer al interesado una serie de datos<\/a><\/strong> sobre lo que haremos con ellos, con qu\u00e9 finalidad o de qu\u00e9 manera.<\/p>\n<p class=\"text-justify\">Con la intenci\u00f3n de ofrecer unas gu\u00edas de comportamiento a los responsables, <strong>la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos ha publicado <a href=\"https:\/\/www.aepd.es\/media\/notas-tecnicas\/nota-tecnica-apps-moviles.pdf\"><\/a><a href=\"https:\/\/www.aepd.es\/media\/notas-tecnicas\/nota-tecnica-apps-moviles.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">esta nota t\u00e9cnica<\/a> en la que desgrana distintas obligaciones de informaci\u00f3n y de responsabilidad proactiva<\/strong> <strong>para el desarrollo de aplicaciones m\u00f3viles<\/strong>.<\/p>\n<p class=\"text-justify\">He aqu\u00ed algunos de los aspectos m\u00e1s significativos de la nota:<\/p>\n<p class=\"text-justify\">&#8211; <strong>La pol\u00edtica de privacidad de la<\/strong> \u00ab<strong><em>app<\/em><\/strong>\u00bb <strong>no solo debe estar en la propia aplicaci\u00f3n, sino<\/strong> <strong>tambi\u00e9n en la tienda de aplicaciones<\/strong>. La idea subyacente es que el usuario no tenga que instalar la \u00ab<strong><em>app<\/em><\/strong>\u00bb para leer la informaci\u00f3n relativa al tratamiento de sus datos de car\u00e1cter personal.<\/p>\n<p class=\"text-justify\">&#8211; Obviamente, <strong>no puede haber discrepancias<\/strong> <strong>entre la pol\u00edtica de privacidad que haya en la tienda de aplicaciones y la que nos muestre la propia<\/strong> \u00ab<strong><em>app<\/em><\/strong>\u00ab.<\/p>\n<p class=\"text-justify\">&#8211; <strong>Acceder a la pol\u00edtica de privacidad debe ser algo sencillo<\/strong>. Se recomienda que para llegar hasta ella solo haga falta un <strong>m\u00e1ximo de dos clics<\/strong>.<\/p>\n<p class=\"text-justify\">&#8211; Como en cualquier otro tratamiento, <strong>el lenguaje usado ha de ser accesible<\/strong>. En el caso de \u00ab<strong><em>apps<\/em><\/strong>\u00bb que vayan dirigidas a ni\u00f1os (juegos, etc.), hay que tener en cuenta que el lenguaje deber\u00e1 ser comprensible para esos menores que son los destinatarios finales de la aplicaci\u00f3n.<\/p>\n<p class=\"text-justify\">&#8211; <strong>La pol\u00edtica de privacidad no puede ser un texto inacabable lleno de jerga jur\u00eddica<\/strong>. Existe una obligaci\u00f3n de <strong>evitar la llamada \u00ab<em>fatiga informativa<\/em>\u00ab<\/strong>. Por ejemplo, deber\u00e1 mencionarse elementos que afecten en concreto a la aplicaci\u00f3n de que se trate; no ser\u00eda buena pr\u00e1ctica incluir aqu\u00ed datos sobre todas las aplicaciones del mismo responsable.<\/p>\n<p class=\"text-justify\">&#8211; Hay que indicar en la pol\u00edtica de privacidad <strong>los<\/strong> <strong>permisos que se va a solicitar en el dispositivo m\u00f3vil<\/strong>. No solo eso, sino que hay que detallar el motivo por el que se solicitan, la finalidad de los mismos y hasta d\u00f3nde llegan. La Agencia aclara que, por ejemplo, debemos especificar si los datos se tratan solo en primer plano o si se tratan tambi\u00e9n en segundo plano.<\/p>\n<p class=\"text-justify\">&#8211; <strong>La informaci\u00f3n sobre los tratamientos realizados debe incluir tambi\u00e9n menciones a si dichos tratamientos ser\u00e1n realizados directamente, o si se har\u00e1n a trav\u00e9s de bibliotecas de terceros<\/strong>.<\/p>\n<p class=\"text-justify\">&#8211; Como en cualquier otro tratamiento -aunque aqu\u00ed deviene un poco m\u00e1s importante-, <strong>el consentimiento prestado debe ser libre<\/strong>, ello implica que <strong>no puede condicionarse el uso de la \u00ab<em>app<\/em>\u00bb a la prestaci\u00f3n de un consentimiento para un tratamiento que no sea necesario<\/strong> <strong>para el uso de dicha aplicaci\u00f3n<\/strong> (por ejemplo, un videojuego que solo funciona si el interesado accede a la cesi\u00f3n de sus datos a terceros que no tienen nada que ver con el videojuego).<\/p>\n<p class=\"text-justify\">Estos son solo algunos ejemplos. En general la AEPD nos recuerda que en el tratamiento de \u00ab<strong><em>apps<\/em><\/strong>\u00bb debemos cumplir los mismos principios y obligaciones que con cualquier otro tratamiento.<\/p>\n<p class=\"text-justify\">Si necesitan m\u00e1s informaci\u00f3n, p\u00f3nganse en contacto con nosotros y estaremos encantados de ayudarles.<\/p>\n<p class=\"text-justify\"><strong>Fabi\u00e1n Plaza Miranda, Auren Abogados y asesores Fiscales<\/strong><\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy en d\u00eda nadie puede negar la omnipresencia de los dispositivos m\u00f3viles y la importancia del mercado digital de aplicaciones para estos soportes. Tampoco es desde\u00f1able la cantidad de datos que se trata a trav\u00e9s de las mismas, y este fue uno de los motivos que impulsaron la redacci\u00f3n del ya de sobras conocido RGPD.<\/p>\n","protected":false},"featured_media":3931,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[],"class_list":["post-3930","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El deber de informaci\u00f3n en aplicaciones m\u00f3viles - Auren Chile<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El deber de informaci\u00f3n en aplicaciones m\u00f3viles - Auren Chile\" \/>\n<meta property=\"og:description\" content=\"Hoy en d\u00eda nadie puede negar la omnipresencia de los dispositivos m\u00f3viles y la importancia del mercado digital de aplicaciones para estos soportes. Tampoco es desde\u00f1able la cantidad de datos que se trata a trav\u00e9s de las mismas, y este fue uno de los motivos que impulsaron la redacci\u00f3n del ya de sobras conocido RGPD.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren Chile\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Auren-Chile-102082852427361\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/cl\/wp-content\/uploads\/2019\/10\/191009-telefonos-moviles.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aurenchile\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/el-deber-de-informacion-en-aplicaciones-moviles\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/el-deber-de-informacion-en-aplicaciones-moviles\\\/\",\"name\":\"El deber de informaci\u00f3n en aplicaciones m\u00f3viles - Auren Chile\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/el-deber-de-informacion-en-aplicaciones-moviles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/el-deber-de-informacion-en-aplicaciones-moviles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/191009-telefonos-moviles.jpg\",\"datePublished\":\"2019-10-09T12:47:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/el-deber-de-informacion-en-aplicaciones-moviles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/el-deber-de-informacion-en-aplicaciones-moviles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/el-deber-de-informacion-en-aplicaciones-moviles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/191009-telefonos-moviles.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/191009-telefonos-moviles.jpg\",\"width\":1920,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/blog\\\/el-deber-de-informacion-en-aplicaciones-moviles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El deber de informaci\u00f3n en aplicaciones m\u00f3viles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/\",\"name\":\"Auren Chile\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#organization\",\"name\":\"Auren Chile\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/cl\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren Chile\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Auren-Chile-102082852427361\\\/\",\"https:\\\/\\\/x.com\\\/aurenchile\",\"https:\\\/\\\/cl.linkedin.com\\\/company\\\/aurengroupchile\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC1INxEQ1wu0Jy5-btcBdzdA\",\"https:\\\/\\\/www.instagram.com\\\/auren.chile\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El deber de informaci\u00f3n en aplicaciones m\u00f3viles - Auren Chile","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/","og_locale":"es_ES","og_type":"article","og_title":"El deber de informaci\u00f3n en aplicaciones m\u00f3viles - Auren Chile","og_description":"Hoy en d\u00eda nadie puede negar la omnipresencia de los dispositivos m\u00f3viles y la importancia del mercado digital de aplicaciones para estos soportes. Tampoco es desde\u00f1able la cantidad de datos que se trata a trav\u00e9s de las mismas, y este fue uno de los motivos que impulsaron la redacci\u00f3n del ya de sobras conocido RGPD.","og_url":"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/","og_site_name":"Auren Chile","article_publisher":"https:\/\/www.facebook.com\/Auren-Chile-102082852427361\/","og_image":[{"width":1920,"height":655,"url":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2019\/10\/191009-telefonos-moviles.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@aurenchile","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/","url":"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/","name":"El deber de informaci\u00f3n en aplicaciones m\u00f3viles - Auren Chile","isPartOf":{"@id":"https:\/\/auren.com\/cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2019\/10\/191009-telefonos-moviles.jpg","datePublished":"2019-10-09T12:47:12+00:00","breadcrumb":{"@id":"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/#primaryimage","url":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2019\/10\/191009-telefonos-moviles.jpg","contentUrl":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2019\/10\/191009-telefonos-moviles.jpg","width":1920,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/cl\/blog\/el-deber-de-informacion-en-aplicaciones-moviles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/cl\/"},{"@type":"ListItem","position":2,"name":"El deber de informaci\u00f3n en aplicaciones m\u00f3viles"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/cl\/#website","url":"https:\/\/auren.com\/cl\/","name":"Auren Chile","description":"","publisher":{"@id":"https:\/\/auren.com\/cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/cl\/#organization","name":"Auren Chile","url":"https:\/\/auren.com\/cl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/cl\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/cl\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren Chile"},"image":{"@id":"https:\/\/auren.com\/cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Auren-Chile-102082852427361\/","https:\/\/x.com\/aurenchile","https:\/\/cl.linkedin.com\/company\/aurengroupchile","https:\/\/www.youtube.com\/channel\/UC1INxEQ1wu0Jy5-btcBdzdA","https:\/\/www.instagram.com\/auren.chile\/"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/blog\/3930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/blog\/3930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/media\/3931"}],"wp:attachment":[{"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/media?parent=3930"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/auren.com\/cl\/wp-json\/wp\/v2\/blog-category?post=3930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}