{"id":10232,"date":"2020-07-08T08:54:39","date_gmt":"2020-07-08T06:54:39","guid":{"rendered":"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/"},"modified":"2020-07-08T08:54:39","modified_gmt":"2020-07-08T06:54:39","slug":"como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva","status":"publish","type":"blog","link":"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/","title":{"rendered":"\u00bfC\u00f3mo deben reportarse las ventas de los 3 d\u00edas sin IVA?"},"content":{"rendered":"<p>El Decreto Legislativo 682 de 2020, con el objetivo de incentivar el consumo y reactivar la econom\u00eda, implement\u00f3 la exenci\u00f3n del IVA por ventas realizadas al consumidor final en los d\u00edas 19 de junio, 3 y 19 de julio de 2020, de bienes tales como vestuario y complementos, electrodom\u00e9sticos, computadores y equipos de comunicaciones, \u00fatiles escolares, elementos deportivos, juguetes y algunos bienes e insumos para el sector agropecuario.<\/p>\n<p> Con prop\u00f3sitos de control, mediante Resoluci\u00f3n 64 del 18 de junio de 2020, la administraci\u00f3n tributaria estableci\u00f3 que frente a los bienes exentos vendidos en los d\u00edas antes referidos, los vendedores debenenviar de forma virtual a la DIAN, a m\u00e1s tardar el 31 de agosto de 2020, la informaci\u00f3n de los compradores de dichos bienes, detallando, entre otros, su documento, nombre, tipo y n\u00famero de factura, valor y descripci\u00f3n de los bienes, medio de pago.<\/p>\n<p>En la Resoluci\u00f3n 64 se advierte que la no entrega de la informaci\u00f3n, o su entrega extempor\u00e1nea o con errores, generar\u00e1 multas de 3, 4 o 5% sobre las sumas que deben reportarse, de acuerdo con lo establecido en el art\u00edculo 651 del Estatuto Tributario. <\/p>\n<p>Finalmente, con el fin de evitar las aglomeraciones ocurridas en la primera jornada de venta sin IVA, mediante Circular Conjunta el Ministerio del Interior y el de Comercio, Industria y Turismo, instaron a Alcaldes y Gobernadores para que en el segundo y tercer d\u00eda sin IVA, 3 y 19 de julio respectivamente, adopten medidas que garanticen los protocolos de bioseguridad, debiendo asegurar que en tales fechas se suspenda en las grandes superficies la venta presencial de electrodom\u00e9sticos, computadores y equipos de comunicaciones.<\/p>\n<blockquote class=\"wp-block-quote\">\n<p>Fuente<\/p>\n<p><cite>DIAN, <a href=\"https:\/\/www.dian.gov.co\/normatividad\/Normatividad\/Resoluci%C3%B3n%20000064%20de%2018-06-2020.pdf\">Resoluci\u00f3n 64 del 18 de junio de 2020<\/a> y Circular Conjunta del Ministerio del Interior y el de Comercio, Industria y Turismo No. 72-DMI-1000 del 28 de junio de 2020<\/cite><\/p><\/blockquote>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Decreto Legislativo 682 de 2020, con el objetivo de incentivar el consumo y reactivar la econom\u00eda, implement\u00f3 la exenci\u00f3n del IVA por ventas realizadas al consumidor final en los [&hellip;]<\/p>\n","protected":false},"featured_media":10233,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[],"class_list":["post-10232","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo deben reportarse las ventas de los 3 d\u00edas sin IVA? - Auren Colombia<\/title>\n<meta name=\"description\" content=\"D\u00edas sin IVA: El Decreto Legislativo 682 de 2020, con el objetivo de incentivar el consumo y reactivar la econom\u00eda, implement\u00f3 la exenci\u00f3n del IVA...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo deben reportarse las ventas de los 3 d\u00edas sin IVA? - Auren Colombia\" \/>\n<meta property=\"og:description\" content=\"D\u00edas sin IVA: El Decreto Legislativo 682 de 2020, con el objetivo de incentivar el consumo y reactivar la econom\u00eda, implement\u00f3 la exenci\u00f3n del IVA...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren Colombia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/07\/Dias-sin-IVA-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AurenColombia\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\\\/\",\"name\":\"\u00bfC\u00f3mo deben reportarse las ventas de los 3 d\u00edas sin IVA? - Auren Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Dias-sin-IVA-1.jpg\",\"datePublished\":\"2020-07-08T06:54:39+00:00\",\"description\":\"D\u00edas sin IVA: El Decreto Legislativo 682 de 2020, con el objetivo de incentivar el consumo y reactivar la econom\u00eda, implement\u00f3 la exenci\u00f3n del IVA...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Dias-sin-IVA-1.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Dias-sin-IVA-1.jpg\",\"width\":1400,\"height\":933},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo deben reportarse las ventas de los 3 d\u00edas sin IVA?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/\",\"name\":\"Auren Colombia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#organization\",\"name\":\"Auren Colombia\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren Colombia\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/AurenColombia\",\"https:\\\/\\\/www.instagram.com\\\/aurencolombia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRYoGRMR_k4oVWesdErApmA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/auren-colombia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo deben reportarse las ventas de los 3 d\u00edas sin IVA? - Auren Colombia","description":"D\u00edas sin IVA: El Decreto Legislativo 682 de 2020, con el objetivo de incentivar el consumo y reactivar la econom\u00eda, implement\u00f3 la exenci\u00f3n del IVA...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo deben reportarse las ventas de los 3 d\u00edas sin IVA? - Auren Colombia","og_description":"D\u00edas sin IVA: El Decreto Legislativo 682 de 2020, con el objetivo de incentivar el consumo y reactivar la econom\u00eda, implement\u00f3 la exenci\u00f3n del IVA...","og_url":"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/","og_site_name":"Auren Colombia","og_image":[{"width":1400,"height":933,"url":"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/07\/Dias-sin-IVA-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AurenColombia","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/","url":"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/","name":"\u00bfC\u00f3mo deben reportarse las ventas de los 3 d\u00edas sin IVA? - Auren Colombia","isPartOf":{"@id":"https:\/\/auren.com\/co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/07\/Dias-sin-IVA-1.jpg","datePublished":"2020-07-08T06:54:39+00:00","description":"D\u00edas sin IVA: El Decreto Legislativo 682 de 2020, con el objetivo de incentivar el consumo y reactivar la econom\u00eda, implement\u00f3 la exenci\u00f3n del IVA...","breadcrumb":{"@id":"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/#primaryimage","url":"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/07\/Dias-sin-IVA-1.jpg","contentUrl":"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/07\/Dias-sin-IVA-1.jpg","width":1400,"height":933},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/co\/blog\/como-deben-reportarse-las-ventas-de-los-3-dias-sin-iva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/co\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo deben reportarse las ventas de los 3 d\u00edas sin IVA?"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/co\/#website","url":"https:\/\/auren.com\/co\/","name":"Auren Colombia","description":"","publisher":{"@id":"https:\/\/auren.com\/co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/co\/#organization","name":"Auren Colombia","url":"https:\/\/auren.com\/co\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/co\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/co\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/co\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren Colombia"},"image":{"@id":"https:\/\/auren.com\/co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/AurenColombia","https:\/\/www.instagram.com\/aurencolombia\/","https:\/\/www.youtube.com\/channel\/UCRYoGRMR_k4oVWesdErApmA","https:\/\/www.linkedin.com\/company\/auren-colombia"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog\/10232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog\/10232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/media\/10233"}],"wp:attachment":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/media?parent=10232"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog-category?post=10232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}