{"id":9143,"date":"2021-07-15T08:52:05","date_gmt":"2021-07-15T06:52:05","guid":{"rendered":"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/"},"modified":"2021-07-15T08:52:05","modified_gmt":"2021-07-15T06:52:05","slug":"plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp","status":"publish","type":"blog","link":"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/","title":{"rendered":"Plan de trabajo para el segundo semestre de 2021 ya fue presentado por el CTCP"},"content":{"rendered":"<p>El Consejo T\u00e9cnico de la Contadur\u00eda P\u00fablica -CTCP- remiti\u00f3 a las direcciones de Regulaci\u00f3n de los ministerios de Hacienda y Cr\u00e9dito P\u00fablico y Comercio, Industria y Turismo, su Plan de Trabajo para el segundo semestre de 2021, en cumplimiento de lo se\u00f1alado en el numeral 1 del art\u00edculo 8 de la Ley 1314 de 2009.<\/p>\n<p>Entre los puntos m\u00e1s destacados de la estrategia para el segundo semestre de 2021 se encuentran:<\/p>\n<ol type=\"1\">\n<li>Presentar las propuestas para la reglamentaci\u00f3n de la profesi\u00f3n del contador p\u00fablico, la actualizaci\u00f3n de la revisor\u00eda fiscal y la elaboraci\u00f3n de un diagn\u00f3stico para establecer mejoras en la formaci\u00f3n de los contadores p\u00fablicos.<\/li>\n<li>Presentar una propuesta regulatoria para el sistema documental contable (anexo 6 del DUR 2420 de 2015), seg\u00fan lo requerido por el art\u00edculo 1 de la Ley 1314 de 2009.<\/li>\n<li>Expedir las recomendaciones pertinentes para la actualizaci\u00f3n de las Normas de Contabilidad, de Informaci\u00f3n Financiera y de Aseguramiento de la Informaci\u00f3n.<\/li>\n<li>Realizar una propuesta para la modernizaci\u00f3n de la revisor\u00eda fiscal en Colombia.<\/li>\n<\/ol>\n<p>El CTCP continuar\u00e1 dando respuesta a las consultas formuladas por los ciudadanos y realizando actividades de divulgaci\u00f3n, para fomentar el conocimiento y comprensi\u00f3n de los marcos t\u00e9cnicos, el relacionamiento con autoridades responsables de la convergencia y otras autoridades, la participaci\u00f3n en organismos y foros internacionales y las actividades administrativas y de gesti\u00f3n interna.<\/p>\n<blockquote class=\"wp-block-quote\">\n<p>Fuente<\/p>\n<p><cite>C<a href=\"https:\/\/www.ctcp.gov.co\/\">onsejo T\u00e9cnico de la Contadur\u00eda P\u00fablica \u2013 CTCP<\/a><\/cite><\/p><\/blockquote>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo T\u00e9cnico de la Contadur\u00eda P\u00fablica -CTCP- remiti\u00f3 a las direcciones de Regulaci\u00f3n de los ministerios de Hacienda y Cr\u00e9dito P\u00fablico y Comercio, Industria y Turismo, su Plan de [&hellip;]<\/p>\n","protected":false},"featured_media":9144,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[],"class_list":["post-9143","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plan de trabajo para el segundo semestre de 2021 ya fue presentado por el CTCP - Auren Colombia<\/title>\n<meta name=\"description\" content=\"El Consejo T\u00e9cnico de la Contadur\u00eda P\u00fablica -CTCP- remiti\u00f3 a las direcciones de Regulaci\u00f3n de los ministerios de Hacienda y Cr\u00e9dito...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan de trabajo para el segundo semestre de 2021 ya fue presentado por el CTCP - Auren Colombia\" \/>\n<meta property=\"og:description\" content=\"El Consejo T\u00e9cnico de la Contadur\u00eda P\u00fablica -CTCP- remiti\u00f3 a las direcciones de Regulaci\u00f3n de los ministerios de Hacienda y Cr\u00e9dito...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren Colombia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/co\/wp-content\/uploads\/2021\/07\/CTCP-2-scaled-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AurenColombia\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\\\/\",\"name\":\"Plan de trabajo para el segundo semestre de 2021 ya fue presentado por el CTCP - Auren Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/CTCP-2-scaled-2.jpg\",\"datePublished\":\"2021-07-15T06:52:05+00:00\",\"description\":\"El Consejo T\u00e9cnico de la Contadur\u00eda P\u00fablica -CTCP- remiti\u00f3 a las direcciones de Regulaci\u00f3n de los ministerios de Hacienda y Cr\u00e9dito...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/CTCP-2-scaled-2.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/CTCP-2-scaled-2.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan de trabajo para el segundo semestre de 2021 ya fue presentado por el CTCP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/\",\"name\":\"Auren Colombia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#organization\",\"name\":\"Auren Colombia\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren Colombia\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/AurenColombia\",\"https:\\\/\\\/www.instagram.com\\\/aurencolombia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRYoGRMR_k4oVWesdErApmA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/auren-colombia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan de trabajo para el segundo semestre de 2021 ya fue presentado por el CTCP - Auren Colombia","description":"El Consejo T\u00e9cnico de la Contadur\u00eda P\u00fablica -CTCP- remiti\u00f3 a las direcciones de Regulaci\u00f3n de los ministerios de Hacienda y Cr\u00e9dito...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/","og_locale":"es_ES","og_type":"article","og_title":"Plan de trabajo para el segundo semestre de 2021 ya fue presentado por el CTCP - Auren Colombia","og_description":"El Consejo T\u00e9cnico de la Contadur\u00eda P\u00fablica -CTCP- remiti\u00f3 a las direcciones de Regulaci\u00f3n de los ministerios de Hacienda y Cr\u00e9dito...","og_url":"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/","og_site_name":"Auren Colombia","og_image":[{"width":2560,"height":1707,"url":"https:\/\/auren.com\/co\/wp-content\/uploads\/2021\/07\/CTCP-2-scaled-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AurenColombia","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/","url":"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/","name":"Plan de trabajo para el segundo semestre de 2021 ya fue presentado por el CTCP - Auren Colombia","isPartOf":{"@id":"https:\/\/auren.com\/co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/co\/wp-content\/uploads\/2021\/07\/CTCP-2-scaled-2.jpg","datePublished":"2021-07-15T06:52:05+00:00","description":"El Consejo T\u00e9cnico de la Contadur\u00eda P\u00fablica -CTCP- remiti\u00f3 a las direcciones de Regulaci\u00f3n de los ministerios de Hacienda y Cr\u00e9dito...","breadcrumb":{"@id":"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/#primaryimage","url":"https:\/\/auren.com\/co\/wp-content\/uploads\/2021\/07\/CTCP-2-scaled-2.jpg","contentUrl":"https:\/\/auren.com\/co\/wp-content\/uploads\/2021\/07\/CTCP-2-scaled-2.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/co\/blog\/plan-de-trabajo-para-el-segundo-semestre-de-2021-ya-fue-presentado-por-el-ctcp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/co\/"},{"@type":"ListItem","position":2,"name":"Plan de trabajo para el segundo semestre de 2021 ya fue presentado por el CTCP"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/co\/#website","url":"https:\/\/auren.com\/co\/","name":"Auren Colombia","description":"","publisher":{"@id":"https:\/\/auren.com\/co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/co\/#organization","name":"Auren Colombia","url":"https:\/\/auren.com\/co\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/co\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/co\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/co\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren Colombia"},"image":{"@id":"https:\/\/auren.com\/co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/AurenColombia","https:\/\/www.instagram.com\/aurencolombia\/","https:\/\/www.youtube.com\/channel\/UCRYoGRMR_k4oVWesdErApmA","https:\/\/www.linkedin.com\/company\/auren-colombia"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog\/9143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog\/9143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/media\/9144"}],"wp:attachment":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/media?parent=9143"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog-category?post=9143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}