{"id":9963,"date":"2020-12-02T11:02:48","date_gmt":"2020-12-02T10:02:48","guid":{"rendered":"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/"},"modified":"2020-12-02T11:02:48","modified_gmt":"2020-12-02T10:02:48","slug":"implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion","status":"publish","type":"blog","link":"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/","title":{"rendered":"Implementaci\u00f3n de herramientas tecnol\u00f3gicas para la solicitud de licencias de construcci\u00f3n"},"content":{"rendered":"<p>Con ocasi\u00f3n del COVID-19, las din\u00e1micas de la vida cotidiana se vieron afectadas dr\u00e1sticamente y los procedimientos ante entidades administrativas no son la excepci\u00f3n. En este contexto, m\u00faltiples procedimientos han sido adaptados a escenarios virtuales, debido a la imposibilidad de adelantarlos de manera presencial. Uno de estos procedimientos es la expedici\u00f3n de licencias de construcci\u00f3n en la modalidad de obra nueva.<\/p>\n<p>El Ministerio de Vivienda Ciudad y Territorio expidi\u00f3 la Resoluci\u00f3n No. 441 de 1 de septiembre de 2020, por medio del cual fija los lineamientos para la expedici\u00f3n de las licencias de construcci\u00f3n antes mencionadas. Adicionalmente, el Ministerio define el ABC de un plan piloto que pretende capitalizar experiencias tanto de particulares como de autoridades urban\u00edsticas relativas al tr\u00e1mite de licencias de manera virtual.<\/p>\n<p>La Resoluci\u00f3n antes se\u00f1alada es una manifestaci\u00f3n clara de la voluntad de implementar la aplicaci\u00f3n de herramientas tecnol\u00f3gicas en la solicitud y concesi\u00f3n de licencias de construcci\u00f3n. Por \u00faltimo, es de resaltar que la Resoluci\u00f3n No. 441 emplea la firma digital, al paso que modifica la noci\u00f3n tradicional de \u201cSede f\u00edsica\u201d del Estado para reemplazarla por una sede virtual.<\/p>\n<blockquote class=\"wp-block-quote\">\n<p>Fuente<\/p>\n<p><cite><a href=\"http:\/\/curaduria2bogota.com.co\/1\/formatos\/RESOLUCION-441-2020.pdf\">Resoluci\u00f3n No. 441 de 1 de septiembre de 2020 del Ministerio de Vivienda Ciudad y Territorio.<\/a><\/cite><\/p><\/blockquote>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con ocasi\u00f3n del COVID-19, las din\u00e1micas de la vida cotidiana se vieron afectadas dr\u00e1sticamente y los procedimientos ante entidades administrativas no son la excepci\u00f3n. En este contexto, m\u00faltiples procedimientos han [&hellip;]<\/p>\n","protected":false},"featured_media":9964,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[],"class_list":["post-9963","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Implementaci\u00f3n de herramientas tecnol\u00f3gicas para la solicitud de licencias de construcci\u00f3n - Auren Colombia<\/title>\n<meta name=\"description\" content=\"Con ocasi\u00f3n del COVID-19, las din\u00e1micas de la vida cotidiana se vieron afectadas dr\u00e1sticamente y los procedimientos ante entidades....\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Implementaci\u00f3n de herramientas tecnol\u00f3gicas para la solicitud de licencias de construcci\u00f3n - Auren Colombia\" \/>\n<meta property=\"og:description\" content=\"Con ocasi\u00f3n del COVID-19, las din\u00e1micas de la vida cotidiana se vieron afectadas dr\u00e1sticamente y los procedimientos ante entidades....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren Colombia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/12\/licencias-de-construccion-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"934\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AurenColombia\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\\\/\",\"name\":\"Implementaci\u00f3n de herramientas tecnol\u00f3gicas para la solicitud de licencias de construcci\u00f3n - Auren Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/licencias-de-construccion-1.jpg\",\"datePublished\":\"2020-12-02T10:02:48+00:00\",\"description\":\"Con ocasi\u00f3n del COVID-19, las din\u00e1micas de la vida cotidiana se vieron afectadas dr\u00e1sticamente y los procedimientos ante entidades....\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/licencias-de-construccion-1.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/licencias-de-construccion-1.jpg\",\"width\":1400,\"height\":934},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Implementaci\u00f3n de herramientas tecnol\u00f3gicas para la solicitud de licencias de construcci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/\",\"name\":\"Auren Colombia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#organization\",\"name\":\"Auren Colombia\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren Colombia\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/AurenColombia\",\"https:\\\/\\\/www.instagram.com\\\/aurencolombia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRYoGRMR_k4oVWesdErApmA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/auren-colombia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Implementaci\u00f3n de herramientas tecnol\u00f3gicas para la solicitud de licencias de construcci\u00f3n - Auren Colombia","description":"Con ocasi\u00f3n del COVID-19, las din\u00e1micas de la vida cotidiana se vieron afectadas dr\u00e1sticamente y los procedimientos ante entidades....","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/","og_locale":"es_ES","og_type":"article","og_title":"Implementaci\u00f3n de herramientas tecnol\u00f3gicas para la solicitud de licencias de construcci\u00f3n - Auren Colombia","og_description":"Con ocasi\u00f3n del COVID-19, las din\u00e1micas de la vida cotidiana se vieron afectadas dr\u00e1sticamente y los procedimientos ante entidades....","og_url":"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/","og_site_name":"Auren Colombia","og_image":[{"width":1400,"height":934,"url":"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/12\/licencias-de-construccion-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AurenColombia","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/","url":"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/","name":"Implementaci\u00f3n de herramientas tecnol\u00f3gicas para la solicitud de licencias de construcci\u00f3n - Auren Colombia","isPartOf":{"@id":"https:\/\/auren.com\/co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/12\/licencias-de-construccion-1.jpg","datePublished":"2020-12-02T10:02:48+00:00","description":"Con ocasi\u00f3n del COVID-19, las din\u00e1micas de la vida cotidiana se vieron afectadas dr\u00e1sticamente y los procedimientos ante entidades....","breadcrumb":{"@id":"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/#primaryimage","url":"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/12\/licencias-de-construccion-1.jpg","contentUrl":"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/12\/licencias-de-construccion-1.jpg","width":1400,"height":934},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/co\/blog\/implementacion-de-herramientas-tecnologicas-para-la-solicitud-de-licencias-de-construccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/co\/"},{"@type":"ListItem","position":2,"name":"Implementaci\u00f3n de herramientas tecnol\u00f3gicas para la solicitud de licencias de construcci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/co\/#website","url":"https:\/\/auren.com\/co\/","name":"Auren Colombia","description":"","publisher":{"@id":"https:\/\/auren.com\/co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/co\/#organization","name":"Auren Colombia","url":"https:\/\/auren.com\/co\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/co\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/co\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/co\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren Colombia"},"image":{"@id":"https:\/\/auren.com\/co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/AurenColombia","https:\/\/www.instagram.com\/aurencolombia\/","https:\/\/www.youtube.com\/channel\/UCRYoGRMR_k4oVWesdErApmA","https:\/\/www.linkedin.com\/company\/auren-colombia"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog\/9963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog\/9963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/media\/9964"}],"wp:attachment":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/media?parent=9963"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog-category?post=9963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}