{"id":9972,"date":"2020-12-02T10:35:08","date_gmt":"2020-12-02T09:35:08","guid":{"rendered":"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/"},"modified":"2020-12-02T10:35:08","modified_gmt":"2020-12-02T09:35:08","slug":"superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020","status":"publish","type":"blog","link":"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/","title":{"rendered":"Superintendencia Financiera fija la tasa de inter\u00e9s moratorio para efectos fiscales del mes de diciembre de 2020"},"content":{"rendered":"<p>La Superintendencia Financiera de Colombia emiti\u00f3 la Resoluci\u00f3n No. 1034 del 26 de noviembre de 2020, por medio de la cual certifica el inter\u00e9s bancario corriente efectivo anual para la modalidad de cr\u00e9dito de consumo y ordinario en un 17,46%,lo cual representa una disminuci\u00f3n de 38 puntos b\u00e1sicos (-0.38%) en relaci\u00f3n con la anterior certificaci\u00f3n (17.84%).<\/p>\n<p>De conformidad con lo establecido en el art\u00edculo 635 del Estatuto Tributario el inter\u00e9s remuneratorio y moratorio (17,46%) no podr\u00e1 exceder 1,5 veces el porcentaje ya mencionado (es decir 26,19%) menos dos puntos porcentuales, para un resultado de 24,19% efectivo anual.<\/p>\n<p>As\u00ed, la tasa de inter\u00e9s moratorio aplicable en el mes de diciembre de 2020 para efectos tributarios, corresponde a 24,19% efectivo anual.<\/p>\n<p>Por \u00faltimo,en relaci\u00f3n con otras certificaciones vigentes,vale la pena recordar que la Superintendencia Financiera, en desarrollo de sus atribuciones legales y reglamentarias, mediante la Resoluci\u00f3n 0869 de 2020, certific\u00f3 el inter\u00e9s bancario corriente para las modalidades de microcr\u00e9dito y consumo de bajo monto, en los siguientes t\u00e9rminos:<\/p>\n<figure class=\"wp-block-table\">\n<table>\n<tbody>\n<tr>\n<td><strong>Modalidad de cr\u00e9dito<\/strong><\/td>\n<td><strong>Inter\u00e9s Bancario Corriente<\/strong><\/td>\n<td><strong>Vigencia<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Microcr\u00e9dito<\/td>\n<td>37.72%<\/td>\n<td>1 de octubre al 31 de diciembre de 2020<\/td>\n<\/tr>\n<tr>\n<td>Consumo de bajo monto<\/td>\n<td>32.42%<\/td>\n<td>1 de octubre de 2020 al 30 de septiembre de 2021<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/figure>\n<blockquote class=\"wp-block-quote\">\n<p>Fuente<\/p>\n<p><cite><a href=\"https:\/\/actualicese.com\/resolucion-1034-del-26-11-2020\/\">Resoluci\u00f3n No. 1034 del 26 de noviembre de 2020 \u2013 Superintendencia Financiera de Colombia<\/a><\/cite><\/p><\/blockquote>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Superintendencia Financiera de Colombia emiti\u00f3 la Resoluci\u00f3n No. 1034 del 26 de noviembre de 2020, por medio de la cual certifica el inter\u00e9s bancario corriente efectivo anual para la [&hellip;]<\/p>\n","protected":false},"featured_media":9973,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[],"class_list":["post-9972","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Superintendencia Financiera fija la tasa de inter\u00e9s moratorio para efectos fiscales del mes de diciembre de 2020 - Auren Colombia<\/title>\n<meta name=\"description\" content=\"La Superintendencia Financiera de Colombia emiti\u00f3 la Resoluci\u00f3n No. 1034 del 26 de noviembre de 2020, por medio de la cual certifica...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Superintendencia Financiera fija la tasa de inter\u00e9s moratorio para efectos fiscales del mes de diciembre de 2020 - Auren Colombia\" \/>\n<meta property=\"og:description\" content=\"La Superintendencia Financiera de Colombia emiti\u00f3 la Resoluci\u00f3n No. 1034 del 26 de noviembre de 2020, por medio de la cual certifica...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren Colombia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/12\/Superintendencia-Financiera-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"934\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AurenColombia\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\\\/\",\"name\":\"Superintendencia Financiera fija la tasa de inter\u00e9s moratorio para efectos fiscales del mes de diciembre de 2020 - Auren Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Superintendencia-Financiera-1.jpg\",\"datePublished\":\"2020-12-02T09:35:08+00:00\",\"description\":\"La Superintendencia Financiera de Colombia emiti\u00f3 la Resoluci\u00f3n No. 1034 del 26 de noviembre de 2020, por medio de la cual certifica...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Superintendencia-Financiera-1.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/Superintendencia-Financiera-1.jpg\",\"width\":1400,\"height\":934},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/blog\\\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Superintendencia Financiera fija la tasa de inter\u00e9s moratorio para efectos fiscales del mes de diciembre de 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/\",\"name\":\"Auren Colombia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#organization\",\"name\":\"Auren Colombia\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/co\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren Colombia\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/AurenColombia\",\"https:\\\/\\\/www.instagram.com\\\/aurencolombia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCRYoGRMR_k4oVWesdErApmA\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/auren-colombia\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Superintendencia Financiera fija la tasa de inter\u00e9s moratorio para efectos fiscales del mes de diciembre de 2020 - Auren Colombia","description":"La Superintendencia Financiera de Colombia emiti\u00f3 la Resoluci\u00f3n No. 1034 del 26 de noviembre de 2020, por medio de la cual certifica...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/","og_locale":"es_ES","og_type":"article","og_title":"Superintendencia Financiera fija la tasa de inter\u00e9s moratorio para efectos fiscales del mes de diciembre de 2020 - Auren Colombia","og_description":"La Superintendencia Financiera de Colombia emiti\u00f3 la Resoluci\u00f3n No. 1034 del 26 de noviembre de 2020, por medio de la cual certifica...","og_url":"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/","og_site_name":"Auren Colombia","og_image":[{"width":1400,"height":934,"url":"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/12\/Superintendencia-Financiera-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AurenColombia","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/","url":"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/","name":"Superintendencia Financiera fija la tasa de inter\u00e9s moratorio para efectos fiscales del mes de diciembre de 2020 - Auren Colombia","isPartOf":{"@id":"https:\/\/auren.com\/co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/12\/Superintendencia-Financiera-1.jpg","datePublished":"2020-12-02T09:35:08+00:00","description":"La Superintendencia Financiera de Colombia emiti\u00f3 la Resoluci\u00f3n No. 1034 del 26 de noviembre de 2020, por medio de la cual certifica...","breadcrumb":{"@id":"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/#primaryimage","url":"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/12\/Superintendencia-Financiera-1.jpg","contentUrl":"https:\/\/auren.com\/co\/wp-content\/uploads\/2020\/12\/Superintendencia-Financiera-1.jpg","width":1400,"height":934},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/co\/blog\/superintendencia-financiera-fija-la-tasa-de-interes-moratorio-para-efectos-fiscales-del-mes-de-diciembre-de-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/co\/"},{"@type":"ListItem","position":2,"name":"Superintendencia Financiera fija la tasa de inter\u00e9s moratorio para efectos fiscales del mes de diciembre de 2020"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/co\/#website","url":"https:\/\/auren.com\/co\/","name":"Auren Colombia","description":"","publisher":{"@id":"https:\/\/auren.com\/co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/co\/#organization","name":"Auren Colombia","url":"https:\/\/auren.com\/co\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/co\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/co\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/co\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren Colombia"},"image":{"@id":"https:\/\/auren.com\/co\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/AurenColombia","https:\/\/www.instagram.com\/aurencolombia\/","https:\/\/www.youtube.com\/channel\/UCRYoGRMR_k4oVWesdErApmA","https:\/\/www.linkedin.com\/company\/auren-colombia"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog\/9972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog\/9972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/media\/9973"}],"wp:attachment":[{"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/media?parent=9972"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/auren.com\/co\/wp-json\/wp\/v2\/blog-category?post=9972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}