{"id":7176,"date":"2019-09-17T11:24:12","date_gmt":"2019-09-17T09:24:12","guid":{"rendered":"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/"},"modified":"2019-09-17T11:24:12","modified_gmt":"2019-09-17T09:24:12","slug":"que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo","status":"publish","type":"blog","link":"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/","title":{"rendered":"\u00bfQu\u00e9 debe saber antes de negociar con un inversor de capital riesgo?"},"content":{"rendered":"<p class=\"text-justify\">En art\u00edculos anteriores del Blog de Corporate ya hemos tratado sobre el tipo de empresas en las que invierten los Fondos de Capital Riesgo y de la utilidad y las ventajas de contar con ellos en el capital de las compa\u00f1\u00edas. En esta entrega, nos centraremos en descubrir qu\u00e9 cuestiones y aspectos entran a formar parte de las negociaciones y operaciones con este tipo de inversores, para las que se debe estar preparado y tener respuesta.<\/p>\n<p class=\"text-justify\">Las inversiones de capital riesgo constituyen un modelo de transacci\u00f3n en la que, posiblemente, usted tenga que realizar alguna concesi\u00f3n cuando acuda a la mesa de negociaci\u00f3n. No obstante, y dado que el objetivo de un Fondo de Capital Riesgo es \u201ccrear valor\u201d, deber\u00e1 preguntarse \u00bfqu\u00e9 valor tiene mi empresa antes de que entre el inversor que aporta los nuevos fondos? y \u00bfqu\u00e9 tipo de contraprestaci\u00f3n recibir\u00e9 a cambio de su inversi\u00f3n? A continuaci\u00f3n, se relacionan algunos de los aspectos m\u00e1s relevantes que acompa\u00f1an a estas transacciones.   <\/p>\n<p class=\"text-justify\"><strong><u>Valoraci\u00f3n de la Compa\u00f1\u00eda<\/u><\/strong>   <\/p>\n<p class=\"text-justify\">A pesar de que el valor contable de su empresa pueda ser peque\u00f1o, el valor de mercado de esta podr\u00eda ser mayor dependiendo de los resultados, el potencial de ventas y la posici\u00f3n en el sector en el que desarrolla su actividad, los contratos recurrentes, el fondo de comercio, la existencia de patentes, la tecnolog\u00eda, y otros m\u00faltiples factores. Siempre resultar\u00e1 m\u00e1s f\u00e1cil defender el valor asignado a la empresa si cuenta con unas proyecciones soportadas o validadas por un asesor financiero que las haya revisado. Esta fase es muy relevante y una de las m\u00e1s duras de la negociaci\u00f3n, ya que ser\u00e1 la que determine el valor de las acciones\/participaciones en las que vaya a invertir el Fondo de Capital Riesgo y el potencial de su retorno, as\u00ed como su exposici\u00f3n posterior al valor futuro de la Compa\u00f1\u00eda.   <\/p>\n<p class=\"text-justify\"><strong><u>Estructura de los Fondos Propios<\/u><\/strong>   <\/p>\n<p class=\"text-justify\">Por la inversi\u00f3n que realizan, los Fondos de Capital Riesgo tratar\u00e1n siempre de minimizar los riesgos asociados a ella. En este sentido, los instrumentos de inversi\u00f3n que m\u00e1s com\u00fanmente solemos encontrar en este tipo de Operaciones son: en el supuesto de sociedades an\u00f3nimas, (i) acciones ordinarias, (ii) <em>warrants<\/em>, y (iii) derechos de suscripci\u00f3n preferente o warrants, y (iv) pr\u00e9stamos participativos, entre otros.   <\/p>\n<p class=\"text-justify\">Para compartir el mismo nivel de riesgo y retorno, en la medida de lo posible, ser\u00eda recomendable que la mayor parte de la inversi\u00f3n se realice en acciones ordinarias. Adicionalmente a esta opci\u00f3n existe como instrumento h\u00edbrido las obligaciones convertibles en acciones.&nbsp;   <\/p>\n<p class=\"text-justify\">Los <em>warrants<\/em>, otorgan a su titular el derecho a comprar o vender un activo subyacente (en este caso las acciones de la Compa\u00f1\u00eda). En tiempos de bonanza de la compa\u00f1\u00eda, el ejercicio de estos&nbsp;<em>warrants<\/em>&nbsp;limitar\u00e1 el valor que a usted le corresponda por su participaci\u00f3n en un evento de salida conjunta, como consecuencia de la diluci\u00f3n a la que dar\u00e1 lugar el ejercicio de dichos warrants.   <\/p>\n<p class=\"text-justify\">En el caso de los pr\u00e9stamos participativos, en momentos de dificultades financieras, estos tienen una prelaci\u00f3n para su devoluci\u00f3n frente a las acciones mientras que, si las cosas van bien, su tipo de inter\u00e9s variable, condicionado a la obtenci\u00f3n de participar de los beneficios determinados resultados por parte de la compa\u00f1\u00eda, minorar\u00e1 sus beneficios. Por otra parte, este instrumento tiene la ventaja de que no diluye el capital de la compa\u00f1\u00eda.   <\/p>\n<p class=\"text-justify\"><strong><u>Estructura Financiera de la Transacci\u00f3n<\/u><\/strong>   <\/p>\n<p class=\"text-justify\">Es habitual que los inversores de Capital Riesgo quieran financiar parte de la transacci\u00f3n con deuda financiera. De esta manera, estos querr\u00e1n acordar con usted cu\u00e1l es el nivel de endeudamiento\/apalancamiento \u00f3ptimo para poder maximizar los retornos obtenidos por ambos en la transacci\u00f3n. En este sentido, usted deber\u00e1 sentirse confortable y estar alineado con el perfil de riesgo financiero del Fondo.   <\/p>\n<p class=\"text-justify\"><strong><u>Cl\u00e1usula antidiluci\u00f3n<\/u><\/strong><\/p>\n<p class=\"text-justify\">Si la compa\u00f1\u00eda empezara a ir mal y se precisara de nuevos fondos, es posible que no tenga m\u00e1s opci\u00f3n que llevar a cabo una emisi\u00f3n de acciones ordinarias m\u00e1s baratas que las emitidas en el pasado. Aunque hay m\u00faltiples alternativas, una opci\u00f3n para mitigar la diluci\u00f3n, por ejemplo, consistir\u00eda en negociar que se apliquen precios medios ponderados por acci\u00f3n de todos los t\u00edtulos en circulaci\u00f3n despu\u00e9s de la emisi\u00f3n de las acciones m\u00e1s baratas.   <\/p>\n<p class=\"text-justify\"><strong><u>Acuerdo entre accionistas (SHA)<\/u><\/strong>   <\/p>\n<p class=\"text-justify\">El acuerdo entre accionistas es un elemento esencial para la convivencia posterior con los Fondos de Capital Riesgo. En este sentido es fundamental que exista un equilibrio en la representaci\u00f3n de cada una de las partes y, en el caso de que los fundadores se queden con participaciones minoritarias, es relevante establecer cu\u00e1les ser\u00e1n las situaciones y decisiones que requerir\u00e1n de mayor\u00edas reforzadas para su aprobaci\u00f3n (por ejemplo, ampliaciones de capital, aprobaci\u00f3n de presupuestos, inversiones estrat\u00e9gicas, fusiones con otras compa\u00f1\u00edas, acceso a la informaci\u00f3n, liquidaci\u00f3n de activos, as\u00ed como intentar articular un mecanismo para la eventual salida de su participaci\u00f3n minoritaria.   <\/p>\n<p class=\"text-justify\"><strong><u>Limitaci\u00f3n en las Responsabilidades y Garant\u00edas<\/u><\/strong><\/p>\n<p class=\"text-justify\">Si usted vende el 100% de una compa\u00f1\u00eda a un Fondo de Capital Riesgo o se queda con una participaci\u00f3n tras la entrada de este, los requerimientos que le realizar\u00e1n en cuanto a responsabilidades y garant\u00edas ser\u00e1n diferentes. En cualquier caso, siempre existen alternativas para acotar el l\u00edmite de responsabilidades que usted est\u00e1 dispuesto a asumir tras la eventual transacci\u00f3n. Trate de minimizar siempre esta cuesti\u00f3n y m\u00e1s en el caso en el que usted se quede participando en el Capital de la compa\u00f1\u00eda. Asimismo, tambi\u00e9n es conveniente negociar un cierto importe de franquicia de manera que para contingencias menores, no relevantes, se eviten reclamaciones posteriores al cierre de la transacci\u00f3n.&nbsp;   <\/p>\n<p class=\"text-justify\"><strong><u>Contrato de trabajo<\/u><\/strong>   <\/p>\n<p class=\"text-justify\">Cuando un Fondo de Capital Riesgo entra en el capital de una compa\u00f1\u00eda, idealmente querr\u00e1 que los fundadores o gestores se queden vinculados a ella y participen de la gesti\u00f3n. Por ello es importante que se negocien adecuadamente las condiciones salariales y laborales, bonus, cl\u00e1usulas de salida (<em>bad leaver \/ good leaver<\/em>), cl\u00e1usula de&nbsp;<em>non compete, non solicitation<\/em>, etc&hellip;   <\/p>\n<p class=\"text-justify\"><strong><u>Otros<\/u><\/strong>   <\/p>\n<p class=\"text-justify\">Otros aspectos con los que habitualmente se encontrar\u00e1 a la hora de evaluar la entrada de un inversor de Capital Riesgo en su Compa\u00f1\u00eda son los siguientes:    <\/p>\n<ul class=\"text-justify\"><\/ul>\n<ol>\n<li class=\"text-justify\">Participaci\u00f3n de aqu\u00e9l en la gesti\u00f3n financiera o en aquellas \u00e1reas donde el Capital Riesgo piense que la compa\u00f1\u00eda debe mejorar. En todo caso, para aquellas decisiones importantes para el control y gesti\u00f3n de la compa\u00f1\u00eda, siempre se cuenta con margen de negociaci\u00f3n, aun cuando los fundadores\/due\u00f1os gestores se queden en una posici\u00f3n minoritaria en el capital.    <\/li>\n<li class=\"text-justify\">Cambio de control o venta de las participaciones del Fondo a un tercero que eventualmente pueda ser perjudicial para usted como accionista minoritario. Aqu\u00ed ser\u00e1 muy com\u00fan que tambi\u00e9n le soliciten la incorporaci\u00f3n de cl\u00e1usulas de <em>Tag Along<\/em> (acompa\u00f1amiento) y <em>Drag Along<\/em> (arrastre).    <\/li>\n<li class=\"text-justify\">Definici\u00f3n del Governance de la compa\u00f1\u00eda que deber\u00e1 estar adecuadamente recogido en el SHA. <\/li>\n<\/ol>\n<p class=\"text-justify\"><strong>Amaya Arag\u00f3n Valor, Socia Auren Corporate<\/strong><\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En art\u00edculos anteriores del Blog de Corporate ya hemos tratado sobre el tipo de empresas en las que invierten los Fondos de Capital Riesgo y de la utilidad y las ventajas de contar con ellos en el capital de las compa\u00f1\u00edas. En esta entrega, nos centraremos en descubrir qu\u00e9 cuestiones y aspectos entran a formar parte de las negociaciones y operaciones con este tipo de inversores, para las que se debe estar preparado y tener respuesta.<\/p>\n","protected":false},"featured_media":7177,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[],"class_list":["post-7176","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 debe saber antes de negociar con un inversor de capital riesgo? - Auren Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 debe saber antes de negociar con un inversor de capital riesgo? - Auren Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"En art\u00edculos anteriores del Blog de Corporate ya hemos tratado sobre el tipo de empresas en las que invierten los Fondos de Capital Riesgo y de la utilidad y las ventajas de contar con ellos en el capital de las compa\u00f1\u00edas. En esta entrega, nos centraremos en descubrir qu\u00e9 cuestiones y aspectos entran a formar parte de las negociaciones y operaciones con este tipo de inversores, para las que se debe estar preparado y tener respuesta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/es\/wp-content\/uploads\/2019\/09\/190917-articulo-amaya-aragon-imagen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auren_spain\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\\\/\",\"name\":\"\u00bfQu\u00e9 debe saber antes de negociar con un inversor de capital riesgo? - Auren Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/190917-articulo-amaya-aragon-imagen.jpg\",\"datePublished\":\"2019-09-17T09:24:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/190917-articulo-amaya-aragon-imagen.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/190917-articulo-amaya-aragon-imagen.jpg\",\"width\":1920,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 debe saber antes de negociar con un inversor de capital riesgo?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"name\":\"Auren\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\"},\"alternateName\":\"Auren\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\",\"name\":\"Auren\",\"alternateName\":\"Auren\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/auren_spain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aurenspainserviciosprofesionales\",\"https:\\\/\\\/www.youtube.com\\\/@AurenEsp\",\"https:\\\/\\\/www.instagram.com\\\/auren_spain\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 debe saber antes de negociar con un inversor de capital riesgo? - Auren Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 debe saber antes de negociar con un inversor de capital riesgo? - Auren Espa\u00f1a","og_description":"En art\u00edculos anteriores del Blog de Corporate ya hemos tratado sobre el tipo de empresas en las que invierten los Fondos de Capital Riesgo y de la utilidad y las ventajas de contar con ellos en el capital de las compa\u00f1\u00edas. En esta entrega, nos centraremos en descubrir qu\u00e9 cuestiones y aspectos entran a formar parte de las negociaciones y operaciones con este tipo de inversores, para las que se debe estar preparado y tener respuesta.","og_url":"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/","og_site_name":"Auren","og_image":[{"width":1920,"height":655,"url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2019\/09\/190917-articulo-amaya-aragon-imagen.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auren_spain","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/","url":"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/","name":"\u00bfQu\u00e9 debe saber antes de negociar con un inversor de capital riesgo? - Auren Espa\u00f1a","isPartOf":{"@id":"https:\/\/auren.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2019\/09\/190917-articulo-amaya-aragon-imagen.jpg","datePublished":"2019-09-17T09:24:12+00:00","breadcrumb":{"@id":"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/#primaryimage","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2019\/09\/190917-articulo-amaya-aragon-imagen.jpg","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2019\/09\/190917-articulo-amaya-aragon-imagen.jpg","width":1920,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/es\/blog\/que-debe-saber-antes-de-negociar-con-un-inversor-de-capital-riesgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 debe saber antes de negociar con un inversor de capital riesgo?"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/es\/#website","url":"https:\/\/auren.com\/es\/","name":"Auren","description":"","publisher":{"@id":"https:\/\/auren.com\/es\/#organization"},"alternateName":"Auren","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/es\/#organization","name":"Auren","alternateName":"Auren","url":"https:\/\/auren.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren"},"image":{"@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/auren_spain","https:\/\/www.linkedin.com\/company\/aurenspainserviciosprofesionales","https:\/\/www.youtube.com\/@AurenEsp","https:\/\/www.instagram.com\/auren_spain"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog\/7176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog\/7176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media\/7177"}],"wp:attachment":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media?parent=7176"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog-category?post=7176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}