{"id":7233,"date":"2019-06-10T11:49:08","date_gmt":"2019-06-10T09:49:08","guid":{"rendered":"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/"},"modified":"2019-06-10T11:49:08","modified_gmt":"2019-06-10T09:49:08","slug":"tratamiento-fiscal-de-los-alquileres-turisticos","status":"publish","type":"blog","link":"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/","title":{"rendered":"Tratamiento fiscal de los alquileres tur\u00edsticos"},"content":{"rendered":"<p class=\"text-justify\">En el presente anuncio efectuamos un recordatorio sobre el tratamiento fiscal del arrendamiento de inmuebles para uso distinto al de vivienda, concretamente, nos referiremos al arrendamiento para fines tur\u00edsticos, y analizaremos la imposici\u00f3n en el Impuesto sobre el Valor A\u00f1adido, en el Impuesto sobre la Renta de las Persona F\u00edsicas, y en el Impuesto sobre la Renta de No Residentes.<\/p>\n<p class=\"text-justify\">Seg\u00fan se establece en la Ley de Arrendamientos Urbanos, constituye alquiler tur\u00edstico la cesi\u00f3n temporal de uso de una vivienda debidamente amueblada y equipada comercializada en canales de oferta tur\u00edstica con finalidad lucrativa. Por otra parte, se considera arrendamiento para uso distinto al de vivienda aquel que tenga como destino primordial un uso distinto al de satisfacer la necesidad permanente de vivienda del arrendatario.<\/p>\n<p class=\"text-justify\">Atendiendo a estas definiciones, detallamos el tratamiento fiscal de los rendimientos derivados del arrendamiento tur\u00edstico:<\/p>\n<p class=\"text-justify\"><strong>a) En el \u00e1mbito del Impuesto sobre el Valor A\u00f1adido:<\/strong><\/p>\n<p class=\"text-justify\">En el art\u00edculo 20.uno.23\u00ba, b) de la Ley 37\/1992 del IVA (en adelante, LIVA), se establece que est\u00e1n exentos del IVA los arrendamientos de edificios o partes de los mismos destinados a vivienda; la exenci\u00f3n no comprende, los arrendamientos de apartamentos o viviendas amuebladas cuando el arrendador se obligue a la prestaci\u00f3n de alguno de los servicios complementarios propios de la industria hotelera, tales como los de restaurante, limpieza, lavado de ropa u otros an\u00e1logos.   <\/p>\n<p class=\"text-justify\">La doctrina administrativa interpreta que estamos ante el supuesto de prestaci\u00f3n de servicios complementarios propios de la industria hotelera en aquellos casos de prestaci\u00f3n de servicios al cliente de forma permanente y continuada durante su estancia (limpieza peri\u00f3dica del inmueble, cambio de ropa de cama y ba\u00f1o, y puesta a disposici\u00f3n de otros servicios como prensa, custodia de maletas, alimentaci\u00f3n y restauraci\u00f3n); por contra, no se considera que se prestan estos servicios cuando: a) el servicio de limpieza y cambio de ropa se presta \u00fanicamente a la entrada y salida del periodo contratado por cada arrendatario; b) se prestan servicios de limpieza a las zonas comunes del edificio; y, c) se prestan servicios de asistencia t\u00e9cnica y mantenimiento para eventuales reparaciones del inmueble tales como fontaner\u00eda, carpinter\u00eda, cristaler\u00eda, etc.<\/p>\n<p class=\"text-justify\">En definitiva, los ingresos por arrendamiento de alojamientos tur\u00edsticos estar\u00e1n exentos de IVA si no se prestan los servicios complementarios propios de la industria hotelera y, en caso contrario, tributar\u00e1n al 10% de IVA por aplicaci\u00f3n del art\u00edculo 91.uno.2.2\u00ba de la LIVA.<\/p>\n<p class=\"text-justify\">&nbsp;<strong>b) En el \u00e1mbito del Impuesto sobre la Renta de las Persona F\u00edsicas:<\/strong><\/p>\n<p class=\"text-justify\">Con car\u00e1cter general, los rendimientos derivados del alquiler de inmuebles destinados a viviendas tendr\u00e1n la consideraci\u00f3n de rendimientos del capital inmobiliario. Para que proceda esta calificaci\u00f3n, el alquiler se tiene que limitar a la mera puesta a disposici\u00f3n del inmueble durante un periodo de tiempo, sin que vaya acompa\u00f1ado de la prestaci\u00f3n de servicios propios de la industria hotelera.   <\/p>\n<p class=\"text-justify\">Al rendimiento neto del capital inmobiliario no le resultar\u00e1 de aplicaci\u00f3n la reducci\u00f3n del 60% prevista en el art\u00edculo 23.2 de la Ley del IRPF ya que los arrendamientos tur\u00edsticos no tienen por finalidad satisfacer una necesidad permanente de vivienda, sino cubrir una necesidad de car\u00e1cter temporal y con finalidad tur\u00edstica.<\/p>\n<p class=\"text-justify\">Adem\u00e1s, en los periodos de tiempo en los que el inmueble no haya sido objeto de cesi\u00f3n por arrendamiento, se consideran tambi\u00e9n rendimientos del capital inmobiliario la correspondiente imputaci\u00f3n de renta inmobiliaria en aplicaci\u00f3n de lo dispuesto en el art\u00edculo 85 de la Ley del IRPF.<\/p>\n<p class=\"text-justify\">No obstante lo anterior, los rendimientos del arrendamiento tur\u00edstico se pueden considerar como rendimientos de actividades econ\u00f3micas en los siguientes supuestos: a) cuando el arrendador ceda el uso del inmueble y se presten los servicios propios de la industria hotelera: y, b) cuando sin prestar tales servicios, se disponga de una persona con contrato laboral y jornada completa para la realizaci\u00f3n de la actividad econ\u00f3mica de arrendamiento por parte del empresario.<\/p>\n<p class=\"text-justify\"><strong>c) En el \u00e1mbito del Impuesto sobre la Renta de No Residentes:<\/strong><\/p>\n<p class=\"text-justify\">Tambi\u00e9n para las personas f\u00edsicas no residentes propietarias o con derechos de uso y disfrute de inmuebles situados en Espa\u00f1a, y atendiendo a lo dispuesto en cada uno de los Convenios de Doble Imposici\u00f3n suscritos por Espa\u00f1a, los rendimientos obtenidos por los alquileres tur\u00edsticos&nbsp; pueden tributar conforme a la Ley espa\u00f1ola.   <\/p>\n<p class=\"text-justify\">De la misma manera que en el apartado b) anterior se pueden considerar, por un lado, como rendimientos del capital inmobiliario con un tipo de gravamen del 19% para los residentes en la UE, Islandia y Noruega o del 24% para el resto de contribuyentes no residentes, y por otro lado, como rendimientos de actividades econ\u00f3micas por medio de Establecimiento Permanente (EP) con un tipo de gravamen general del 25%.<\/p>\n<p class=\"text-justify\">En los \u00faltimos a\u00f1os est\u00e1 en auge el uso del alojamiento privado para fines tur\u00edsticos en Espa\u00f1a, y la doctrina administrativa no ha sido ajena a este incremento en el uso de los servicios de alojamiento tur\u00edstico, por lo que ha desarrollado una intensa labor doctrinal que no permite afirmar que en la actualidad gozamos de mayor seguridad jur\u00eddica a la hora de interpretar la imposici\u00f3n que afecta a este tipo de arrendamientos.<\/p>\n<p class=\"text-justify\"><strong>Soledad Ortol\u00e1 Domenech, Gerente Auren Abogados y Asesores.<\/strong><\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el presente anuncio efectuamos un recordatorio sobre el tratamiento fiscal del arrendamiento de inmuebles para uso distinto al de vivienda, concretamente, nos referiremos al arrendamiento para fines tur\u00edsticos, y analizaremos la imposici\u00f3n en el Impuesto sobre el Valor A\u00f1adido, en el Impuesto sobre la Renta de las Persona F\u00edsicas, y en el Impuesto sobre la Renta de No Residentes.<\/p>\n","protected":false},"featured_media":7234,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[],"class_list":["post-7233","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tratamiento fiscal de los alquileres tur\u00edsticos - Auren Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tratamiento fiscal de los alquileres tur\u00edsticos - Auren Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"En el presente anuncio efectuamos un recordatorio sobre el tratamiento fiscal del arrendamiento de inmuebles para uso distinto al de vivienda, concretamente, nos referiremos al arrendamiento para fines tur\u00edsticos, y analizaremos la imposici\u00f3n en el Impuesto sobre el Valor A\u00f1adido, en el Impuesto sobre la Renta de las Persona F\u00edsicas, y en el Impuesto sobre la Renta de No Residentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/es\/wp-content\/uploads\/2019\/06\/tratamiento-fiscal-de-loos-alquileres-turisticos-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auren_spain\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/tratamiento-fiscal-de-los-alquileres-turisticos\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/tratamiento-fiscal-de-los-alquileres-turisticos\\\/\",\"name\":\"Tratamiento fiscal de los alquileres tur\u00edsticos - Auren Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/tratamiento-fiscal-de-los-alquileres-turisticos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/tratamiento-fiscal-de-los-alquileres-turisticos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/tratamiento-fiscal-de-loos-alquileres-turisticos-2.jpg\",\"datePublished\":\"2019-06-10T09:49:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/tratamiento-fiscal-de-los-alquileres-turisticos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/tratamiento-fiscal-de-los-alquileres-turisticos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/tratamiento-fiscal-de-los-alquileres-turisticos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/tratamiento-fiscal-de-loos-alquileres-turisticos-2.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/tratamiento-fiscal-de-loos-alquileres-turisticos-2.jpg\",\"width\":1920,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/tratamiento-fiscal-de-los-alquileres-turisticos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tratamiento fiscal de los alquileres tur\u00edsticos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"name\":\"Auren\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\"},\"alternateName\":\"Auren\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\",\"name\":\"Auren\",\"alternateName\":\"Auren\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/auren_spain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aurenspainserviciosprofesionales\",\"https:\\\/\\\/www.youtube.com\\\/@AurenEsp\",\"https:\\\/\\\/www.instagram.com\\\/auren_spain\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tratamiento fiscal de los alquileres tur\u00edsticos - Auren Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/","og_locale":"es_ES","og_type":"article","og_title":"Tratamiento fiscal de los alquileres tur\u00edsticos - Auren Espa\u00f1a","og_description":"En el presente anuncio efectuamos un recordatorio sobre el tratamiento fiscal del arrendamiento de inmuebles para uso distinto al de vivienda, concretamente, nos referiremos al arrendamiento para fines tur\u00edsticos, y analizaremos la imposici\u00f3n en el Impuesto sobre el Valor A\u00f1adido, en el Impuesto sobre la Renta de las Persona F\u00edsicas, y en el Impuesto sobre la Renta de No Residentes.","og_url":"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/","og_site_name":"Auren","og_image":[{"width":1920,"height":655,"url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2019\/06\/tratamiento-fiscal-de-loos-alquileres-turisticos-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auren_spain","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/","url":"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/","name":"Tratamiento fiscal de los alquileres tur\u00edsticos - Auren Espa\u00f1a","isPartOf":{"@id":"https:\/\/auren.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2019\/06\/tratamiento-fiscal-de-loos-alquileres-turisticos-2.jpg","datePublished":"2019-06-10T09:49:08+00:00","breadcrumb":{"@id":"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/#primaryimage","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2019\/06\/tratamiento-fiscal-de-loos-alquileres-turisticos-2.jpg","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2019\/06\/tratamiento-fiscal-de-loos-alquileres-turisticos-2.jpg","width":1920,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/es\/blog\/tratamiento-fiscal-de-los-alquileres-turisticos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tratamiento fiscal de los alquileres tur\u00edsticos"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/es\/#website","url":"https:\/\/auren.com\/es\/","name":"Auren","description":"","publisher":{"@id":"https:\/\/auren.com\/es\/#organization"},"alternateName":"Auren","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/es\/#organization","name":"Auren","alternateName":"Auren","url":"https:\/\/auren.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren"},"image":{"@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/auren_spain","https:\/\/www.linkedin.com\/company\/aurenspainserviciosprofesionales","https:\/\/www.youtube.com\/@AurenEsp","https:\/\/www.instagram.com\/auren_spain"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog\/7233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog\/7233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media\/7234"}],"wp:attachment":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media?parent=7233"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog-category?post=7233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}