{"id":7617,"date":"2017-12-18T10:07:59","date_gmt":"2017-12-18T09:07:59","guid":{"rendered":"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/"},"modified":"2017-12-18T10:07:59","modified_gmt":"2017-12-18T09:07:59","slug":"reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria","status":"publish","type":"blog","link":"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/","title":{"rendered":"Reflexiones sobre los aspectos estrat\u00e9gicos y operativos de la Gesti\u00f3n de Tesorer\u00eda."},"content":{"rendered":"<p class=\"text-justify\">Es muy com\u00fan en el \u00e1mbito empresarial estar expuesto al concepto de gesti\u00f3n de tesorer\u00eda. Este vocablo de uso habitual se instala en la percepci\u00f3n del oyente como la actividad de coordinar cobros y pagos, d\u00e1ndole as\u00ed una visi\u00f3n muy operativa y encuadr\u00e1ndola, por otro lado, en una funci\u00f3n tradicional de la actividad del tesorero.<\/p>\n<p class=\"text-justify\">Sin embargo, nada m\u00e1s lejos de la realidad actual en relaci\u00f3n a lo que esta expresi\u00f3n debe suponer. La gesti\u00f3n de tesorer\u00eda debe orientarse al VALOR, y esta palabra en el mundo de las empresas va \u00edntimamente relacionada con estrategia.<\/p>\n<p class=\"text-justify\">En general cualquier actividad de la empresa debe estar orientada a la generaci\u00f3n de valor. Esto, que es algo muy evidente, por ejemplo, en el \u00e1mbito comercial o productivo, no lo es tanto para actividades m\u00e1s estructurales como la administraci\u00f3n y las finanzas que, hasta la fecha, han sido contempladas como COSTES y por tanto ausentes en la contribuci\u00f3n al valor.<\/p>\n<p class=\"text-justify\">La primera cuesti\u00f3n que necesita de una respuesta es la detallada comprensi\u00f3n de la generaci\u00f3n de la liquidez en la compa\u00f1\u00eda. Una forma de tantas, ser\u00eda expresarlo como sigue:<\/p>\n<figure class=\"text-center\"><img decoding=\"async\" data-src=\"https:\/\/d33c2a5xmvj7uh.cloudfront.net\/images\/originals\/blog-dia-141217-fernando-alvarez-blanco.jpg?v=1513591171\" data-image=\"9993185\" style=\"--smush-placeholder-width: 370px; --smush-placeholder-aspect-ratio: 370\/385;width: 370px; height: 385px;\" width=\"370\" height=\"385\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\"><\/figure>\n<p class=\"text-justify\">El Cash Flow en un periodo determinado es la consecuencia de la <u>generaci\u00f3n de <em>un origen de liquidez procedente de nuestras operaciones<\/em><\/u> (<em>Cash flow de explotaci\u00f3n<\/em>), que ha de satisfacer a las dos fuentes b\u00e1sicas de la estructura financiera de la empresa: los capitales propios y los ajenos (Cash flow de los capitales propios y el servicio neto de la deuda).<\/p>\n<p class=\"text-justify\">Efectivamente, el ciclo de actividad de la empresa nos manifiesta que los financiadores requieren la recuperaci\u00f3n de los capitales invertidos y un rendimiento asociado a su nivel de riesgo en el proyecto empresarial (primas de riesgo), sin una regularidad en este flujo, el ciclo de capital se quiebra y el proyecto empresarial resulta inviable.<\/p>\n<p class=\"text-justify\"><strong>Maximizando el Cash Flow de Explotaci\u00f3n<\/strong><\/p>\n<p class=\"text-justify\">La importancia de la gesti\u00f3n activa de esta magnitud es fundamental y ah\u00ed reside el valor que la tesorer\u00eda debe aportar a la organizaci\u00f3n de forma primaria y con independencia de gestiones secundarias m\u00e1s vinculadas a la propia actividad de la tesorer\u00eda a corto o muy corto plazo (financiaci\u00f3n de d\u00e9ficits transitorios, puntas de tesorer\u00eda, previsiones a muy corto plazo, mapa bancario, etc.).<\/p>\n<p class=\"text-justify\">Deteng\u00e1monos un momento en sus componentes y veamos qu\u00e9 elementos est\u00e1n presentes:<\/p>\n<ul class=\"text-justify\">\n<li class=\"text-justify\"><strong>EBIT (1-t):<\/strong> El beneficio econ\u00f3mico neto de impuestos es una prolongaci\u00f3n del EBITDA y por tanto es la plusval\u00eda devengada de los ingresos sobre los costes. Hablar de ingresos es equivalente a consideraciones directas sobre elementos estrat\u00e9gicos como el posicionamiento de los productos \/ servicios, los nichos de mercado, la capacidad para competir y otros. Hablar de costes implica necesariamente la reflexi\u00f3n sobre la eficiencia en las operaciones y en consecuencia el establecer una estructura de costes (fijo\/variable, directos\/indirectos) adecuada a nuestra l\u00ednea de ingresos.   <\/li>\n<li class=\"text-justify\"><strong>Capital de trabajo<\/strong>: &nbsp;En ocasiones veces denominada \u201cinversi\u00f3n espont\u00e1nea\u201d ya que, a diferencia del CAPEX (el cual mantiene una clara uni\u00f3n con los elementos estrat\u00e9gicos), el capital de trabajo se sit\u00faa en el \u00e1mbito de las pol\u00edticas de la empresa. Evidentemente han de considerarse los aspectos estrat\u00e9gicos que se desprenden del modelo de negocio (nos referimos a los periodos de maduraci\u00f3n que son consecuencia de decisiones de c\u00f3mo competir), pero la actitud de gesti\u00f3n en el corto\/medio plazo es mucho m\u00e1s destacada que en el caso de la inversi\u00f3n estructural.   <\/li>\n<li class=\"text-justify\"><strong>CAPEX<\/strong>: hablamos de una magnitud claramente estrat\u00e9gica como es la inversi\u00f3n estructural y como tal vinculada al largo plazo.<\/li>\n<\/ul>\n<p class=\"text-justify\">En definitiva, <u>el cash flow de explotaci\u00f3n es una prolongaci\u00f3n de todos los aspectos estrat\u00e9gicos y operativos de las sociedades mercantiles<\/u> y de ah\u00ed su complejidad de manejo del mismo. Sin duda, la necesidad de planificaci\u00f3n y control para con este componente de la liquidez es vital en pro de garantizar la viabilidad de la compa\u00f1\u00eda.<\/p>\n<p class=\"text-justify\">Pudiera parecer que todo lo que hemos comentado ha sido de espaldas al mercado. No hemos efectuado referencia alguna al marco macroecon\u00f3mico, a la tecnolog\u00eda, regulaci\u00f3n, los competidores, los clientes, los proveedores &hellip; Etc.<\/p>\n<p class=\"text-justify\">Sin embargo, nada m\u00e1s lejos de la realidad. La consideraci\u00f3n de la estrategia y en continuaci\u00f3n de la misma los aspectos de gesti\u00f3n, es una muestra clara de que todos los elementos antes mencionados deben ser tenidos en cuenta en las etapas de planificaci\u00f3n estrat\u00e9gica para que as\u00ed la mejora de la magnitud \u201ccash flow de explotaci\u00f3n\u201d pueda implementarse con garant\u00edas.<\/p>\n<p class=\"text-justify\">No hemos hecho menci\u00f3n al tipo tributario (t) ya que es un elemento del entorno sobre el que no tenemos capacidad de influir, pero al que no se le debe restar importancia como un componente m\u00e1s de nuestra capacidad para satisfacer las demandas de nuestros financiadores.<\/p>\n<p class=\"text-justify\">Vivir de espaldas a esta realidad de las compa\u00f1\u00edas es un error de magnitud que no nos podemos permitir en las organizaciones, si no queremos poner en peligro la confianza de aquellos que con sus capitales garantizan la continuidad de la compa\u00f1\u00eda y en consecuencia nuestra propia existencia.<\/p>\n<p><strong>&nbsp;Fernando Alvarez Blanco, Socio Auren Corporate<\/strong><\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es muy com\u00fan en el \u00e1mbito empresarial estar expuesto al concepto de gesti\u00f3n de tesorer\u00eda. Este vocablo de uso habitual se instala en la percepci\u00f3n del oyente como la actividad de coordinar cobros y pagos, d\u00e1ndole as\u00ed una visi\u00f3n muy operativa y encuadr\u00e1ndola, por otro lado, en una funci\u00f3n tradicional de la actividad del tesorero.<\/p>\n","protected":false},"featured_media":7618,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[],"class_list":["post-7617","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reflexiones sobre los aspectos estrat\u00e9gicos y operativos de la Gesti\u00f3n de Tesorer\u00eda. - Auren Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reflexiones sobre los aspectos estrat\u00e9gicos y operativos de la Gesti\u00f3n de Tesorer\u00eda. - Auren Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Es muy com\u00fan en el \u00e1mbito empresarial estar expuesto al concepto de gesti\u00f3n de tesorer\u00eda. Este vocablo de uso habitual se instala en la percepci\u00f3n del oyente como la actividad de coordinar cobros y pagos, d\u00e1ndole as\u00ed una visi\u00f3n muy operativa y encuadr\u00e1ndola, por otro lado, en una funci\u00f3n tradicional de la actividad del tesorero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/es\/wp-content\/uploads\/2017\/12\/171214-gestion-de-tesoreria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auren_spain\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\\\/\",\"name\":\"Reflexiones sobre los aspectos estrat\u00e9gicos y operativos de la Gesti\u00f3n de Tesorer\u00eda. - Auren Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/171214-gestion-de-tesoreria.jpg\",\"datePublished\":\"2017-12-18T09:07:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/171214-gestion-de-tesoreria.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/171214-gestion-de-tesoreria.jpg\",\"width\":1920,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reflexiones sobre los aspectos estrat\u00e9gicos y operativos de la Gesti\u00f3n de Tesorer\u00eda.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"name\":\"Auren\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\"},\"alternateName\":\"Auren\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\",\"name\":\"Auren\",\"alternateName\":\"Auren\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/auren_spain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aurenspainserviciosprofesionales\",\"https:\\\/\\\/www.youtube.com\\\/@AurenEsp\",\"https:\\\/\\\/www.instagram.com\\\/auren_spain\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reflexiones sobre los aspectos estrat\u00e9gicos y operativos de la Gesti\u00f3n de Tesorer\u00eda. - Auren Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/","og_locale":"es_ES","og_type":"article","og_title":"Reflexiones sobre los aspectos estrat\u00e9gicos y operativos de la Gesti\u00f3n de Tesorer\u00eda. - Auren Espa\u00f1a","og_description":"Es muy com\u00fan en el \u00e1mbito empresarial estar expuesto al concepto de gesti\u00f3n de tesorer\u00eda. Este vocablo de uso habitual se instala en la percepci\u00f3n del oyente como la actividad de coordinar cobros y pagos, d\u00e1ndole as\u00ed una visi\u00f3n muy operativa y encuadr\u00e1ndola, por otro lado, en una funci\u00f3n tradicional de la actividad del tesorero.","og_url":"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/","og_site_name":"Auren","og_image":[{"width":1920,"height":655,"url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2017\/12\/171214-gestion-de-tesoreria.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auren_spain","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/","url":"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/","name":"Reflexiones sobre los aspectos estrat\u00e9gicos y operativos de la Gesti\u00f3n de Tesorer\u00eda. - Auren Espa\u00f1a","isPartOf":{"@id":"https:\/\/auren.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2017\/12\/171214-gestion-de-tesoreria.jpg","datePublished":"2017-12-18T09:07:59+00:00","breadcrumb":{"@id":"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/#primaryimage","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2017\/12\/171214-gestion-de-tesoreria.jpg","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2017\/12\/171214-gestion-de-tesoreria.jpg","width":1920,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/es\/blog\/reflexiones-sobre-los-aspectos-estrategicos-y-operativos-de-la-gestion-de-tesoreria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/es\/"},{"@type":"ListItem","position":2,"name":"Reflexiones sobre los aspectos estrat\u00e9gicos y operativos de la Gesti\u00f3n de Tesorer\u00eda."}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/es\/#website","url":"https:\/\/auren.com\/es\/","name":"Auren","description":"","publisher":{"@id":"https:\/\/auren.com\/es\/#organization"},"alternateName":"Auren","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/es\/#organization","name":"Auren","alternateName":"Auren","url":"https:\/\/auren.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren"},"image":{"@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/auren_spain","https:\/\/www.linkedin.com\/company\/aurenspainserviciosprofesionales","https:\/\/www.youtube.com\/@AurenEsp","https:\/\/www.instagram.com\/auren_spain"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog\/7617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog\/7617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media\/7618"}],"wp:attachment":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media?parent=7617"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog-category?post=7617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}