{"id":7974,"date":"2016-06-01T14:49:07","date_gmt":"2016-06-01T12:49:07","guid":{"rendered":"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/"},"modified":"2016-06-01T14:49:07","modified_gmt":"2016-06-01T12:49:07","slug":"la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion","status":"publish","type":"blog","link":"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/","title":{"rendered":"La reducci\u00f3n fiscal en el Impuesto sobre Sociedades por el concepto de reserva de capitalizaci\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\">En esta ocasi\u00f3n vamos a abordar el comentario de una de las medidas implementadas en la reforma fiscal de 2014, concretamente, en el \u00e1mbito del Impuesto sobre Sociedades: <u>la denominada reducci\u00f3n de base imponible por reserva de capitalizaci\u00f3n<\/u>. Observamos que este beneficio fiscal es uno de los que tiene mayor incidencia a la hora de la determinaci\u00f3n de la cuota de este Impuesto. <\/p>\n<p style=\"text-align: justify;\">Seg\u00fan se dispone en la Exposici\u00f3n de Motivos de la nueva Ley del Impuesto sobre Sociedades (Ley 27\/2014), la implementaci\u00f3n de este beneficio fiscal consistente en una reducci\u00f3n de la base imponible de este Impuesto tiene como objetivo: <\/p>\n<ol>\n<li>Minorar el efecto negativo que pueda suponer la supresi\u00f3n de las deducciones por reinversi\u00f3n de beneficios extraordinarios y por inversi\u00f3n de beneficios reguladas en el anterior Texto Refundido de la Ley del Impuesto sobre Sociedades (RD Legislativo 4\/2004).<\/li>\n<li>Potenciar la financiaci\u00f3n propia de las empresas mediante el incremento del patrimonio neto, y con ello incentivar el saneamiento de las empresas y su competitividad. <\/li>\n<\/ol>\n<p style=\"text-align: justify;\">La introducci\u00f3n de este beneficio fiscal en la normativa reguladora del Impuesto sobre Sociedades, junto con las limitaciones existentes en la deducibilidad de los gastos financieros, pone de relieve que en se ha optado por dar un mejor tratamiento a la financiaci\u00f3n propia frente a la ajena.<\/p>\n<p><i>\u00bfCu\u00e1ndo y qui\u00e9n puede aplicar la reserva de capitalizaci\u00f3n? <\/i><\/p>\n<p style=\"text-align: justify;\">La reserva de capitalizaci\u00f3n es de aplicaci\u00f3n en per\u00edodos impositivos iniciados a partir del 1 de Enero de 2015, y para sujetos pasivos que tributen al tipo de gravamen previsto los apartados 1 \u00f3 6 del art\u00edculo 29 de la LIS, es decir, podr\u00e1n acogerse aquellos sujetos pasivos que tributen al tipo de gravamen general y al tipo de gravamen del 30% (33% para periodos impositivos iniciados en 2015).<\/p>\n<p><i>\u00bfExisten requisitos adicionales para poder aplicar esta reducci\u00f3n en base imponible? <\/i><\/p>\n<p style=\"text-align: justify;\">S\u00ed, esta reducci\u00f3n s\u00f3lo puede aplicarse en aquellos casos en los que se cumplen los siguientes extremos:<\/p>\n<ol>\n<li>Que el importe del incremento de los fondos propios de la entidad se mantenga durante un plazo de 5 a\u00f1os desde el cierre del periodo impositivo al que corresponda esta reducci\u00f3n, salvo en los casos que existan p\u00e9rdidas contables.<\/li>\n<li>Que se dote una reserva por el importe de la reducci\u00f3n, que deber\u00e1 figurar en el balance con absoluta separaci\u00f3n y t\u00edtulo apropiado y ser\u00e1 indisponible durante el plazo de 5 a\u00f1os previsto en la letra anterior. A estos efectos, no se entender\u00e1 que se ha dispuesto de la referida reserva cuando: <\/li>\n<\/ol>\n<ul>\n<li>El socio ejerza su derecho a separarse de la entidad.<\/li>\n<li>La reserva se elimine, total o parcialmente, como consecuencia de operaciones a las que resulte de aplicaci\u00f3n el r\u00e9gimen fiscal especial de fusiones y escisiones.<\/li>\n<li>La entidad deba aplicar la referida reserva en virtud de una obligaci\u00f3n de car\u00e1cter legal.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">El incumplimiento de los requisitos establecidos anteriormente dar\u00e1 lugar a la regularizaci\u00f3n de las cantidades indebidamente reducidas, as\u00ed como de los correspondientes intereses de demora, en los t\u00e9rminos establecidos en el art\u00edculo 125.3 de la LIS.<\/p>\n<p><i>\u00bfC\u00f3mo se determina el importe de la reducci\u00f3n de base imponible del IS por reserva de capitalizaci\u00f3n?<\/i><\/p>\n<p style=\"text-align: justify;\">Debemos determinar en primer lugar lo que se denomina el incremento de los fondos propios de la entidad al cierre del ejercicio, y lo anterior, en t\u00e9rminos generales efectuando la comparaci\u00f3n entre los existentes a 01\/01 y 31\/12 de cada per\u00edodo impositivo, en ning\u00fan caso se incluir\u00e1 el resultado del propio ejercicio, ni del ejercicio anterior. Lo anterior se observa claramente en la siguiente f\u00f3rmula: <\/p>\n<p><b>\u0394 FP = (FP cierre N \u2013 Resultado N) \u2013 (FP inicio N \u2013 Resultado N-1)<\/b><\/p>\n<p>Adem\u00e1s, hay que corregir los fondos propios en los siguientes conceptos: <\/p>\n<ul>\n<li>Las aportaciones de los socios.<\/li>\n<li>Las ampliaciones de capital o fondos propios por compensaci\u00f3n de cr\u00e9ditos.<\/li>\n<li>Las ampliaciones de fondos propios por operaciones con acciones propias o de reestructuraci\u00f3n.<\/li>\n<li>Las reservas de car\u00e1cter legal o estatutario.<\/li>\n<li>Las reservas indisponibles que se doten por aplicaci\u00f3n de lo dispuesto en el art\u00edculo 105 de la LIS, correspondiente a la reserva de nivelaci\u00f3n, y en el art\u00edculo 27 de la Ley 19\/1994, de modificaci\u00f3n del R\u00e9gimen Econ\u00f3mico y Fiscal de Canarias, correspondiente a la reserva para inversiones en Canarias.<\/li>\n<li>Los fondos propios que correspondan a una emisi\u00f3n de instrumentos financieros compuestos.<\/li>\n<li>Los fondos propios que se correspondan con variaciones en activos por impuesto diferido derivadas de una disminuci\u00f3n o aumento del tipo de gravamen del Impuesto sobre Sociedades.<\/li>\n<\/ul>\n<p><i>\u00bfExiste alguna limitaci\u00f3n a la hora de aplicar este beneficio fiscal?<\/i><\/p>\n<p>Efectivamente, en la normativa reguladora se establece un doble l\u00edmite, por una parte, la cuant\u00eda de la reducci\u00f3n de la base imponible del Impuesto sobre Sociedades <u>no podr\u00e1 superar el 10% del incremento de los fondos propios<\/u> determinado seg\u00fan lo dispuesto en el apartado anterior, y por otra, <u>tampoco podr\u00e1 superar el importe del 10% de la base imponible del IS positiva previa a: a) la propia reducci\u00f3n por reserva de capitalizaci\u00f3n; b) la integraci\u00f3n a que se refiere el apartado 12 del art\u00edculo 11 de la LIS; y, c) la compensaci\u00f3n de bases imponibles negativas<\/u>.<\/p>\n<p style=\"text-align: justify;\">En caso de que no se pueda aplicar la totalidad del importe de la reducci\u00f3n por insuficiencia de base imponible, las cantidades pendientes podr\u00e1n ser objeto de aplicaci\u00f3n en los per\u00edodos impositivos que finalicen en los 2 a\u00f1os inmediatos y sucesivos al cierre del per\u00edodo impositivo en que se haya generado el derecho a la reducci\u00f3n, conjuntamente con la reducci\u00f3n que pudiera corresponder, en su caso, por aplicaci\u00f3n de lo dispuesto en este art\u00edculo en el per\u00edodo impositivo correspondiente, y con el l\u00edmite previsto en el p\u00e1rrafo anterior.<\/p>\n<p style=\"text-align: justify;\">Por \u00faltimo existe una cuesti\u00f3n que ha planteado dudas en su interpretaci\u00f3n y que fue resuelta en fecha 22\/12\/2015 por la Direcci\u00f3n General de Tributos en su Resoluci\u00f3n a Consulta Vinculante (V4127-15), y la duda a resolver consist\u00eda en determinar <i>la fecha en la que deb\u00eda dotarse y contabilizarse la reserva de capitalizaci\u00f3n<\/i>. En este sentido se ha resuelto que <i>\u201cteniendo en cuenta que s\u00f3lo a la finalizaci\u00f3n del periodo impositivo es posible conocer el incremento de fondos propios y habi\u00e9ndose generado un incremento en las reservas de la entidad, el cumplimiento formal relativo a registrar en balance una reserva indisponible con separaci\u00f3n y t\u00edtulo apropiado se entender\u00e1 cumplido siempre que la dotaci\u00f3n formal de la reserva de capitalizaci\u00f3n se produzca en el plazo legalmente previsto en la normativa mercantil para la aprobaci\u00f3n de las cuentas anuales del ejercicio correspondiente al periodo impositivo en que se aplique la reducci\u00f3n\u00bb.<\/i><\/p>\n<p style=\"text-align: justify;\">El traslado de lo anterior al primero de los ejercicios en que va a ser de aplicaci\u00f3n este beneficio fiscal (2015) determina, como explica la DGT, que se disponga del plazo establecido para la presentaci\u00f3n de las Cuentas Anuales del ejercicio 2015, para dotar\/reclasificar la reserva de capitalizaci\u00f3n de forma que figure en el balance separadamente (aunque dicho cumplimiento se registre contablemente en el balance de cuentas anuales del ejercicio 2016 y no en el de 2015).<\/p>\n<p style=\"text-align: justify;\">La Direcci\u00f3n General de los Registros y del Notariado en su Resoluci\u00f3n de 26\/02\/2016 (BOE de 09\/03\/2016) ha aprobado unos nuevos modelos de cuentas anuales en los que se identifica de manera separada un apartado de reserva de capitalizaci\u00f3n dentro de las reservas del balance de situaci\u00f3n (modelo Pymes, Abreviado y Normal).<\/p>\n<p style=\"text-align: justify;\">En conclusi\u00f3n,<b> <\/b>nos encontramos ante un beneficio fiscal que puede aplicarse en un gran n\u00famero de casos (nuestra experiencia en Pyme y Micropyme nos confirma que muchas de estas entidades no distribuyen los recursos que obtienen en sus actividades) y que puede llegar a representar un ahorro importante en la cuota a satisfacer por el Impuesto sobre Sociedades.<\/p>\n<p>Jos\u00e9 Manuel Cambra Gras, Socio director de Auren Asesores; Ricard P\u00e9rez Mi\u00f1ana, Socio de Auren Asesores; Soledad Ortol\u00e1 Domenech, Gerente de Auren Asesores<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta ocasi\u00f3n vamos a abordar el comentario de una de las medidas implementadas en la reforma fiscal de 2014, concretamente, en el \u00e1mbito del Impuesto sobre Sociedades: la denominada reducci\u00f3n de base imponible por reserva de capitalizaci\u00f3n. Observamos que este beneficio fiscal es uno de los que tiene mayor incidencia a la hora de la determinaci\u00f3n de la cuota de este Impuesto.<\/p>\n","protected":false},"featured_media":7975,"template":"","meta":{"_acf_changed":false,"footnotes":""},"blog-category":[],"class_list":["post-7974","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La reducci\u00f3n fiscal en el Impuesto sobre Sociedades por el concepto de reserva de capitalizaci\u00f3n - Auren Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La reducci\u00f3n fiscal en el Impuesto sobre Sociedades por el concepto de reserva de capitalizaci\u00f3n - Auren Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"En esta ocasi\u00f3n vamos a abordar el comentario de una de las medidas implementadas en la reforma fiscal de 2014, concretamente, en el \u00e1mbito del Impuesto sobre Sociedades: la denominada reducci\u00f3n de base imponible por reserva de capitalizaci\u00f3n. Observamos que este beneficio fiscal es uno de los que tiene mayor incidencia a la hora de la determinaci\u00f3n de la cuota de este Impuesto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/es\/wp-content\/uploads\/2016\/06\/la-reduccion-fiscal-jose-manuel-cambra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auren_spain\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\\\/\",\"name\":\"La reducci\u00f3n fiscal en el Impuesto sobre Sociedades por el concepto de reserva de capitalizaci\u00f3n - Auren Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/la-reduccion-fiscal-jose-manuel-cambra.jpg\",\"datePublished\":\"2016-06-01T12:49:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/la-reduccion-fiscal-jose-manuel-cambra.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/la-reduccion-fiscal-jose-manuel-cambra.jpg\",\"width\":1920,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/blog\\\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La reducci\u00f3n fiscal en el Impuesto sobre Sociedades por el concepto de reserva de capitalizaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"name\":\"Auren\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\"},\"alternateName\":\"Auren\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\",\"name\":\"Auren\",\"alternateName\":\"Auren\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/auren_spain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aurenspainserviciosprofesionales\",\"https:\\\/\\\/www.youtube.com\\\/@AurenEsp\",\"https:\\\/\\\/www.instagram.com\\\/auren_spain\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La reducci\u00f3n fiscal en el Impuesto sobre Sociedades por el concepto de reserva de capitalizaci\u00f3n - Auren Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/","og_locale":"es_ES","og_type":"article","og_title":"La reducci\u00f3n fiscal en el Impuesto sobre Sociedades por el concepto de reserva de capitalizaci\u00f3n - Auren Espa\u00f1a","og_description":"En esta ocasi\u00f3n vamos a abordar el comentario de una de las medidas implementadas en la reforma fiscal de 2014, concretamente, en el \u00e1mbito del Impuesto sobre Sociedades: la denominada reducci\u00f3n de base imponible por reserva de capitalizaci\u00f3n. Observamos que este beneficio fiscal es uno de los que tiene mayor incidencia a la hora de la determinaci\u00f3n de la cuota de este Impuesto.","og_url":"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/","og_site_name":"Auren","og_image":[{"width":1920,"height":655,"url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2016\/06\/la-reduccion-fiscal-jose-manuel-cambra.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auren_spain","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/","url":"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/","name":"La reducci\u00f3n fiscal en el Impuesto sobre Sociedades por el concepto de reserva de capitalizaci\u00f3n - Auren Espa\u00f1a","isPartOf":{"@id":"https:\/\/auren.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2016\/06\/la-reduccion-fiscal-jose-manuel-cambra.jpg","datePublished":"2016-06-01T12:49:07+00:00","breadcrumb":{"@id":"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/#primaryimage","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2016\/06\/la-reduccion-fiscal-jose-manuel-cambra.jpg","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2016\/06\/la-reduccion-fiscal-jose-manuel-cambra.jpg","width":1920,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/es\/blog\/la-reduccion-fiscal-en-el-impuesto-sobre-sociedades-por-el-concepto-de-reserva-de-capitalizacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/es\/"},{"@type":"ListItem","position":2,"name":"La reducci\u00f3n fiscal en el Impuesto sobre Sociedades por el concepto de reserva de capitalizaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/es\/#website","url":"https:\/\/auren.com\/es\/","name":"Auren","description":"","publisher":{"@id":"https:\/\/auren.com\/es\/#organization"},"alternateName":"Auren","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/es\/#organization","name":"Auren","alternateName":"Auren","url":"https:\/\/auren.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren"},"image":{"@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/auren_spain","https:\/\/www.linkedin.com\/company\/aurenspainserviciosprofesionales","https:\/\/www.youtube.com\/@AurenEsp","https:\/\/www.instagram.com\/auren_spain"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog\/7974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog\/7974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media\/7975"}],"wp:attachment":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media?parent=7974"}],"wp:term":[{"taxonomy":"blog-category","embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/blog-category?post=7974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}