{"id":4999,"date":"2020-04-13T13:29:53","date_gmt":"2020-04-13T11:29:53","guid":{"rendered":"https:\/\/auren.com\/es\/new\/apps-salud-y-datos-personales-lawyerpress\/"},"modified":"2020-04-13T13:29:53","modified_gmt":"2020-04-13T11:29:53","slug":"apps-salud-y-datos-personales-lawyerpress","status":"publish","type":"new","link":"https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/","title":{"rendered":"\u00abAPPS, salud y datos personales\u00bb &#8211; Lawyerpress"},"content":{"rendered":"<p>Art\u00edculo de Alberto Malo,  abogado del departamento de Media &amp; Technology de Auren en LawyerPress.<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo de Alberto Malo, abogado del departamento de Media &amp; Technology de Auren en LawyerPress.<\/p>\n","protected":false},"featured_media":5000,"template":"","meta":{"_acf_changed":false,"footnotes":""},"new-category":[],"class_list":["post-4999","new","type-new","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;APPS, salud y datos personales&quot; - Lawyerpress - Auren Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Art\u00edculo de Alberto Malo, abogado del departamento de Media &amp; Technology de Auren en LawyerPress.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;APPS, salud y datos personales&quot; - Lawyerpress - Auren Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Art\u00edculo de Alberto Malo, abogado del departamento de Media &amp; Technology de Auren en LawyerPress.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/es\/wp-content\/uploads\/2020\/04\/Linkedin-alertas-boceto-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1089\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auren_spain\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/noticias\\\/apps-salud-y-datos-personales-lawyerpress\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/noticias\\\/apps-salud-y-datos-personales-lawyerpress\\\/\",\"name\":\"\\\"APPS, salud y datos personales\\\" - Lawyerpress - Auren Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/noticias\\\/apps-salud-y-datos-personales-lawyerpress\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/noticias\\\/apps-salud-y-datos-personales-lawyerpress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Linkedin-alertas-boceto-2.jpg\",\"datePublished\":\"2020-04-13T11:29:53+00:00\",\"description\":\"Art\u00edculo de Alberto Malo, abogado del departamento de Media & Technology de Auren en LawyerPress.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/noticias\\\/apps-salud-y-datos-personales-lawyerpress\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/es\\\/noticias\\\/apps-salud-y-datos-personales-lawyerpress\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/noticias\\\/apps-salud-y-datos-personales-lawyerpress\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Linkedin-alertas-boceto-2.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Linkedin-alertas-boceto-2.jpg\",\"width\":1089,\"height\":542},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/noticias\\\/apps-salud-y-datos-personales-lawyerpress\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abAPPS, salud y datos personales\u00bb &#8211; Lawyerpress\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"name\":\"Auren\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\"},\"alternateName\":\"Auren\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\",\"name\":\"Auren\",\"alternateName\":\"Auren\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/auren_spain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aurenspainserviciosprofesionales\",\"https:\\\/\\\/www.youtube.com\\\/@AurenEsp\",\"https:\\\/\\\/www.instagram.com\\\/auren_spain\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"APPS, salud y datos personales\" - Lawyerpress - Auren Espa\u00f1a","description":"Art\u00edculo de Alberto Malo, abogado del departamento de Media & Technology de Auren en LawyerPress.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/","og_locale":"es_ES","og_type":"article","og_title":"\"APPS, salud y datos personales\" - Lawyerpress - Auren Espa\u00f1a","og_description":"Art\u00edculo de Alberto Malo, abogado del departamento de Media & Technology de Auren en LawyerPress.","og_url":"https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/","og_site_name":"Auren","og_image":[{"width":1089,"height":542,"url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2020\/04\/Linkedin-alertas-boceto-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auren_spain","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/","url":"https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/","name":"\"APPS, salud y datos personales\" - Lawyerpress - Auren Espa\u00f1a","isPartOf":{"@id":"https:\/\/auren.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2020\/04\/Linkedin-alertas-boceto-2.jpg","datePublished":"2020-04-13T11:29:53+00:00","description":"Art\u00edculo de Alberto Malo, abogado del departamento de Media & Technology de Auren en LawyerPress.","breadcrumb":{"@id":"https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/#primaryimage","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2020\/04\/Linkedin-alertas-boceto-2.jpg","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2020\/04\/Linkedin-alertas-boceto-2.jpg","width":1089,"height":542},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/es\/noticias\/apps-salud-y-datos-personales-lawyerpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00abAPPS, salud y datos personales\u00bb &#8211; Lawyerpress"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/es\/#website","url":"https:\/\/auren.com\/es\/","name":"Auren","description":"","publisher":{"@id":"https:\/\/auren.com\/es\/#organization"},"alternateName":"Auren","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/es\/#organization","name":"Auren","alternateName":"Auren","url":"https:\/\/auren.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren"},"image":{"@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/auren_spain","https:\/\/www.linkedin.com\/company\/aurenspainserviciosprofesionales","https:\/\/www.youtube.com\/@AurenEsp","https:\/\/www.instagram.com\/auren_spain"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/new\/4999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/new\/4999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media\/5000"}],"wp:attachment":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media?parent=4999"}],"wp:term":[{"taxonomy":"new-category","embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/new-category?post=4999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}