{"id":21771,"date":"2025-04-09T11:06:26","date_gmt":"2025-04-09T09:06:26","guid":{"rendered":"https:\/\/auren.com\/es\/?post_type=press-release&#038;p=21771"},"modified":"2025-04-09T11:06:31","modified_gmt":"2025-04-09T09:06:31","slug":"auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico","status":"publish","type":"press-release","link":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/","title":{"rendered":"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>Abogado del Estado en excedencia, ha ejercido ante el Tribunal Superior de Justicia de Madrid, la Audiencia Nacional y el Tribunal Supremo.<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Su especializaci\u00f3n incluye energ\u00eda, urbanismo, expropiaciones e infraestructuras, con una destacada trayectoria en proyectos clave del \u00e1mbito p\u00fablico y privado.<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Para Mario Alonso, presidente de Auren, esta incorporaci\u00f3n \u201cfortalece a\u00fan m\u00e1s nuestra capacidad de ofrecer asesoramiento especializado en Derecho P\u00fablico, especialmente en sectores clave como la energ\u00eda y el urbanismo\u201d.<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Madrid, 9 de abril de 2025. &#8211;<\/strong> Auren, firma espa\u00f1ola l\u00edder en prestaci\u00f3n de servicios profesionales a nivel global de auditor\u00eda, asesoramiento legal, consultor\u00eda y\u00a0<em>corporate<\/em>, ha incorporado a <strong>Francisco Garc\u00eda G\u00f3mez de Mercado<\/strong> como nuevo socio de<strong> <a href=\"\/?p=3769\">Auren Legal<\/a><\/strong>, con el objetivo de reforzar el \u00e1rea de Derecho P\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Francisco es licenciado en Derecho y diplomado en Derecho Civil Catal\u00e1n por la Universidad de Barcelona. Adem\u00e1s, es doctor en Derecho por la Universidad Complutense de Madrid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lo largo de su trayectoria, ha ocupado cargos de gran relevancia en el \u00e1mbito jur\u00eddico. <strong>Abogado del Estado<\/strong> en excedencia, ha ejercido ante el Tribunal Superior de Justicia de Madrid, la Audiencia Nacional y el Tribunal Supremo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con <strong>m\u00e1s de 25 a\u00f1os de experiencia<\/strong>, antes de su incorporaci\u00f3n a Auren fue socio director de G\u00f3mez de Mercado Abogados (2008-2025). Previamente, ocup\u00f3 el cargo de director general de los Servicios Jur\u00eddicos de la Comunidad de Madrid y fue director del \u00c1rea Jur\u00eddica de la Junta de Compensaci\u00f3n del Parque de Valdebebas, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n ocupa distintos cargos de responsabilidad en el \u00e1mbito institucional destacando su actual papel como <strong>presidente de la Secci\u00f3n de Energ\u00eda<\/strong> del Ilustre Colegio de la Abogac\u00eda de Madrid desde 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su <strong>especializaci\u00f3n<\/strong> abarca sectores estrat\u00e9gicos como el de la energ\u00eda e infraestructuras, siendo adem\u00e1s experto en expropiaci\u00f3n y urbanismo. A lo largo de su carrera, ha sido autor de numerosas publicaciones en estas materias y ha desempe\u00f1ado un papel clave en diversos proyectos de gran envergadura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de Auren, <strong>Mario Alonso<\/strong>, ha destacado que la incorporaci\u00f3n de Francisco Garc\u00eda G\u00f3mez de Mercado \u201cfortalece a\u00fan m\u00e1s nuestra capacidad de ofrecer asesoramiento especializado en Derecho P\u00fablico, especialmente en sectores clave como la energ\u00eda y el urbanismo. Su experiencia y visi\u00f3n estrat\u00e9gica son un gran valor para nuestra firma y nuestros clientes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte,<strong> Francisco Garc\u00eda G\u00f3mez de Mercado <\/strong>ha expresado: \u201cMi incorporaci\u00f3n a Auren marca una nueva etapa llena de retos y oportunidades. Estoy convencido de que, junto con este equipo de profesionales, podremos ofrecer soluciones innovadoras y de gran valor a nuestros clientes en un entorno legal en constante evoluci\u00f3n\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auren ha incorporado a Francisco Garc\u00eda G\u00f3mez de Mercado como nuevo socio de Auren Legal, con el objetivo de reforzar el \u00e1rea de Derecho P\u00fablico.<\/p>\n","protected":false},"featured_media":21772,"template":"","meta":{"_acf_changed":false,"footnotes":""},"press-release-category":[],"class_list":["post-21771","press-release","type-press-release","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico - Auren<\/title>\n<meta name=\"description\" content=\"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico. Francisco es licenciado en Derecho y diplomado en Derecho Civil Catal\u00e1n por la Universidad de Barcelona. Adem\u00e1s, es doctor en Derecho por la Universidad Complutense de Madrid.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico - Auren\" \/>\n<meta property=\"og:description\" content=\"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico. Francisco es licenciado en Derecho y diplomado en Derecho Civil Catal\u00e1n por la Universidad de Barcelona. Adem\u00e1s, es doctor en Derecho por la Universidad Complutense de Madrid.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-09T09:06:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/04\/Mario-Alonso-y-Francisco-Garcia-Gomez-de-Mercado-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auren_spain\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\\\/\",\"name\":\"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico - Auren\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Mario-Alonso-y-Francisco-Garcia-Gomez-de-Mercado-scaled.jpg\",\"datePublished\":\"2025-04-09T09:06:26+00:00\",\"dateModified\":\"2025-04-09T09:06:31+00:00\",\"description\":\"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico. Francisco es licenciado en Derecho y diplomado en Derecho Civil Catal\u00e1n por la Universidad de Barcelona. Adem\u00e1s, es doctor en Derecho por la Universidad Complutense de Madrid.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Mario-Alonso-y-Francisco-Garcia-Gomez-de-Mercado-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Mario-Alonso-y-Francisco-Garcia-Gomez-de-Mercado-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"name\":\"Auren\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\"},\"alternateName\":\"Auren\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\",\"name\":\"Auren\",\"alternateName\":\"Auren\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/auren_spain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aurenspainserviciosprofesionales\",\"https:\\\/\\\/www.youtube.com\\\/@AurenEsp\",\"https:\\\/\\\/www.instagram.com\\\/auren_spain\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico - Auren","description":"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico. Francisco es licenciado en Derecho y diplomado en Derecho Civil Catal\u00e1n por la Universidad de Barcelona. Adem\u00e1s, es doctor en Derecho por la Universidad Complutense de Madrid.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/","og_locale":"es_ES","og_type":"article","og_title":"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico - Auren","og_description":"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico. Francisco es licenciado en Derecho y diplomado en Derecho Civil Catal\u00e1n por la Universidad de Barcelona. Adem\u00e1s, es doctor en Derecho por la Universidad Complutense de Madrid.","og_url":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/","og_site_name":"Auren","article_modified_time":"2025-04-09T09:06:31+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/04\/Mario-Alonso-y-Francisco-Garcia-Gomez-de-Mercado-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auren_spain","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/","url":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/","name":"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico - Auren","isPartOf":{"@id":"https:\/\/auren.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/04\/Mario-Alonso-y-Francisco-Garcia-Gomez-de-Mercado-scaled.jpg","datePublished":"2025-04-09T09:06:26+00:00","dateModified":"2025-04-09T09:06:31+00:00","description":"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico. Francisco es licenciado en Derecho y diplomado en Derecho Civil Catal\u00e1n por la Universidad de Barcelona. Adem\u00e1s, es doctor en Derecho por la Universidad Complutense de Madrid.","breadcrumb":{"@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/#primaryimage","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/04\/Mario-Alonso-y-Francisco-Garcia-Gomez-de-Mercado-scaled.jpg","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/04\/Mario-Alonso-y-Francisco-Garcia-Gomez-de-Mercado-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-incorpora-a-francisco-garcia-gomez-de-mercado-para-reforzar-el-area-de-derecho-publico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/es\/"},{"@type":"ListItem","position":2,"name":"Auren incorpora a Francisco Garc\u00eda G\u00f3mez de Mercado para reforzar el \u00e1rea de Derecho P\u00fablico"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/es\/#website","url":"https:\/\/auren.com\/es\/","name":"Auren","description":"","publisher":{"@id":"https:\/\/auren.com\/es\/#organization"},"alternateName":"Auren","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/es\/#organization","name":"Auren","alternateName":"Auren","url":"https:\/\/auren.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren"},"image":{"@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/auren_spain","https:\/\/www.linkedin.com\/company\/aurenspainserviciosprofesionales","https:\/\/www.youtube.com\/@AurenEsp","https:\/\/www.instagram.com\/auren_spain"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/press-release\/21771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/types\/press-release"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/press-release\/21771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media\/21772"}],"wp:attachment":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media?parent=21771"}],"wp:term":[{"taxonomy":"press-release-category","embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/press-release-category?post=21771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}