{"id":28651,"date":"2025-10-15T12:04:54","date_gmt":"2025-10-15T10:04:54","guid":{"rendered":"https:\/\/auren.com\/es\/?post_type=press-release&#038;p=28651"},"modified":"2025-10-15T12:04:58","modified_gmt":"2025-10-15T10:04:58","slug":"auren-promociona-a-cuatro-nuevos-socios","status":"publish","type":"press-release","link":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/","title":{"rendered":"Auren promociona a cuatro nuevos socios y refuerza su apuesta por el talento interno"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>La firma ha promocionado a cuatro nuevos socios en \u00e1reas clave: Alejandro Serrano en la divisi\u00f3n de Legal (Compliance); Carmen Arenas en Consultor\u00eda (Estrategia y Procesos); Pablo Mart\u00ednez Varela en Legal (Reestructuraciones e Insolvencias) y Silvia S\u00e1nchez en la divisi\u00f3n de Auditor\u00eda.<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Estas promociones reflejan la apuesta de Auren por el desarrollo interno junto a un modelo de crecimiento mixto que combina el impulso del talento propio con la integraci\u00f3n de nuevas firmas y profesionales.<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Para Mario Alonso, presidente de Auren, \u201cLa promoci\u00f3n de estos cuatro nuevos socios representa lo mejor de nuestra filosof\u00eda: crecer desde dentro, apostando por el talento de profesionales que han demostrado compromiso, excelencia y liderazgo\u201d.<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Madrid, 15 de octubre de 2025. &#8211;<\/strong> <a href=\"https:\/\/auren.com\/es\/\">Auren<\/a>, firma l\u00edder en servicios profesionales de auditor\u00eda, asesoramiento legal, consultor\u00eda y <em>corporate<\/em>, ha anunciado la <strong>promoci\u00f3n interna de cuatro profesionales a la categor\u00eda de socios<\/strong>, reforzando as\u00ed el talento y el liderazgo de la firma en \u00e1reas estrat\u00e9gicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de <strong>Alejandro Serrano<\/strong>, que pasa a ser socio de Compliance dentro de la divisi\u00f3n de Legal; <strong>Carmen Arenas<\/strong>, nueva socia de Consultor\u00eda en el \u00e1rea de Estrategia y Procesos; <strong>Pablo Mart\u00ednez Varela<\/strong>, nuevo socio de Reestructuraciones e Insolvencias de Auren Legal y <strong>Silvia S\u00e1nchez<\/strong>, nueva socia de la divisi\u00f3n de Auditor\u00eda en la oficina de Sevilla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con estas promociones, Auren afianza su compromiso con el desarrollo profesional de su equipo y con el reconocimiento al esfuerzo, la experiencia y el liderazgo de los profesionales de la firma. Todo ello en el marco de un <strong>modelo de crecimiento mixto<\/strong>: apostando por impulsar el talento desde dentro y, al mismo tiempo, integrando otras firmas y profesionales que le permiten mantenerse a la vanguardia, ampliar capacidades y dar respuesta a las necesidades de los clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alejandro Serrano, nuevo socio de Compliance (Auren Legal)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Licenciado en Derecho y Administraci\u00f3n y Direcci\u00f3n de Empresas por la Universidad de Zaragoza y M\u00e1ster en Auditor\u00eda por la Universidad de Alcal\u00e1, Alejandro cuenta con m\u00e1s de 15 a\u00f1os de experiencia en el sector. Antes de unirse a Auren en 2021, desarroll\u00f3 su carrera en firmas como PwC, Augustus Capital y Singular Bank. Hasta el momento, ejerc\u00eda como Gerente y Responsable de Cumplimiento Normativo de Entidades Reguladas en Auren, y ahora asume el liderazgo como socio de Compliance, en la divisi\u00f3n de Auren Legal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carmen Arenas, nueva socia de Consultor\u00eda en Estrategia y Procesos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estudi\u00f3 Arquitectura T\u00e9cnica en la Universidad Polit\u00e9cnica de Madrid, cuenta con m\u00e1s de 20 a\u00f1os de experiencia en consultor\u00eda, con una especializaci\u00f3n en financiaci\u00f3n p\u00fablica, fondos europeos y proyectos estrat\u00e9gicos tanto en el sector privado como p\u00fablico. Ha liderado iniciativas y proyectos cofinanciados desde Programas\/Fondos como FSE, FEDER, Horizonte Europa, CDTI, entre otros. Inici\u00f3 su carrera en Auren en noviembre de 2017 y hasta ahora ocupaba el puesto de directora de financiaci\u00f3n p\u00fablica. Su promoci\u00f3n como socia refuerza el \u00e1rea de Consultor\u00eda de Auren, especialmente en el \u00e1mbito de Estrategia y Procesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pablo Mart\u00ednez Varela, nuevo socio de Reestructuraciones e Insolvencias en Auren Legal<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Licenciado en Derecho por la Universidad Complutense de Madrid y colegiado en el Ilustre Colegio de Abogados de Madrid. Pablo tiene un M\u00e1ster en Pr\u00e1ctica Procesal Laboral y Derecho de la Seguridad Social, un M\u00e1ster en Administraci\u00f3n Concursal y Diploma Universitario de alta especializaci\u00f3n en Reestructuraci\u00f3n de empresas en crisis (Experto en Reestructuraciones) por la Universidad Complutense. Actualmente, es codirector del M\u00e1ster de Abogac\u00eda y Procura en la Universidad Europea de Madrid. Forma parte de la Asociaci\u00f3n Profesional de Administradores Concursales (ASPAC) y es miembro de TMA. Tambi\u00e9n desempe\u00f1a funciones como administrador concursal en toda Espa\u00f1a. Su promoci\u00f3n refuerza el \u00e1rea de Reestructuraciones de Auren Legal, aportando experiencia en procesos complejos, tanto concursales como de reestructuraci\u00f3n y ventas de unidades productivas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Silvia S\u00e1nchez, nueva socia de Auditor\u00eda<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Licenciada en Administraci\u00f3n y Direcci\u00f3n de Empresas por la Universidad de Extremadura (UEx), Experta en Normas Internacionales de Auditor\u00eda, inscrita desde el a\u00f1o 2009 en el Registro Oficial de Auditores de Cuentas (ROAC) y posteriormente en el Registro de Expertos Contables (REC). Cuenta con una s\u00f3lida trayectoria en auditor\u00eda financiera desde hace m\u00e1s de 20 a\u00f1os, tanto en el sector privado como en el p\u00fablico. A lo largo de su carrera ha liderado auditor\u00edas en sociedades individuales, grupos empresariales nacionales e internacionales, as\u00ed como procesos de Due Diligence, valoraciones de empresas y auditor\u00edas de cumplimiento y operativas en entidades y empresas del sector p\u00fablico local y auton\u00f3mico. Desde la oficina de Sevilla, reforzar\u00e1 la presencia de Auren en Andaluc\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte,<strong> Mario Alonso, presidente de Auren<\/strong>, ha destacado que: \u201cLa promoci\u00f3n de estos cuatro nuevos socios representa lo mejor de nuestra filosof\u00eda como firma: crecer desde dentro, apostando por el talento de profesionales que han demostrado compromiso, excelencia y liderazgo. Con ellos reforzamos nuestras capacidades estrat\u00e9gicas y seguimos avanzando en nuestro objetivo de aportar soluciones globales e innovadoras a nuestros clientes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Talento, cultura y diversidad como pilares estrat\u00e9gicos en Auren<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Auren el crecimiento sostenible solo es posible si se construye sobre una cultura s\u00f3lida y compartida. La firma sit\u00faa el talento, la cultura humanista y la diversidad en el centro de la transformaci\u00f3n, apostando por un entorno en el que las personas puedan desarrollarse, innovar y aportar lo mejor de s\u00ed mismas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta visi\u00f3n se refleja en iniciativas que promueven la conciliaci\u00f3n y la flexibilidad laboral, programas de mentoring y desarrollo de liderazgo, acciones concretas en bienestar y salud mental, y un compromiso real con la diversidad e inclusi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La firma ha promocionado a cuatro nuevos socios en \u00e1reas clave: Alejandro Serrano en la divisi\u00f3n de Legal (Compliance); Carmen Arenas en Consultor\u00eda (Estrategia y Procesos); Pablo Mart\u00ednez Varela en Legal (Reestructuraciones e Insolvencias) y Silvia S\u00e1nchez en la divisi\u00f3n de Auditor\u00eda.<\/p>\n","protected":false},"featured_media":28652,"template":"","meta":{"_acf_changed":true,"footnotes":""},"press-release-category":[],"class_list":["post-28651","press-release","type-press-release","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auren promociona a cuatro nuevos socios<\/title>\n<meta name=\"description\" content=\"Se trata de cuatro profesionales reforzando as\u00ed el talento y el liderazgo de la firma en \u00e1reas estrat\u00e9gicas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auren promociona a cuatro nuevos socios\" \/>\n<meta property=\"og:description\" content=\"Se trata de cuatro profesionales reforzando as\u00ed el talento y el liderazgo de la firma en \u00e1reas estrat\u00e9gicas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-15T10:04:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/10\/plan-de-sucesion-17.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"784\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auren_spain\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-promociona-a-cuatro-nuevos-socios\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-promociona-a-cuatro-nuevos-socios\\\/\",\"name\":\"Auren promociona a cuatro nuevos socios\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-promociona-a-cuatro-nuevos-socios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-promociona-a-cuatro-nuevos-socios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/plan-de-sucesion-17.png\",\"datePublished\":\"2025-10-15T10:04:54+00:00\",\"dateModified\":\"2025-10-15T10:04:58+00:00\",\"description\":\"Se trata de cuatro profesionales reforzando as\u00ed el talento y el liderazgo de la firma en \u00e1reas estrat\u00e9gicas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-promociona-a-cuatro-nuevos-socios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-promociona-a-cuatro-nuevos-socios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-promociona-a-cuatro-nuevos-socios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/plan-de-sucesion-17.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/plan-de-sucesion-17.png\",\"width\":1500,\"height\":784},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/auren-promociona-a-cuatro-nuevos-socios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auren promociona a cuatro nuevos socios y refuerza su apuesta por el talento interno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"name\":\"Auren\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\"},\"alternateName\":\"Auren\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\",\"name\":\"Auren\",\"alternateName\":\"Auren\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/auren_spain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aurenspainserviciosprofesionales\",\"https:\\\/\\\/www.youtube.com\\\/@AurenEsp\",\"https:\\\/\\\/www.instagram.com\\\/auren_spain\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auren promociona a cuatro nuevos socios","description":"Se trata de cuatro profesionales reforzando as\u00ed el talento y el liderazgo de la firma en \u00e1reas estrat\u00e9gicas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/","og_locale":"es_ES","og_type":"article","og_title":"Auren promociona a cuatro nuevos socios","og_description":"Se trata de cuatro profesionales reforzando as\u00ed el talento y el liderazgo de la firma en \u00e1reas estrat\u00e9gicas.","og_url":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/","og_site_name":"Auren","article_modified_time":"2025-10-15T10:04:58+00:00","og_image":[{"width":1500,"height":784,"url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/10\/plan-de-sucesion-17.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@auren_spain","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/","url":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/","name":"Auren promociona a cuatro nuevos socios","isPartOf":{"@id":"https:\/\/auren.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/10\/plan-de-sucesion-17.png","datePublished":"2025-10-15T10:04:54+00:00","dateModified":"2025-10-15T10:04:58+00:00","description":"Se trata de cuatro profesionales reforzando as\u00ed el talento y el liderazgo de la firma en \u00e1reas estrat\u00e9gicas.","breadcrumb":{"@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/#primaryimage","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/10\/plan-de-sucesion-17.png","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/10\/plan-de-sucesion-17.png","width":1500,"height":784},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/auren-promociona-a-cuatro-nuevos-socios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/es\/"},{"@type":"ListItem","position":2,"name":"Auren promociona a cuatro nuevos socios y refuerza su apuesta por el talento interno"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/es\/#website","url":"https:\/\/auren.com\/es\/","name":"Auren","description":"","publisher":{"@id":"https:\/\/auren.com\/es\/#organization"},"alternateName":"Auren","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/es\/#organization","name":"Auren","alternateName":"Auren","url":"https:\/\/auren.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren"},"image":{"@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/auren_spain","https:\/\/www.linkedin.com\/company\/aurenspainserviciosprofesionales","https:\/\/www.youtube.com\/@AurenEsp","https:\/\/www.instagram.com\/auren_spain"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/press-release\/28651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/types\/press-release"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/press-release\/28651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media\/28652"}],"wp:attachment":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media?parent=28651"}],"wp:term":[{"taxonomy":"press-release-category","embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/press-release-category?post=28651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}