{"id":29246,"date":"2025-11-19T11:19:54","date_gmt":"2025-11-19T10:19:54","guid":{"rendered":"https:\/\/auren.com\/es\/?post_type=press-release&#038;p=29246"},"modified":"2025-11-19T11:20:01","modified_gmt":"2025-11-19T10:20:01","slug":"eduardo-romero-nuevo-consejero-de-auren","status":"publish","type":"press-release","link":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/","title":{"rendered":"Eduardo Romero se incorpora al Consejo de Administraci\u00f3n de Auren"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>Eduardo cuenta con una s\u00f3lida trayectoria de m\u00e1s de 25 a\u00f1os en el \u00e1mbito de la consultor\u00eda, y desde hace m\u00e1s de dos d\u00e9cadas forma parte de Auren, donde en los \u00faltimos 13 a\u00f1os ha desarrollado su carrera como socio en la divisi\u00f3n de Consultor\u00eda de Estrategia y Procesos. <\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Se incorpora al Consejo en sustituci\u00f3n de Javier Cantera, quien ha liderado en los \u00faltimos a\u00f1os la divisi\u00f3n de Consultor\u00eda y ha contribuido decisivamente al crecimiento y consolidaci\u00f3n de Auren. Cantera continuar\u00e1 vinculado a la firma como miembro del Consejo Asesor y participando activamente en distintos proyectos.<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>El Consejo de Administraci\u00f3n de Auren queda actualmente formado por Mario Alonso, Jos\u00e9 Luis Galipienso, Ignacio Ir\u00edgoras y, desde ahora, Eduardo Romero, junto a David Torralba y Matthias Geyssens, en representaci\u00f3n de Waterland. Mario Alonso continuar\u00e1 ejerciendo como presidente de la firma.<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Madrid, 19 de noviembre de 2025. &#8211;<\/strong> <a href=\"https:\/\/auren.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Auren<\/a>, firma espa\u00f1ola l\u00edder en prestaci\u00f3n de servicios profesionales a nivel global de auditor\u00eda, asesoramiento legal, consultor\u00eda y\u00a0<em>corporate<\/em>, ha anunciado la incorporaci\u00f3n de <strong>Eduardo Romero<\/strong>, socio de la divisi\u00f3n de Consultor\u00eda desde 2012, al <strong>Consejo de Administraci\u00f3n<\/strong> de la firma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eduardo cuenta con una s\u00f3lida trayectoria de <strong>m\u00e1s de 25 a\u00f1os en el \u00e1mbito de la consultor\u00eda, y desde hace m\u00e1s de dos d\u00e9cadas forma parte de Auren<\/strong>, donde en los \u00faltimos 13 a\u00f1os ha desarrollado su carrera como socio en la divisi\u00f3n de Estrategia y Procesos. Es licenciado en Biolog\u00eda, especialidad Biotecnolog\u00eda, por la Universidad Complutense de Madrid y posee un M\u00e1ster en Gesti\u00f3n de Calidad Total por la ETSII de la Universidad Polit\u00e9cnica de Madrid. Adem\u00e1s, es auditor l\u00edder ISO 9001 e ISO 14001 reconocido por IRCA. En el \u00e1mbito acad\u00e9mico, ha sido profesor durante ocho a\u00f1os en el M\u00e1ster en Gesti\u00f3n de Calidad y en la C\u00e1tedra Madrid Excelente de la Universidad Rey Juan Carlos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eduardo Romero se incorpora al Consejo en sustituci\u00f3n de <strong>Javier Cantera<\/strong>, quien ha ejercido de presidente de la divisi\u00f3n de Consultor\u00eda, un \u00e1rea clave de la firma que <strong>ha crecido un 66% en los \u00faltimos cinco ejercicios<\/strong>. Su liderazgo humanista, unido a un profundo conocimiento t\u00e9cnico, ha contribuido de forma decisiva a consolidar el posicionamiento de Auren en este \u00e1mbito. Cantera continuar\u00e1 vinculado a la firma como miembro del Consejo Asesor y participando activamente en distintos proyectos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En palabras de <strong>Mario Alonso<\/strong>, presidente de Auren: \u00abQueremos expresar nuestro m\u00e1s profundo agradecimiento a Javier por su dedicaci\u00f3n, liderazgo que, sin duda, seguir\u00e1 transmiti\u00e9ndonos. Su visi\u00f3n, compromiso y su contribuci\u00f3n a consolidar la <strong>cultura humanista<\/strong> de Auren han sido decisivos para el crecimiento de la firma. Al mismo tiempo, damos la bienvenida al Consejo a Eduardo, cuyo conocimiento, experiencia y capacidad de gesti\u00f3n representan un paso adelante en la consolidaci\u00f3n y el futuro de nuestra firma. Su liderazgo, centrado en las personas, refuerza la continuidad y la proyecci\u00f3n de Auren en los pr\u00f3ximos a\u00f1os, aportando un <strong>enfoque humano<\/strong> que resulta especialmente valioso en la actualidad. Este relevo supone, adem\u00e1s, un cambio generacional que garantiza la solidez y el crecimiento de la firma\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, <strong>Eduardo Romero<\/strong> ha declarado: \u00abAsumo este nuevo reto con enorme ilusi\u00f3n y responsabilidad. Formar parte del Consejo de Administraci\u00f3n de Auren es una oportunidad para seguir contribuyendo al crecimiento de la firma y a su vocaci\u00f3n de acompa\u00f1ar a clientes, profesionales y sociedad. Afronto esta etapa con el compromiso de sumar, escuchar y aportar para continuar abriendo nuevos caminos de futuro\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, <strong>Javier Cantera<\/strong> ha querido compartir unas palabras sobre esta nueva etapa: \u00abTras muchos a\u00f1os de recorrido, me siento orgulloso de seguir formando parte de un proyecto apasionante y humano, rodeado de grandes profesionales y mejores personas. Auren es y seguir\u00e1 siendo mi familia, con la que continuar\u00e9 colaborando en distintos proyectos y aportando mi experiencia, confiando plenamente en el talento y la visi\u00f3n de las nuevas generaciones que impulsan su crecimiento\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Consejo de Administraci\u00f3n de Auren queda actualmente formado por <strong>Mario Alonso<\/strong>, <strong>Jos\u00e9 Luis Galipienso<\/strong>, <strong>Ignacio Ir\u00edgoras<\/strong> y, desde ahora, <strong>Eduardo Romero<\/strong>, junto a <strong>David Torralba<\/strong> y <strong>Matthias Geyssens<\/strong>, en representaci\u00f3n de <a href=\"https:\/\/www.waterlandpe.com\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Waterland<\/a>. Mario Alonso continuar\u00e1 ejerciendo como presidente de la firma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eduardo cuenta con una s\u00f3lida trayectoria de m\u00e1s de 25 a\u00f1os en el \u00e1mbito de la consultor\u00eda, y desde hace m\u00e1s de dos d\u00e9cadas forma parte de Auren, donde en los \u00faltimos 13 a\u00f1os ha desarrollado su carrera como socio en la divisi\u00f3n de Consultor\u00eda de Estrategia y Procesos. <\/p>\n","protected":false},"featured_media":29247,"template":"","meta":{"_acf_changed":true,"footnotes":""},"press-release-category":[],"class_list":["post-29246","press-release","type-press-release","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eduardo Romero nuevo Consejero de Auren<\/title>\n<meta name=\"description\" content=\"Cuenta con una trayectoria de m\u00e1s de 25 a\u00f1os en el \u00e1mbito de la consultor\u00eda, y desde hace m\u00e1s de dos d\u00e9cadas forma parte de Auren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eduardo Romero nuevo Consejero de Auren\" \/>\n<meta property=\"og:description\" content=\"Cuenta con una trayectoria de m\u00e1s de 25 a\u00f1os en el \u00e1mbito de la consultor\u00eda, y desde hace m\u00e1s de dos d\u00e9cadas forma parte de Auren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T10:20:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/11\/Eduardo-Romero-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auren_spain\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/eduardo-romero-nuevo-consejero-de-auren\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/eduardo-romero-nuevo-consejero-de-auren\\\/\",\"name\":\"Eduardo Romero nuevo Consejero de Auren\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/eduardo-romero-nuevo-consejero-de-auren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/eduardo-romero-nuevo-consejero-de-auren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Eduardo-Romero-scaled.jpg\",\"datePublished\":\"2025-11-19T10:19:54+00:00\",\"dateModified\":\"2025-11-19T10:20:01+00:00\",\"description\":\"Cuenta con una trayectoria de m\u00e1s de 25 a\u00f1os en el \u00e1mbito de la consultor\u00eda, y desde hace m\u00e1s de dos d\u00e9cadas forma parte de Auren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/eduardo-romero-nuevo-consejero-de-auren\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/eduardo-romero-nuevo-consejero-de-auren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/eduardo-romero-nuevo-consejero-de-auren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Eduardo-Romero-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/Eduardo-Romero-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/conoce-auren\\\/sala-de-prensa\\\/eduardo-romero-nuevo-consejero-de-auren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eduardo Romero se incorpora al Consejo de Administraci\u00f3n de Auren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"name\":\"Auren\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\"},\"alternateName\":\"Auren\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#organization\",\"name\":\"Auren\",\"alternateName\":\"Auren\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/es\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/auren_spain\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aurenspainserviciosprofesionales\",\"https:\\\/\\\/www.youtube.com\\\/@AurenEsp\",\"https:\\\/\\\/www.instagram.com\\\/auren_spain\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eduardo Romero nuevo Consejero de Auren","description":"Cuenta con una trayectoria de m\u00e1s de 25 a\u00f1os en el \u00e1mbito de la consultor\u00eda, y desde hace m\u00e1s de dos d\u00e9cadas forma parte de Auren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/","og_locale":"es_ES","og_type":"article","og_title":"Eduardo Romero nuevo Consejero de Auren","og_description":"Cuenta con una trayectoria de m\u00e1s de 25 a\u00f1os en el \u00e1mbito de la consultor\u00eda, y desde hace m\u00e1s de dos d\u00e9cadas forma parte de Auren.","og_url":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/","og_site_name":"Auren","article_modified_time":"2025-11-19T10:20:01+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/11\/Eduardo-Romero-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auren_spain","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/","url":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/","name":"Eduardo Romero nuevo Consejero de Auren","isPartOf":{"@id":"https:\/\/auren.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/11\/Eduardo-Romero-scaled.jpg","datePublished":"2025-11-19T10:19:54+00:00","dateModified":"2025-11-19T10:20:01+00:00","description":"Cuenta con una trayectoria de m\u00e1s de 25 a\u00f1os en el \u00e1mbito de la consultor\u00eda, y desde hace m\u00e1s de dos d\u00e9cadas forma parte de Auren.","breadcrumb":{"@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/#primaryimage","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/11\/Eduardo-Romero-scaled.jpg","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/11\/Eduardo-Romero-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/es\/conoce-auren\/sala-de-prensa\/eduardo-romero-nuevo-consejero-de-auren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eduardo Romero se incorpora al Consejo de Administraci\u00f3n de Auren"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/es\/#website","url":"https:\/\/auren.com\/es\/","name":"Auren","description":"","publisher":{"@id":"https:\/\/auren.com\/es\/#organization"},"alternateName":"Auren","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/es\/#organization","name":"Auren","alternateName":"Auren","url":"https:\/\/auren.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/es\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren"},"image":{"@id":"https:\/\/auren.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/auren_spain","https:\/\/www.linkedin.com\/company\/aurenspainserviciosprofesionales","https:\/\/www.youtube.com\/@AurenEsp","https:\/\/www.instagram.com\/auren_spain"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/press-release\/29246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/types\/press-release"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/press-release\/29246\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media\/29247"}],"wp:attachment":[{"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/media?parent=29246"}],"wp:term":[{"taxonomy":"press-release-category","embeddable":true,"href":"https:\/\/auren.com\/es\/wp-json\/wp\/v2\/press-release-category?post=29246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}