{"id":10358,"date":"2023-01-05T10:08:12","date_gmt":"2023-01-05T09:08:12","guid":{"rendered":"https:\/\/auren.com\/uy\/new\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/"},"modified":"2023-01-05T10:08:12","modified_gmt":"2023-01-05T09:08:12","slug":"452-resolucion-92-022-teletrabajo-en-las-zonas-francas","status":"publish","type":"new","link":"https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/","title":{"rendered":"452 &#8211; RESOLUCI\u00d3N 92\/022 \u2013 TELETRABAJO EN LAS ZONAS FRANCAS\ufffc"},"content":{"rendered":"<p class=\"has-text-align-justify\">Con fecha 29 de noviembre de 2022, se prorroga la entrada en vigencia del r\u00e9gimen de teletrabajo en la Zonas Francas, mediante la Resoluci\u00f3n 92\/022, el cual se aplicar\u00e1 a partir del 5 de enero de 2023.<\/p>\n<p class=\"has-text-align-left has-black-color has-text-color\"><strong>Antecedentes<\/strong><\/p>\n<p class=\"has-text-align-justify\">Mediante la Ley N\u00b0 19.996 de fecha 3 de noviembre de 2021, se incorpor\u00f3 el Art\u00edculo 14 Ter a la Ley N\u00b0 15.921 del 17 de diciembre de 1987, incluyendo la posibilidad de realizar teletrabajo en el caso de las empresas usuarias de Zona Franca.<\/p>\n<p class=\"has-text-align-justify\">En el mes de setiembre el Poder Ejecutivo promulg\u00f3 el Decreto que reglamenta esta disposici\u00f3n, estableciendo los siguientes requisitos:<\/p>\n<p class=\"has-text-align-justify\">\u2022 Se limita a qu\u00e9 usuarios alcanza: para poder prestar servicios en modalidad teletrabajo <strong>la plantilla de trabajadores de cada uno de los Usuarios<\/strong> de Zona Franca, deber\u00e1<strong> cumplir 1000 horas mensuales<\/strong> en forma <strong>presencial<\/strong>.<\/p>\n<p class=\"has-text-align-justify\">\u2022\u00a0 Se determina a qu\u00e9 trabajadores alcanza: a los <strong>dependientes<\/strong> que cumplan una jornada completa, con una <strong>carga horaria no menor <\/strong>a las <strong>veinticinco horas semanales<\/strong>.<\/p>\n<div class=\"wp-block-group is-layout-flow\">\n<div class=\"wp-block-group__inner-container\">\n<p class=\"has-text-align-left\">\u2022\u00a0Se fijan determinados l\u00edmites:<\/p>\n<p class=\"has-text-align-left\">&#8211; El <strong>90%<\/strong> de los trabajadores <strong>beneficiarios<\/strong>, deber\u00e1n desempe\u00f1ar como<strong> m\u00ednimo un 60%<\/strong> de su <strong>carga horaria mensual en forma presencial.<\/strong> \u00a0El <strong>10% <\/strong>de los trabajadores restantes, quedara <strong>exceptuado <\/strong>del m\u00ednimo se\u00f1alado.<\/p>\n<p class=\"has-text-align-left\">&#8211; La <strong>suma<\/strong> de las <strong>horas presenciales <\/strong>de la totalidad de los dependientes <strong>no<\/strong> podr\u00e1 ser <strong>inferior al 60% <\/strong>del total de las horas en ese mes.<\/p>\n<\/div>\n<\/div>\n<p class=\"has-text-align-justify\">\u2022 <strong>Se establecen las actividades cuyos trabajadores<\/strong> no quedan <strong>comprendidos<\/strong> en la modalidad de teletrabajo:<\/p>\n<p class=\"has-text-align-justify\"><strong>&#8211; <\/strong>producci\u00f3n o fabriles, de distribuci\u00f3n o log\u00edsticas;<\/p>\n<p class=\"has-text-align-left\"><strong>&#8211; <\/strong>actividades sustantivas se\u00f1alados en el art\u00edculo 14 de la Ley N\u00b0 15.921;<\/p>\n<p class=\"has-text-align-left\"><strong>&#8211; <\/strong>actividades excepcionales, auxiliares y complementarias.<\/p>\n<p class=\"has-text-align-justify\"><strong><u>Resoluci\u00f3n Direcci\u00f3n Nacional de Zonas Francas<\/u><\/strong><\/p>\n<p class=\"has-text-align-justify\">En el pasado mes de noviembre, la Direcci\u00f3n Nacional de Zonas Francas emiti\u00f3 la Resoluci\u00f3n 92\/022 que, haciendo uso de las facultades otorgadas por el Decreto 319\/022, prorroga la entrada en vigor de las disposiciones de dicho Decreto para el 5 de enero de 2023. Por lo tanto, a partir de esa fecha, las empresas usuarias de Zona Franca que adopten el r\u00e9gimen de teletrabajo deben comenzar a aplicar tales disposiciones.<\/p>\n<p class=\"has-text-align-justify\">Si no cumplieran con las condiciones establecidas en el Decreto, deben volver a la presencialidad en esa fecha.<\/p>\n<p class=\"has-text-align-justify\"><strong>La Resoluci\u00f3n <\/strong>tambi\u00e9n introduce modificaciones relativas a los reportes que deben enviar al Desarrollador las empresas que adopten el r\u00e9gimen de teletrabajo, indicando que deber\u00e1n detallarse, entre otros, los siguientes datos:<\/p>\n<p class=\"has-text-align-left\"><strong>&#8211; <\/strong>Nombre y apellido del trabajador.<\/p>\n<p class=\"has-text-align-left\"><strong>&#8211; <\/strong>Domicilio donde llevar\u00e1 a cabo el teletrabajo.<\/p>\n<p class=\"has-text-align-left\"><strong>&#8211; <\/strong>Fecha de ingreso.<\/p>\n<p class=\"has-text-align-left\"><strong>&#8211;<\/strong> Fecha de egreso.<\/p>\n<p class=\"has-text-align-left\"><strong>&#8211; <\/strong>Modalidad de teletrabajo (total, parcial o presencial).<\/p>\n<p class=\"has-text-align-left\"><strong>&#8211; <\/strong>Horas trabajadas en el mes.<\/p>\n<p class=\"has-text-align-left\"><strong>&#8211; <\/strong>Total de horas de teletrabajo en el mes.<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con fecha 29 de noviembre de 2022, se prorroga la entrada en vigencia del r\u00e9gimen de teletrabajo en la Zonas Francas, mediante la Resoluci\u00f3n 92\/022, el cual se aplicar\u00e1 a [&hellip;]<\/p>\n","protected":false},"featured_media":10359,"template":"","meta":{"_acf_changed":false,"footnotes":""},"new-category":[],"class_list":["post-10358","new","type-new","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>452 - RESOLUCI\u00d3N 92\/022 \u2013 TELETRABAJO EN LAS ZONAS FRANCAS\ufffc - Auren Uruguay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"452 - RESOLUCI\u00d3N 92\/022 \u2013 TELETRABAJO EN LAS ZONAS FRANCAS\ufffc - Auren Uruguay\" \/>\n<meta property=\"og:description\" content=\"Con fecha 29 de noviembre de 2022, se prorroga la entrada en vigencia del r\u00e9gimen de teletrabajo en la Zonas Francas, mediante la Resoluci\u00f3n 92\/022, el cual se aplicar\u00e1 a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren Uruguay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aurenuruguay\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/uy\/wp-content\/uploads\/2023\/01\/shutterstock_161759321-1024x683-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AurenUruguay\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\\\/\",\"name\":\"452 - RESOLUCI\u00d3N 92\\\/022 \u2013 TELETRABAJO EN LAS ZONAS FRANCAS\ufffc - Auren Uruguay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/shutterstock_161759321-1024x683-1.jpg\",\"datePublished\":\"2023-01-05T09:08:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/shutterstock_161759321-1024x683-1.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/shutterstock_161759321-1024x683-1.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/uy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"452 &#8211; RESOLUCI\u00d3N 92\\\/022 \u2013 TELETRABAJO EN LAS ZONAS FRANCAS\ufffc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/\",\"name\":\"Auren Uruguay\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/uy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#organization\",\"name\":\"Auren Uruguay\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren Uruguay\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aurenuruguay\",\"https:\\\/\\\/x.com\\\/AurenUruguay\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/auren-uruguay\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClkpSYFfsAuqdTaVF5whedQ\",\"https:\\\/\\\/www.instagram.com\\\/aurenuruguay\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"452 - RESOLUCI\u00d3N 92\/022 \u2013 TELETRABAJO EN LAS ZONAS FRANCAS\ufffc - Auren Uruguay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/","og_locale":"es_ES","og_type":"article","og_title":"452 - RESOLUCI\u00d3N 92\/022 \u2013 TELETRABAJO EN LAS ZONAS FRANCAS\ufffc - Auren Uruguay","og_description":"Con fecha 29 de noviembre de 2022, se prorroga la entrada en vigencia del r\u00e9gimen de teletrabajo en la Zonas Francas, mediante la Resoluci\u00f3n 92\/022, el cual se aplicar\u00e1 a [&hellip;]","og_url":"https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/","og_site_name":"Auren Uruguay","article_publisher":"https:\/\/www.facebook.com\/aurenuruguay","og_image":[{"width":1024,"height":683,"url":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2023\/01\/shutterstock_161759321-1024x683-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AurenUruguay","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/","url":"https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/","name":"452 - RESOLUCI\u00d3N 92\/022 \u2013 TELETRABAJO EN LAS ZONAS FRANCAS\ufffc - Auren Uruguay","isPartOf":{"@id":"https:\/\/auren.com\/uy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2023\/01\/shutterstock_161759321-1024x683-1.jpg","datePublished":"2023-01-05T09:08:12+00:00","breadcrumb":{"@id":"https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/#primaryimage","url":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2023\/01\/shutterstock_161759321-1024x683-1.jpg","contentUrl":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2023\/01\/shutterstock_161759321-1024x683-1.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/uy\/noticias\/452-resolucion-92-022-teletrabajo-en-las-zonas-francas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/uy\/"},{"@type":"ListItem","position":2,"name":"452 &#8211; RESOLUCI\u00d3N 92\/022 \u2013 TELETRABAJO EN LAS ZONAS FRANCAS\ufffc"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/uy\/#website","url":"https:\/\/auren.com\/uy\/","name":"Auren Uruguay","description":"","publisher":{"@id":"https:\/\/auren.com\/uy\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/uy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/uy\/#organization","name":"Auren Uruguay","url":"https:\/\/auren.com\/uy\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/uy\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren Uruguay"},"image":{"@id":"https:\/\/auren.com\/uy\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aurenuruguay","https:\/\/x.com\/AurenUruguay","https:\/\/www.linkedin.com\/company\/auren-uruguay","https:\/\/www.youtube.com\/channel\/UClkpSYFfsAuqdTaVF5whedQ","https:\/\/www.instagram.com\/aurenuruguay\/"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new\/10358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new\/10358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/media\/10359"}],"wp:attachment":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/media?parent=10358"}],"wp:term":[{"taxonomy":"new-category","embeddable":true,"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new-category?post=10358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}