{"id":10361,"date":"2022-12-01T21:52:37","date_gmt":"2022-12-01T20:52:37","guid":{"rendered":"https:\/\/auren.com\/uy\/new\/450-comap-cambios-en-proyectos-de-inversion\/"},"modified":"2022-12-01T21:52:37","modified_gmt":"2022-12-01T20:52:37","slug":"450-comap-cambios-en-proyectos-de-inversion","status":"publish","type":"new","link":"https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/","title":{"rendered":"450 &#8211; COMAP: CAMBIOS EN PROYECTOS DE INVERSI\u00d3N"},"content":{"rendered":"<p class=\"has-text-align-left\">El mi\u00e9rcoles 30 de noviembre fueron publicados por COMAP cambios a los criterios b\u00e1sicos de funcionamiento del <strong>Decreto N\u00b0 268 de 2020<\/strong>.<\/p>\n<p class=\"has-text-align-left\">A continuaci\u00f3n comentamos los principales cambios introducidos, que <strong>entrar\u00e1n en vigencia plena a partir del 19 de diciembre pr\u00f3ximo<\/strong>, por lo que hasta el 18\/12 es posible presentarse considerando los criterios anteriores.<\/p>\n<p class=\"has-text-align-left\"><strong>Inversi\u00f3n en veh\u00edculos el\u00e9ctricos<\/strong><\/p>\n<p class=\"has-text-align-left\">Tanto para veh\u00edculos de pasajeros, como para veh\u00edculos utilitarios para ser arrendados, se limita el valor de importaci\u00f3n CIF a USD 27.000. Cabe recordar que hasta ahora el tope era de USD 60.000 CIF Montevideo. <\/p>\n<p class=\"has-text-align-left\"><strong>Inversi\u00f3n en veh\u00edculos utilitarios<\/strong><\/p>\n<p class=\"has-text-align-left\">Se except\u00faa del l\u00edmite de valor precio CIF USD 30.000 a los furgones que cumplan con la definici\u00f3n a criterio de COMAP (veh\u00edculos de 4 ruedas o m\u00e1s, destinados al transporte de mercanc\u00edas, con caja cerrada, sin vidrios laterales, que no excedan las 12 toneladas de peso total bruto).<\/p>\n<p class=\"has-text-align-left\"><strong>Indicador de descentralizaci\u00f3n<\/strong><\/p>\n<p class=\"has-text-align-left\">Se modifica el criterio para la determinaci\u00f3n del puntaje, en general se reduce el puntaje para la mayor\u00eda de los departamentos.<\/p>\n<p class=\"has-text-align-left\">A los departamentos de frontera (Artigas, Salto, Paysand\u00fa, R\u00edo Negro, Rivera y Cerro Largo), se le adicionan 2 puntos de forma transitoria debido a la coyuntura econ\u00f3mica actual.<\/p>\n<p class=\"has-text-align-left\"><strong>Inversi\u00f3n en energ\u00edas renovables (paneles solares fotovoltaicos)<\/strong><\/p>\n<p class=\"has-text-align-left\">Para grandes consumidores de energ\u00eda (potencia contratada mayor o igual a 250 kW) se except\u00faa la limitaci\u00f3n en porcentaje de inversi\u00f3n y la obligaci\u00f3n de generaci\u00f3n de empleo, (m\u00e1ximo 20% de la inversi\u00f3n total en paneles solares, debi\u00e9ndose generar un m\u00ednimo de 4 puntos de empleo).<\/p>\n<p class=\"has-text-align-left\"><strong>Indicador sectorial \u2013 Mejora de la empleabilidad personal: opci\u00f3n cantidad de empleados capacitados<\/strong><\/p>\n<p class=\"has-text-align-left\">Los gastos se limitan a un curso por empleado y por a\u00f1o. \u00danicamente ser\u00e1 considerado un n\u00famero mayor de cursos por empleado, si estos forman parte de un programa, o plan org\u00e1nico de perfeccionamiento en el tema de que se trate.<\/p>\n<p class=\"has-text-align-left\">No ser\u00e1n considerados cursos que formen parte de una carrera de grado, maestr\u00eda, doctorado o similares.<\/p>\n<p class=\"has-text-align-left\">Se excluye a due\u00f1os, socios y directores.<\/p>\n<p class=\"has-text-align-left\">Se modifica el puntaje, otorg\u00e1ndose 1 punto por la capacitaci\u00f3n de entre 10% y 20% de la plantilla, y 3 puntos para capacitaciones por encima del 20% del personal promedio de la empresa.<\/p>\n<p class=\"has-text-align-left\"><strong>Indicador sectorial \u2013 Pr\u00e1cticas Formativas<\/strong><\/p>\n<p class=\"has-text-align-left\">Se incorpora este indicador, com\u00fan a todos los sectores de actividad.<\/p>\n<p class=\"has-text-align-left\">Se medir\u00e1 en funci\u00f3n de cantidad de empleados en Pr\u00e1cticas Formativas respecto al total de empleados de la empresa.<\/p>\n<p class=\"has-text-align-left\">El cronograma de compromiso es de 3 ejercicios.<\/p>\n<p class=\"has-text-align-left\">Se otorgan entre 3 y 10 puntos en funci\u00f3n del porcentaje de empleados en Pr\u00e1cticas Formativas respecto del total.<\/p>\n<p class=\"has-text-align-left\"><strong>Ampliacione<\/strong>s<\/p>\n<p class=\"has-text-align-left\">Ampliaciones hasta 10% de la inversi\u00f3n promovida elegible: no se exigir\u00e1 la generaci\u00f3n de externalidades adicionales.<\/p>\n<p class=\"has-text-align-left\">Ampliaciones entre 10% y 30% de la inversi\u00f3n promovida elegible: se exigir\u00e1 un incremento en el puntaje total de indicadores de la matriz, el cual resultar\u00e1 de deducir al porcentaje total de la ampliaci\u00f3n, el 10% que no requiere externalidades adicionales.<\/p>\n<p class=\"has-text-align-left\">Se incorporan tambi\u00e9n algunos cambios espec\u00edficos que aplican a determinados sectores de actividad, estamos a las \u00f3rdenes para analizar el impacto de las modificaciones en casos concretos.<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mi\u00e9rcoles 30 de noviembre fueron publicados por COMAP cambios a los criterios b\u00e1sicos de funcionamiento del Decreto N\u00b0 268 de 2020. A continuaci\u00f3n comentamos los principales cambios introducidos, que [&hellip;]<\/p>\n","protected":false},"featured_media":10362,"template":"","meta":{"_acf_changed":false,"footnotes":""},"new-category":[],"class_list":["post-10361","new","type-new","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>450 - COMAP: CAMBIOS EN PROYECTOS DE INVERSI\u00d3N - Auren Uruguay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"450 - COMAP: CAMBIOS EN PROYECTOS DE INVERSI\u00d3N - Auren Uruguay\" \/>\n<meta property=\"og:description\" content=\"El mi\u00e9rcoles 30 de noviembre fueron publicados por COMAP cambios a los criterios b\u00e1sicos de funcionamiento del Decreto N\u00b0 268 de 2020. A continuaci\u00f3n comentamos los principales cambios introducidos, que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren Uruguay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aurenuruguay\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/uy\/wp-content\/uploads\/2022\/12\/CUADRO-SALA-1_0_0-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AurenUruguay\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/450-comap-cambios-en-proyectos-de-inversion\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/450-comap-cambios-en-proyectos-de-inversion\\\/\",\"name\":\"450 - COMAP: CAMBIOS EN PROYECTOS DE INVERSI\u00d3N - Auren Uruguay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/450-comap-cambios-en-proyectos-de-inversion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/450-comap-cambios-en-proyectos-de-inversion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/CUADRO-SALA-1_0_0-2.jpeg\",\"datePublished\":\"2022-12-01T20:52:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/450-comap-cambios-en-proyectos-de-inversion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/450-comap-cambios-en-proyectos-de-inversion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/450-comap-cambios-en-proyectos-de-inversion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/CUADRO-SALA-1_0_0-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/CUADRO-SALA-1_0_0-2.jpeg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/450-comap-cambios-en-proyectos-de-inversion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/uy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"450 &#8211; COMAP: CAMBIOS EN PROYECTOS DE INVERSI\u00d3N\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/\",\"name\":\"Auren Uruguay\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/uy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#organization\",\"name\":\"Auren Uruguay\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren Uruguay\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aurenuruguay\",\"https:\\\/\\\/x.com\\\/AurenUruguay\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/auren-uruguay\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClkpSYFfsAuqdTaVF5whedQ\",\"https:\\\/\\\/www.instagram.com\\\/aurenuruguay\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"450 - COMAP: CAMBIOS EN PROYECTOS DE INVERSI\u00d3N - Auren Uruguay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/","og_locale":"es_ES","og_type":"article","og_title":"450 - COMAP: CAMBIOS EN PROYECTOS DE INVERSI\u00d3N - Auren Uruguay","og_description":"El mi\u00e9rcoles 30 de noviembre fueron publicados por COMAP cambios a los criterios b\u00e1sicos de funcionamiento del Decreto N\u00b0 268 de 2020. A continuaci\u00f3n comentamos los principales cambios introducidos, que [&hellip;]","og_url":"https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/","og_site_name":"Auren Uruguay","article_publisher":"https:\/\/www.facebook.com\/aurenuruguay","og_image":[{"width":700,"height":525,"url":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2022\/12\/CUADRO-SALA-1_0_0-2.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AurenUruguay","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/","url":"https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/","name":"450 - COMAP: CAMBIOS EN PROYECTOS DE INVERSI\u00d3N - Auren Uruguay","isPartOf":{"@id":"https:\/\/auren.com\/uy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2022\/12\/CUADRO-SALA-1_0_0-2.jpeg","datePublished":"2022-12-01T20:52:37+00:00","breadcrumb":{"@id":"https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/#primaryimage","url":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2022\/12\/CUADRO-SALA-1_0_0-2.jpeg","contentUrl":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2022\/12\/CUADRO-SALA-1_0_0-2.jpeg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/uy\/noticias\/450-comap-cambios-en-proyectos-de-inversion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/uy\/"},{"@type":"ListItem","position":2,"name":"450 &#8211; COMAP: CAMBIOS EN PROYECTOS DE INVERSI\u00d3N"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/uy\/#website","url":"https:\/\/auren.com\/uy\/","name":"Auren Uruguay","description":"","publisher":{"@id":"https:\/\/auren.com\/uy\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/uy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/uy\/#organization","name":"Auren Uruguay","url":"https:\/\/auren.com\/uy\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/uy\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren Uruguay"},"image":{"@id":"https:\/\/auren.com\/uy\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aurenuruguay","https:\/\/x.com\/AurenUruguay","https:\/\/www.linkedin.com\/company\/auren-uruguay","https:\/\/www.youtube.com\/channel\/UClkpSYFfsAuqdTaVF5whedQ","https:\/\/www.instagram.com\/aurenuruguay\/"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new\/10361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new\/10361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/media\/10362"}],"wp:attachment":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/media?parent=10361"}],"wp:term":[{"taxonomy":"new-category","embeddable":true,"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new-category?post=10361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}