{"id":10431,"date":"2020-05-27T14:57:13","date_gmt":"2020-05-27T12:57:13","guid":{"rendered":"https:\/\/auren.com\/uy\/new\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/"},"modified":"2020-05-27T14:57:13","modified_gmt":"2020-05-27T12:57:13","slug":"430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20","status":"publish","type":"new","link":"https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/","title":{"rendered":"430- PROMOCI\u00d3N DE PARQUES INDUSTRIALES Y PARQUES CIENT\u00cdFICO TECNOL\u00d3GICOS &#8211; DECRETO N\u00ba 79\/20"},"content":{"rendered":"<p class=\"has-text-align-justify\">El pasado 28 de febrero se promulg\u00f3 el <strong>Decreto N\u00ba 79\/020<\/strong>, con el objetivo de reglamentar la <strong>Ley N\u00ba 19.784 <\/strong>de promoci\u00f3n y desarrollo de Parques Industriales y Parques Cient\u00edfico Tecnol\u00f3gicos.<\/p>\n<p class=\"has-text-align-justify\">En este sentido, el<strong> art\u00edculo 1\u00ba<\/strong> de la <strong>Ley N\u00ba 19.784<\/strong> dispone que el objetivo es \u201cestimular la cadena de valores industriales, a trav\u00e9s de la inversi\u00f3n, la agregaci\u00f3n de valor, la investigaci\u00f3n, la innovaci\u00f3n, la generaci\u00f3n de conocimiento, el progreso tecnol\u00f3gico y la creaci\u00f3n de puestos de trabajo, en un \u00e1mbito espacial de fomento a la asociatividad y generaci\u00f3n de sinergias, y procurando la descentralizaci\u00f3n geogr\u00e1fica de las actividades econ\u00f3micas\u201d.<\/p>\n<p class=\"has-text-align-justify\">Un <strong>Parque Industrial (PI) <\/strong>es aquel que tiene por objeto la instalaci\u00f3n y explotaci\u00f3n de industrias manufactureras y de servicios enumeradas en forma taxativa en la ley (log\u00edsticos, investigaci\u00f3n y desarrollo, formaci\u00f3n y capacitaci\u00f3n, etc).<\/p>\n<p class=\"has-text-align-justify\">Por su parte, un <strong>Parque Cient\u00edfico Tecnol\u00f3gico <\/strong>(en adelante <strong>PCT<\/strong>), es aquel que tiene por objeto la instalaci\u00f3n de centros de conocimiento e innovaci\u00f3n, junto con empresas y emprendimientos innovadores.<\/p>\n<p class=\"has-text-align-justify has-vivid-red-color has-text-color\" style=\"font-size:25px\"><strong>BENEFICIOS FISCALES PARA LOS INSTALADORES DE PI O PCT<\/strong><\/p>\n<p class=\"has-text-align-justify\">El instalador es aquella persona jur\u00eddica, p\u00fablica o privada, que habiendo obtenido la habilitaci\u00f3n correspondiente del Poder Ejecutivo, realice las actividades necesarias para que el parque cumpla con los requerimientos de infraestructura, bienes y servicios.<\/p>\n<p class=\"has-text-align-justify\">Podr\u00e1 prestar los servicios por s\u00ed o a trav\u00e9s de terceros, siendo responsable por todas las obligaciones que surjan de la Ley y su reglamentaci\u00f3n.<\/p>\n<p class=\"has-text-align-justify\">Los beneficios fiscales que obtiene el instalador cuyos proyectos de inversi\u00f3n hayan sido promovidos son los siguientes:<\/p>\n<p class=\"has-text-align-justify\">Exoneraci\u00f3n de<strong> IRAE <\/strong>por hasta un porcentaje de la inversi\u00f3n computable y <strong>efectivamente ejecutada<\/strong> seg\u00fan el siguiente detalle:<\/p>\n<p class=\"has-text-align-justify\">\u2022 PI: 50% de exoneraci\u00f3n sobre la inversi\u00f3n a aprovecharse en un plazo m\u00e1ximo de 6 a\u00f1os;<\/p>\n<p>\u2022 PCT: 75% de exoneraci\u00f3n sobre la inversi\u00f3n a aprovecharse en un plazo m\u00e1ximo de 10 a\u00f1os;<\/p>\n<p>La exoneraci\u00f3n se incrementar\u00e1 de acuerdo con la localizaci\u00f3n del PI o PCT:<\/p>\n<p class=\"has-text-align-justify\">\u2022 <strong>Zona Norte<\/strong> (Artigas, Cerro Largo, Durazno, Paysand\u00fa, Rivera, Salto, Tacuaremb\u00f3, Treinta y Tres): 10% adicional y 2 a\u00f1os m\u00e1s de plazo;<\/p>\n<p class=\"has-text-align-justify\">\u2022 <strong>Zona Sur <\/strong>(Canelones, Colonia, Flores, Florida, Lavalleja, Maldonado, Rocha, R\u00edo Negro, San Jos\u00e9, Soriano): 5% adicional y 1 a\u00f1o m\u00e1s de plazo.<\/p>\n<p class=\"has-text-align-justify\">En lo que respecta a la exoneraci\u00f3n otorgada a los PI, la misma podr\u00e1 incrementarse en un 20% adicional a la inversi\u00f3n computable, y 3 a\u00f1os m\u00e1s de plazo para su aplicaci\u00f3n, siempre y cuando se cumplan <strong>simult\u00e1neamente <\/strong>las siguientes condiciones:<\/p>\n<p class=\"has-text-align-justify\">Se instalen un m\u00ednimo de tres usuarios de las siguientes caracter\u00edsticas:<br \/>&#x25aa; Emprendedores e incubadoras de empresas,<\/p>\n<p class=\"has-text-align-justify\">&#x25aa; Instituciones de formaci\u00f3n y capacitaci\u00f3n,<\/p>\n<p class=\"has-text-align-justify\">&#x25aa; Instituciones de investigaci\u00f3n o innovaci\u00f3n, <\/p>\n<p class=\"has-text-align-justify\">&#x25aa; Otras instituciones vinculadas a la generaci\u00f3n de conocimiento aplicado.<\/p>\n<p class=\"has-text-align-justify\">&#8211; Que no sean todos de la misma categor\u00eda.<\/p>\n<p class=\"has-text-align-justify\">Por \u00faltimo, se obtendr\u00e1 una exoneraci\u00f3n adicional del <strong>15%<\/strong> sobre la inversi\u00f3n computable y 2 a\u00f1os m\u00e1s de plazo si se trata de un Parque especializado (parques que tienen por objeto la instalaci\u00f3n de un sector espec\u00edfico).<\/p>\n<p class=\"has-text-align-justify\">Respecto del <strong>aprovechamiento de esta exoneraci\u00f3n,<\/strong> es importante mencionar que el beneficio utilizado no podr\u00e1 superar el <strong>80% del IRAE<\/strong> de cada ejercicio.<\/p>\n<p class=\"has-text-align-justify\">\u2022 Cr\u00e9dito por el <strong>IVA<\/strong> incluido en la compra en plaza de bienes de activo fijo, materiales y servicios destinados a la obra civil del instalador, as\u00ed como tambi\u00e9n de los bienes de activo fijo destinados a la operativa del PI o PCT.<\/p>\n<p class=\"has-text-align-justify\">A su vez, el instalador obtendr\u00e1 un cr\u00e9dito por el <strong>IVA <\/strong>incluido en la compra de los mencionados bienes y servicios, cuando se trate de emprendimientos de personas jur\u00eddicas p\u00fablicas que no sean sujetos pasivos de IVA por tales actividades.<\/p>\n<p class=\"has-text-align-justify\">\u2022 Exoneraci\u00f3n del<strong> Impuesto al Patrimonio<\/strong> sobre los equipos de procesamiento electr\u00f3nico de datos por toda su vida \u00fatil.<\/p>\n<p class=\"has-text-align-justify\">\u2022 Exoneraci\u00f3n de las <strong>tasas y tributos a la importaci\u00f3n<\/strong> (incluido el IVA) de bienes de activo fijo y materiales destinados tanto a la operativa del instalador como a la obra civil, siempre que no sean competitivos con la industria nacional.<\/p>\n<p class=\"has-text-align-justify has-vivid-red-color has-text-color\" style=\"font-size:25px\"><strong>BENEFICIOS FISCALES PARA LOS USUARIOS DE PI O PCT<\/strong><\/p>\n<p class=\"has-text-align-justify\">\u2022 Los beneficios otorgados a los usuarios de PI o PCT se traducen en la concesi\u00f3n de mayores beneficios mediante la presentaci\u00f3n de proyectos de inversi\u00f3n ante la COMAP, al amparo del actual <strong>Decreto N\u00ba 143\/018.<\/strong><\/p>\n<p class=\"has-text-align-justify\">En este sentido se incrementa en un <strong>15%<\/strong> el monto del <strong>IRAE exonerado y el plazo para usufructuar la exoneraci\u00f3n<\/strong>, respecto al obtenido en la Matriz de Indicadores, siempre que se realicen <strong>alguna<\/strong> de las siguientes actividades:<\/p>\n<p class=\"has-text-align-justify\">\u2022 Actividades industriales;<\/p>\n<p class=\"has-text-align-justify\">\u2022 Operaciones de almacenaje, acondicionamiento, selecci\u00f3n, clasificaci\u00f3n, fraccionamiento, armado, desarmado, entre otras, vinculados a las actividades desarrolladas en el Parque;<\/p>\n<p class=\"has-text-align-justify\">\u2022 Generaci\u00f3n de energ\u00eda solar t\u00e9rmica y\/o fotovoltaica enmarcados en medidas promocionales del Poder Ejecutivo;<\/p>\n<p class=\"has-text-align-justify\">\u2022 Valoraci\u00f3n y aprovechamiento de residuos;<\/p>\n<p class=\"has-text-align-justify\">\u2022 Servicios en las \u00e1reas de tecnolog\u00eda de la informaci\u00f3n, comunicaci\u00f3n, biotecnolog\u00eda, entre otras.<\/p>\n<p class=\"has-text-align-justify\">Para aquellas empresas que no se encuentran comprendidas en las categor\u00edas anteriores, el monto de exoneraci\u00f3n de IRAE y el plazo para usufructuar la exoneraci\u00f3n se incrementar\u00e1 en un <strong>5%<\/strong> respecto al que corresponder\u00eda de aplicar la Matriz de Indicadores.<\/p>\n<p class=\"has-text-align-justify\">\u2022 Los usuarios que realicen determinadas actividades industriales dispondr\u00e1n adem\u00e1s de un cr\u00e9dito fiscal por los <strong>aportes patronales jubilatorios<\/strong> correspondientes al empleo comprometido en el indicador de generaci\u00f3n de empleo, por el que obtuvieron los beneficios fiscales.<\/p>\n<p class=\"has-text-align-justify\">Debe tenerse presente que tanto para el instalador como para el usuario, los bienes de activo fijo que fueran objeto de exoneraciones tributarias al amparo del presente r\u00e9gimen deber\u00e1n mantenerse por el t\u00e9rmino de su vida \u00fatil, considerando a tales efectos los criterios fiscales, o de 10 (diez) a\u00f1os en el caso que la vida \u00fatil sea mayor.<\/p>\n<p class=\"has-text-align-justify has-vivid-red-color has-text-color\" style=\"font-size:25px\"><strong>OTROS BENEFICIOS PARA INSTALADORES Y USUARIOS DE PI O PCT<\/strong><\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\">\u2022 UTE podr\u00e1 establecer una tarifa promocional para el instalador y\/o sus usuarios que incluir\u00e1:<\/p>\n<p class=\"has-text-align-justify has-black-color has-text-color\">&#8211; un precio de energ\u00eda igual al que corresponder\u00eda de considerar el consumo global del parque y sus usuarios como de un \u00fanico suscriptor;<\/p>\n<p class=\"has-text-align-justify\">&#8211; cargos fijos para el instalador y\/o usuarios conforme a su consumo individual de energ\u00eda.<\/p>\n<p class=\"has-text-align-justify\">Esta tarifa no podr\u00e1 implicar un precio de energ\u00eda o cargo fijo superior a los derivados de la tarifa ordinaria.<\/p>\n<p class=\"has-text-align-justify\">\u2022 Se exhorta a las empresas del Estado o entes p\u00fablicos a establecer tarifas y precios promocionales, siempre y cuando resulten beneficiosos para el instalador y\/o usuarios del PI o PCT considerados individualmente.<\/p>\n<p class=\"has-text-align-justify\">El presente r\u00e9gimen se aplicar\u00e1 a los PI y PCT habilitados a partir de la promulgaci\u00f3n de la <strong>Ley N\u00ba 19.784<\/strong> (23\/08\/2019), sin perjuicio de que los parques ya instalados pueden solicitar la modificaci\u00f3n de su habilitaci\u00f3n vigente, a efectos de incorporar los beneficios y obligaciones que regula la nueva reglamentaci\u00f3n.<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 28 de febrero se promulg\u00f3 el Decreto N\u00ba 79\/020, con el objetivo de reglamentar la Ley N\u00ba 19.784 de promoci\u00f3n y desarrollo de Parques Industriales y Parques Cient\u00edfico [&hellip;]<\/p>\n","protected":false},"featured_media":10432,"template":"","meta":{"_acf_changed":false,"footnotes":""},"new-category":[],"class_list":["post-10431","new","type-new","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>430- PROMOCI\u00d3N DE PARQUES INDUSTRIALES Y PARQUES CIENT\u00cdFICO TECNOL\u00d3GICOS - DECRETO N\u00ba 79\/20 - Auren Uruguay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"430- PROMOCI\u00d3N DE PARQUES INDUSTRIALES Y PARQUES CIENT\u00cdFICO TECNOL\u00d3GICOS - DECRETO N\u00ba 79\/20 - Auren Uruguay\" \/>\n<meta property=\"og:description\" content=\"El pasado 28 de febrero se promulg\u00f3 el Decreto N\u00ba 79\/020, con el objetivo de reglamentar la Ley N\u00ba 19.784 de promoci\u00f3n y desarrollo de Parques Industriales y Parques Cient\u00edfico [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren Uruguay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aurenuruguay\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/uy\/wp-content\/uploads\/2020\/05\/park.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AurenUruguay\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\\\/\",\"name\":\"430- PROMOCI\u00d3N DE PARQUES INDUSTRIALES Y PARQUES CIENT\u00cdFICO TECNOL\u00d3GICOS - DECRETO N\u00ba 79\\\/20 - Auren Uruguay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/park.jpg\",\"datePublished\":\"2020-05-27T12:57:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/park.jpg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/park.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/uy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"430- PROMOCI\u00d3N DE PARQUES INDUSTRIALES Y PARQUES CIENT\u00cdFICO TECNOL\u00d3GICOS &#8211; DECRETO N\u00ba 79\\\/20\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/\",\"name\":\"Auren Uruguay\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/uy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#organization\",\"name\":\"Auren Uruguay\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren Uruguay\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aurenuruguay\",\"https:\\\/\\\/x.com\\\/AurenUruguay\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/auren-uruguay\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClkpSYFfsAuqdTaVF5whedQ\",\"https:\\\/\\\/www.instagram.com\\\/aurenuruguay\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"430- PROMOCI\u00d3N DE PARQUES INDUSTRIALES Y PARQUES CIENT\u00cdFICO TECNOL\u00d3GICOS - DECRETO N\u00ba 79\/20 - Auren Uruguay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/","og_locale":"es_ES","og_type":"article","og_title":"430- PROMOCI\u00d3N DE PARQUES INDUSTRIALES Y PARQUES CIENT\u00cdFICO TECNOL\u00d3GICOS - DECRETO N\u00ba 79\/20 - Auren Uruguay","og_description":"El pasado 28 de febrero se promulg\u00f3 el Decreto N\u00ba 79\/020, con el objetivo de reglamentar la Ley N\u00ba 19.784 de promoci\u00f3n y desarrollo de Parques Industriales y Parques Cient\u00edfico [&hellip;]","og_url":"https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/","og_site_name":"Auren Uruguay","article_publisher":"https:\/\/www.facebook.com\/aurenuruguay","og_image":[{"width":640,"height":480,"url":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2020\/05\/park.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AurenUruguay","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/","url":"https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/","name":"430- PROMOCI\u00d3N DE PARQUES INDUSTRIALES Y PARQUES CIENT\u00cdFICO TECNOL\u00d3GICOS - DECRETO N\u00ba 79\/20 - Auren Uruguay","isPartOf":{"@id":"https:\/\/auren.com\/uy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2020\/05\/park.jpg","datePublished":"2020-05-27T12:57:13+00:00","breadcrumb":{"@id":"https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/#primaryimage","url":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2020\/05\/park.jpg","contentUrl":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2020\/05\/park.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/uy\/noticias\/430-promocion-de-parques-industriales-y-parques-cientifico-tecnologicos-decreto-no-79-20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/uy\/"},{"@type":"ListItem","position":2,"name":"430- PROMOCI\u00d3N DE PARQUES INDUSTRIALES Y PARQUES CIENT\u00cdFICO TECNOL\u00d3GICOS &#8211; DECRETO N\u00ba 79\/20"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/uy\/#website","url":"https:\/\/auren.com\/uy\/","name":"Auren Uruguay","description":"","publisher":{"@id":"https:\/\/auren.com\/uy\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/uy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/uy\/#organization","name":"Auren Uruguay","url":"https:\/\/auren.com\/uy\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/uy\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren Uruguay"},"image":{"@id":"https:\/\/auren.com\/uy\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aurenuruguay","https:\/\/x.com\/AurenUruguay","https:\/\/www.linkedin.com\/company\/auren-uruguay","https:\/\/www.youtube.com\/channel\/UClkpSYFfsAuqdTaVF5whedQ","https:\/\/www.instagram.com\/aurenuruguay\/"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new\/10431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new\/10431\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/media\/10432"}],"wp:attachment":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/media?parent=10431"}],"wp:term":[{"taxonomy":"new-category","embeddable":true,"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new-category?post=10431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}