{"id":10444,"date":"2020-04-28T15:27:38","date_gmt":"2020-04-28T13:27:38","guid":{"rendered":"https:\/\/auren.com\/uy\/new\/427-inclusion-de-covid-19-como-enfermedad-profesional\/"},"modified":"2020-04-28T15:27:38","modified_gmt":"2020-04-28T13:27:38","slug":"427-inclusion-de-covid-19-como-enfermedad-profesional","status":"publish","type":"new","link":"https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/","title":{"rendered":"427- INCLUSI\u00d3N DE COVID-19 COMO ENFERMEDAD PROFESIONAL"},"content":{"rendered":"<p class=\"has-text-align-justify\">La <strong>Ley 19.873,<\/strong> de 3 de abril de 2020, \u201cCOVID-19 se incluye como enfermedad profesional durante la emergencia sanitaria\u201d, incluy\u00f3 al coronavirus COVID-19 como enfermedad profesional, durante el tiempo en que se desarrolle la emergencia sanitaria declarada por el Poder Ejecutivo, para el personal m\u00e9dico y no m\u00e9dico de la salud.<\/p>\n<p class=\"has-text-align-justify\">Mediante el <strong>Decreto 131\/020<\/strong>, se reglament\u00f3 la Ley antes mencionada. En \u00e9ste, se establece que ser\u00e1n <strong>beneficiarios <\/strong>del seguro por enfermedad profesional el personal dependiente de la salud, que cumpla con los siguientes requisitos:<\/p>\n<p class=\"has-text-align-justify\">\u2022 Que participe directa o indirectamente en el proceso asistencial (trabajadores m\u00e9dicos y no m\u00e9dicos);<\/p>\n<p class=\"has-text-align-justify\">\u2022 Que desempe\u00f1e tareas en las instituciones privadas de asistencia m\u00e9dica, en la Comisi\u00f3n de Apoyo y el Patronato del Psic\u00f3pata, as\u00ed como el personal dependiente de empresas contratadas por las instituciones referidas;<\/p>\n<p class=\"has-text-align-justify\">\u2022 Que est\u00e9 comprendido en las disposiciones de la<strong> Ley 16.074<\/strong>, de 10 de octubre de 1989 \u201cRegulaci\u00f3n de los seguros sobre accidentes de trabajo y enfermedades profesionales\u201d.<\/p>\n<p class=\"has-text-align-justify has-vivid-red-color has-text-color\" style=\"font-size:25px\"><strong>REGISTRO DE PERSONAL COVID-19<\/strong><\/p>\n<p class=\"has-text-align-justify\">Se crea el Registro de Personal COVID-19, el que funcionar\u00e1 en la \u00f3rbita del Ministerio de Salud P\u00fablica. En \u00e9l, se recabar\u00e1 informaci\u00f3n correspondiente al personal m\u00e9dico y no m\u00e9dico que participe directa o indirectamente en el proceso asistencial y est\u00e9 expuesto al riesgo de contagio por la enfermedad COV1D 19.<\/p>\n<p class=\"has-text-align-justify\">El registro deber\u00e1 mantener la siguiente informaci\u00f3n: <\/p>\n<p class=\"has-text-align-justify\">\u2022 Datos personales de todos los trabajadores que en el \u00e1mbito de la salud, m\u00e9dicos y no m\u00e9dicos, participen del proceso asistencial estando expuestos al contagio de la enfermedad COVID 19.<\/p>\n<p class=\"has-text-align-justify\">\u2022 Datos personales del personal de limpieza y otros servicios conexos, aun cuando tenga relaci\u00f3n de dependencia con otra empresa que suministra el servicio prestado, siempre que est\u00e9n expuestos al contagio directo o indirecto de la enfermedad COVID 19.<\/p>\n<p class=\"has-text-align-justify\">\u2022 La lista de pacientes asistidos por cada instituci\u00f3n de salud que puedan contagiar la enfermedad COVID-19<\/p>\n<p class=\"has-text-align-justify\">\u2022 Toda otra informaci\u00f3n que las autoridades de salud p\u00fablica entiendan conveniente registrar de acuerdo a lo establecido en la <strong>Ley 19.873,<\/strong> de 3 de abril de 2020, \u201cCOVID-19 se incluye como enfermedad profesional durante la emergencia sanitaria\u201d.<\/p>\n<p class=\"has-text-align-justify has-vivid-red-color has-text-color\" style=\"font-size:25px\"><strong>COBERTURA DEL BANCO DE SEGUROS DE ESTADO<\/strong><\/p>\n<p class=\"has-text-align-justify\">El Banco de Seguros del Estado asumir\u00e1 el pago de la renta temporaria, durante el per\u00edodo de la enfermedad y con el l\u00edmite m\u00e1ximo de cuarenta y cinco d\u00edas.<\/p>\n<p class=\"has-text-align-justify\">La base de c\u00e1lculo de la referida renta tendr\u00e1 un tope de diez salarios m\u00ednimos nacionales mensuales.<\/p>\n<p class=\"has-text-align-justify\">Al momento de efectuar la denuncia de enfermedad profesional, deber\u00e1n adjuntarse los comprobantes de laboratorio de los casos positivos que demuestren el nexo causal.<\/p>\n<p class=\"has-text-align-justify\">La asistencia m\u00e9dica y su costo, en todos los casos, estar\u00e1n a cargo del prestador integral de salud del que sea afiliado el trabajador afectado.<\/p>\n<p class=\"has-text-align-justify has-vivid-red-color has-text-color\" style=\"font-size:25px\"><strong>PROFESIONALES DE LA SALUD INDEPENDIENTES<\/strong><\/p>\n<p class=\"has-text-align-justify\">Tanto la <strong>Ley 19.873<\/strong> como su decreto reglamentario, brindan cobertura al personal m\u00e9dico y no m\u00e9dico que se encuentran <span style=\"text-decoration: underline;\">bajo relaci\u00f3n de dependencia.<\/span><\/p>\n<p class=\"has-text-align-justify\">La <span style=\"text-decoration: underline;\">Caja de Jubilaciones y Pensiones de Profesionales Universitarios,<\/span> mediante Resoluci\u00f3n de fecha 2\/4\/2020, dispone admitir las solicitudes de subsidio por incapacidad temporal que formulen los profesionales de la salud en la modalidad de ejercicio libre profesional y que estando en el desempe\u00f1o de tareas en las instituciones privadas de asistencia m\u00e9dica m\u00f3vil de emergencia, habiendo atendido pacientes con riesgo o diagnosticados de la enfermedad COV1D-19, hayan contra\u00eddo dicha enfermedad y dicho extremo se encuentre acreditado mediante certificaci\u00f3n m\u00e9dica referida a un per\u00edodo igual o menor a treinta d\u00edas.<\/p>\n<p class=\"has-text-align-justify\">En tal sentido, el <strong>Decreto 130\/020<\/strong>, autoriza con cargo al \u201cFondo Solidario COVID-19&#8243; creado por la<strong> Ley 19.874<\/strong>, de 8 de abril de 2020, \u201cCreaci\u00f3n del Fondo Solidario COVID-19\u201d, la asistencia financiera y transferencia a la Caja de Jubilaciones y Pensiones de Profesionales Universitarios, de los montos equivalentes a las erogaciones que dicha Caja realice por concepto del subsidio por incapacidad temporal, en las oportunidades y formas que disponga el Ministerio de Econom\u00eda y Finanzas, facult\u00e1ndolo a realizar las compensaciones que puedan corresponder.<\/p>\n<p class=\"has-text-align-justify\">A dichos efectos, la Caja de Jubilaciones y Pensiones de Profesionales Universitarios brindar\u00e1 al referido Ministerio toda la informaci\u00f3n que \u00e9ste le solicitare.<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Ley 19.873, de 3 de abril de 2020, \u201cCOVID-19 se incluye como enfermedad profesional durante la emergencia sanitaria\u201d, incluy\u00f3 al coronavirus COVID-19 como enfermedad profesional, durante el tiempo en [&hellip;]<\/p>\n","protected":false},"featured_media":10445,"template":"","meta":{"_acf_changed":false,"footnotes":""},"new-category":[],"class_list":["post-10444","new","type-new","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>427- INCLUSI\u00d3N DE COVID-19 COMO ENFERMEDAD PROFESIONAL - Auren Uruguay<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"427- INCLUSI\u00d3N DE COVID-19 COMO ENFERMEDAD PROFESIONAL - Auren Uruguay\" \/>\n<meta property=\"og:description\" content=\"La Ley 19.873, de 3 de abril de 2020, \u201cCOVID-19 se incluye como enfermedad profesional durante la emergencia sanitaria\u201d, incluy\u00f3 al coronavirus COVID-19 como enfermedad profesional, durante el tiempo en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/\" \/>\n<meta property=\"og:site_name\" content=\"Auren Uruguay\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aurenuruguay\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auren.com\/uy\/wp-content\/uploads\/2020\/04\/covv.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"387\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AurenUruguay\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/427-inclusion-de-covid-19-como-enfermedad-profesional\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/427-inclusion-de-covid-19-como-enfermedad-profesional\\\/\",\"name\":\"427- INCLUSI\u00d3N DE COVID-19 COMO ENFERMEDAD PROFESIONAL - Auren Uruguay\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/427-inclusion-de-covid-19-como-enfermedad-profesional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/427-inclusion-de-covid-19-como-enfermedad-profesional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/covv.jpeg\",\"datePublished\":\"2020-04-28T13:27:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/427-inclusion-de-covid-19-como-enfermedad-profesional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/427-inclusion-de-covid-19-como-enfermedad-profesional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/427-inclusion-de-covid-19-como-enfermedad-profesional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/covv.jpeg\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/covv.jpeg\",\"width\":580,\"height\":387},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/noticias\\\/427-inclusion-de-covid-19-como-enfermedad-profesional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/auren.com\\\/uy\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"427- INCLUSI\u00d3N DE COVID-19 COMO ENFERMEDAD PROFESIONAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#website\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/\",\"name\":\"Auren Uruguay\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auren.com\\\/uy\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#organization\",\"name\":\"Auren Uruguay\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"contentUrl\":\"https:\\\/\\\/auren.com\\\/uy\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-cropped-favicon-Auren.png\",\"width\":512,\"height\":512,\"caption\":\"Auren Uruguay\"},\"image\":{\"@id\":\"https:\\\/\\\/auren.com\\\/uy\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aurenuruguay\",\"https:\\\/\\\/x.com\\\/AurenUruguay\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/auren-uruguay\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClkpSYFfsAuqdTaVF5whedQ\",\"https:\\\/\\\/www.instagram.com\\\/aurenuruguay\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"427- INCLUSI\u00d3N DE COVID-19 COMO ENFERMEDAD PROFESIONAL - Auren Uruguay","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/","og_locale":"es_ES","og_type":"article","og_title":"427- INCLUSI\u00d3N DE COVID-19 COMO ENFERMEDAD PROFESIONAL - Auren Uruguay","og_description":"La Ley 19.873, de 3 de abril de 2020, \u201cCOVID-19 se incluye como enfermedad profesional durante la emergencia sanitaria\u201d, incluy\u00f3 al coronavirus COVID-19 como enfermedad profesional, durante el tiempo en [&hellip;]","og_url":"https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/","og_site_name":"Auren Uruguay","article_publisher":"https:\/\/www.facebook.com\/aurenuruguay","og_image":[{"width":580,"height":387,"url":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2020\/04\/covv.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AurenUruguay","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/","url":"https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/","name":"427- INCLUSI\u00d3N DE COVID-19 COMO ENFERMEDAD PROFESIONAL - Auren Uruguay","isPartOf":{"@id":"https:\/\/auren.com\/uy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/#primaryimage"},"image":{"@id":"https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/#primaryimage"},"thumbnailUrl":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2020\/04\/covv.jpeg","datePublished":"2020-04-28T13:27:38+00:00","breadcrumb":{"@id":"https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/#primaryimage","url":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2020\/04\/covv.jpeg","contentUrl":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2020\/04\/covv.jpeg","width":580,"height":387},{"@type":"BreadcrumbList","@id":"https:\/\/auren.com\/uy\/noticias\/427-inclusion-de-covid-19-como-enfermedad-profesional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/auren.com\/uy\/"},{"@type":"ListItem","position":2,"name":"427- INCLUSI\u00d3N DE COVID-19 COMO ENFERMEDAD PROFESIONAL"}]},{"@type":"WebSite","@id":"https:\/\/auren.com\/uy\/#website","url":"https:\/\/auren.com\/uy\/","name":"Auren Uruguay","description":"","publisher":{"@id":"https:\/\/auren.com\/uy\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auren.com\/uy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/auren.com\/uy\/#organization","name":"Auren Uruguay","url":"https:\/\/auren.com\/uy\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/auren.com\/uy\/#\/schema\/logo\/image\/","url":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","contentUrl":"https:\/\/auren.com\/uy\/wp-content\/uploads\/2025\/01\/cropped-cropped-favicon-Auren.png","width":512,"height":512,"caption":"Auren Uruguay"},"image":{"@id":"https:\/\/auren.com\/uy\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aurenuruguay","https:\/\/x.com\/AurenUruguay","https:\/\/www.linkedin.com\/company\/auren-uruguay","https:\/\/www.youtube.com\/channel\/UClkpSYFfsAuqdTaVF5whedQ","https:\/\/www.instagram.com\/aurenuruguay\/"]}]}},"_links":{"self":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new\/10444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":0,"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new\/10444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/media\/10445"}],"wp:attachment":[{"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/media?parent=10444"}],"wp:term":[{"taxonomy":"new-category","embeddable":true,"href":"https:\/\/auren.com\/uy\/wp-json\/wp\/v2\/new-category?post=10444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}